{"id":139,"date":"2012-03-14T13:37:32","date_gmt":"2012-03-14T13:37:32","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2012\/03\/14\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/"},"modified":"2012-03-14T13:37:32","modified_gmt":"2012-03-14T13:37:32","slug":"les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/","title":{"rendered":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits"},"content":{"rendered":"<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><\/p>\n<p> Les difficult\u00e9s rencontr\u00e9es lorsque l\u2019on discute de proph\u00e9ties bibliques et le t\u00e9moignage de quelques \u00e9rudits qui attestent que certains versets bibliques font bel et bien allusion \u00e0 Mohammed.<\/p>\n<p><span style=\"color: #0000ff;\">Questions pr\u00e9liminaires<\/span><br \/>La Bible est le livre sacr\u00e9 du juda\u00efsme et du christianisme.\u00a0 La Bible chr\u00e9tienne est constitu\u00e9e de l\u2019Ancien et du Nouveau <img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-137\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg\" border=\"0\" style=\"float: right;\" width=\"425\" height=\"283\" srcset=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg 425w, https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/>Testament, mais les versions catholique romaine et orthodoxe de l\u2019Ancien Testament sont l\u00e9g\u00e8rement plus volumineuses parce que ces \u00e9glises acceptent certains livres que les protestants n\u2019acceptent pas.\u00a0 La Bible juive ne comprend que les livres que les chr\u00e9tiens connaissent sous le nom d\u2019Ancien Testament.\u00a0 De plus, la disposition des canons juif et chr\u00e9tien diff\u00e8rent consid\u00e9rablement.[1]\u00a0 La venue du proph\u00e8te Mohammed a \u00e9t\u00e9 proph\u00e9tis\u00e9e \u00e0 la fois dans l\u2019Ancien et le Nouveau Testament.<br \/> Il est commun\u00e9ment admis que J\u00e9sus et ses ap\u00f4tres parlaient l\u2019aram\u00e9en.\u00a0 L\u2019aram\u00e9en a \u00e9t\u00e9 couramment parl\u00e9 jusqu\u2019en l\u2019an 650, environ, puis a \u00e9t\u00e9 supplant\u00e9 par l\u2019arabe.[2]\u00a0 La Bible que l\u2019on retrouve de nos jours n\u2019est cependant pas fond\u00e9e sur les manuscrits aram\u00e9ens, mais sur des versions grecques et latines.<br \/>(Le fait de citer des proph\u00e9ties de la Bible ne signifie pas que les musulmans acceptent la Bible contemporaine comme r\u00e9v\u00e9lation divine dans toute son int\u00e9gralit\u00e9.)<br \/>Le fait que sa venue soit proph\u00e9tis\u00e9e par un autre proph\u00e8te n\u2019est pas une condition requise pour qu\u2019un proph\u00e8te soit accept\u00e9 et reconnu.\u00a0 Mo\u00efse, qui \u00e9tait un proph\u00e8te envoy\u00e9 au peuple de Pharaon, n\u2019avait \u00e9t\u00e9 annonc\u00e9 par aucun proph\u00e8te avant lui.\u00a0 Abraham a \u00e9t\u00e9 envoy\u00e9 par Dieu \u00e0 Nimrod, mais aucun proph\u00e8te n\u2019avait pr\u00e9dit sa venue.\u00a0 De m\u00eame pour No\u00e9, Lot et d\u2019autres qui \u00e9taient tous de vrais proph\u00e8tes envoy\u00e9s par Dieu sans que leur venue n\u2019ait\u00a0 jamais \u00e9t\u00e9 proph\u00e9tis\u00e9e par un autre proph\u00e8te.\u00a0 La preuve de l\u2019authenticit\u00e9 d\u2019un proph\u00e8te ne se limite donc pas \u00e0 des proph\u00e9ties faites sur lui; elle inclut le message qu\u2019il a \u00e0 transmettre, les miracles qu\u2019il accomplit, etc.<br \/> Discuter des proph\u00e9ties demeure un exercice d\u00e9licat, car il implique de faire le tri parmi de nombreuses versions et traductions de la Bible et des manuscrits r\u00e9cemment d\u00e9couverts, et de faire des recherches sur des mots h\u00e9breux, grecs et aram\u00e9ens.\u00a0 La t\u00e2che devient particuli\u00e8rement difficile lorsque l\u2019on sait que \u00ab toutes les copies de la Bible \u00e9mises avant l\u2019invention de l\u2019imprimerie (au 15e si\u00e8cle) pr\u00e9sentent des variantes textuelles \u00bb.[3]\u00a0 Voil\u00e0 qui n\u2019est pas un sujet facile pour les non initi\u00e9s.\u00a0 Les meilleurs t\u00e9moignages nous viennent donc d\u2019experts dans le domaine, contemporains ou non, qui ont reconnu ces proph\u00e9ties.<br \/>Nous avons des t\u00e9moignages d\u2019individus parmi les premiers juifs et les premiers chr\u00e9tiens, des rabbins et des moines, qui t\u00e9moignent du fait que Mohammed \u00e9tait bel et bien l\u2019homme auxquelles faisaient allusion des proph\u00e9ties bibliques bien sp\u00e9cifiques.\u00a0 En voici quelques exemples.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><span style=\"color: #0000ff;\">Le proph\u00e8te attendu<\/span><br \/>Les juifs et les chr\u00e9tiens de l\u2019\u00e8re pr\u00e9-islamique, en Arabie, attendaient un proph\u00e8te.\u00a0 Avant la venue de Mohammed, l\u2019Arabie \u00e9tait un pays partag\u00e9 par des juifs, des chr\u00e9tiens et des pa\u00efens, et les trois groupes se faisaient la guerre \u00e0 l\u2019occasion.\u00a0 Les juifs et les chr\u00e9tiens disaient aux pa\u00efens : \u00ab Le temps est venu pour que le proph\u00e8te illettr\u00e9 apparaisse parmi nous afin de faire revivre la religion d\u2019Abraham.\u00a0 Nous nous joindrons \u00e0 lui et nous vous livrerons une guerre acharn\u00e9e \u00e0 ses c\u00f4t\u00e9s. \u00bb\u00a0 Mais lorsque Mohammed apparut pour de bon, certains crurent en lui et d\u2019autres le rejet\u00e8rent.\u00a0 C\u2019est pourquoi Dieu a r\u00e9v\u00e9l\u00e9 :<span style=\"color: #008000;\"><br \/>\u00ab Et quand leur vient, de Dieu, un Livre confirmant celui qu\u2019ils ont d\u00e9j\u00e0 entre leurs mains \u2013 alors qu\u2019auparavant ils priaient pour obtenir une victoire d\u00e9cisive sur les m\u00e9cr\u00e9ants \u2013\u00a0 et lorsque leur vient ce qu\u2019ils savent, au fond, (\u00eatre la v\u00e9rit\u00e9), ils refusent d\u2019y croire. Que la mal\u00e9diction de Dieu soit sur les m\u00e9cr\u00e9ants! \u00bb<\/span> (Coran 2:89)<br \/>Le premier t\u00e9moin fut Bahira, un moine chr\u00e9tien qui reconnut que Mohammed \u00e9tait un proph\u00e8te alors que ce dernier \u00e9tait encore tout jeune. Il dit \u00e0 l\u2019oncle de Mohammed :<br \/>\u00ab \u2026un brillant avenir attend ton neveu; alors ram\u00e8ne-le rapidement chez lui. \u00bb[4]<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-138\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/2222.jpg\" border=\"0\" width=\"452\" height=\"454\" \/><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Le second t\u00e9moin fut Waraqah bin Nawfal, un \u00e9rudit chr\u00e9tien qui mourut peu de temps apr\u00e8s une rencontre seul \u00e0 seul avec Mohammed.\u00a0 Waraqah reconnut que Mohammed \u00e9tait le proph\u00e8te de son \u00e9poque et qu\u2019il avait re\u00e7u la r\u00e9v\u00e9lation comme l\u2019avaient re\u00e7ue Mo\u00efse et J\u00e9sus.[5] Les juifs de M\u00e9dine attendaient avec impatience la venue d\u2019un proph\u00e8te.\u00a0 Les troisi\u00e8me et quatri\u00e8me t\u00e9moins furent leurs deux grands rabbins, Abdoullah bin Salam et Moykhayriq.[6]Les cinqui\u00e8me et sixi\u00e8me t\u00e9moins furent deux rabbins y\u00e9m\u00e9nites, Wahb ibn Mounabbih et Ka\u2019b al-Ahbar.\u00a0 Ka\u2019b trouva dans la Bible de long passages de louanges et la description du proph\u00e8te par Mo\u00efse.[7]Le Coran dit :<br \/><span style=\"color: #008000;\">\u00ab N\u2019est-ce pas pour eux un signe que les savants des enfants d\u2019Isra\u00ebl en soient inform\u00e9s? \u00bb (Coran 26:197)<\/span><\/p>\n<p>________________________________________<br \/><span style=\"color: #ff0000;\">Footnotes: <br \/>[1] \u201cBible.\u201d\u00a0 Encyclop\u00e6dia Britannica, de l\u2019Encyclop\u00e6dia Britannica Premium Service. (http:\/\/www.britannica.com\/eb\/article-9079096)<br \/>[2] \u201cAramaic language.\u201d\u00a0 Encyclop\u00e6dia Britannica deEncyclop\u00e6dia Britannica Premium Service. (http:\/\/www.britannica.com\/eb\/article-9009190)<br \/>[3] \u201cbiblical literature.\u201d\u00a0 Encyclop\u00e6dia Britannica de Encyclop\u00e6dia Britannica Premium Service. (http:\/\/www.britannica.com\/eb\/article-73396)<br \/>[4] \u2018Muhammad: His Life Based on the Earliest Sources\u2019 par Martin Lings, p. 29. \u2018Sirat Rasul Allah\u2019 par Ibn Ishaq, traduit par A. Guillame, p. 79-81. \u2018The Quran And The Gospels: A Comparative Study,\u2019 p. 46 par Dr. Muhammad Abu Laylah de l\u2019universit\u00e9 d\u2019al-Azhar.<br \/>[5] \u2018Muhammad: His Life Based on the Earliest Sources\u2019 par Martin Lings, p. 35.<br \/>[6] \u2018The Quran And The Gospels: A Comparative Study,\u2019 p. 47 par Dr. Muhammad Abu Laylah of Azhar University.<br \/>[7] \u2018The Quran And The Gospels: A Comparative Study,\u2019 p. 47-48 par Dr. Muhammad Abu Laylah de l\u2019Universit\u00e9 d\u2019al-Azhar.<\/p>\n<p>par IslamReligion.com<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les difficult\u00e9s rencontr\u00e9es lorsque l\u2019on discute de proph\u00e9ties bibliques et le t\u00e9moignage de quelques \u00e9rudits qui attestent que certains versets bibliques font bel et bien allusion \u00e0 Mohammed. Questions pr\u00e9liminairesLa Bible est le livre sacr\u00e9 du juda\u00efsme et du christianisme.\u00a0 La Bible chr\u00e9tienne est constitu\u00e9e de l\u2019Ancien et du Nouveau Testament, mais les versions catholique &hellip;<\/p>\n","protected":false},"author":7,"featured_media":137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bibel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Les difficult\u00e9s rencontr\u00e9es lorsque l\u2019on discute de proph\u00e9ties bibliques et le t\u00e9moignage de quelques \u00e9rudits qui attestent que certains versets bibliques font bel et bien allusion \u00e0 Mohammed. Questions pr\u00e9liminairesLa Bible est le livre sacr\u00e9 du juda\u00efsme et du christianisme.\u00a0 La Bible chr\u00e9tienne est constitu\u00e9e de l\u2019Ancien et du Nouveau Testament, mais les versions catholique &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-14T13:37:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits\",\"datePublished\":\"2012-03-14T13:37:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/\"},\"wordCount\":1081,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/111.jpg\",\"articleSection\":[\"Gospel- Bible\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/\",\"name\":\"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/111.jpg\",\"datePublished\":\"2012-03-14T13:37:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/111.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/111.jpg\",\"width\":425,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/","og_locale":"fr_FR","og_type":"article","og_title":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L'islam est la verit\u00e9","og_description":"Les difficult\u00e9s rencontr\u00e9es lorsque l\u2019on discute de proph\u00e9ties bibliques et le t\u00e9moignage de quelques \u00e9rudits qui attestent que certains versets bibliques font bel et bien allusion \u00e0 Mohammed. Questions pr\u00e9liminairesLa Bible est le livre sacr\u00e9 du juda\u00efsme et du christianisme.\u00a0 La Bible chr\u00e9tienne est constitu\u00e9e de l\u2019Ancien et du Nouveau Testament, mais les versions catholique &hellip;","og_url":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2012-03-14T13:37:32+00:00","og_image":[{"width":425,"height":283,"url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits","datePublished":"2012-03-14T13:37:32+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/"},"wordCount":1081,"commentCount":0,"image":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg","articleSection":["Gospel- Bible"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/","url":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/","name":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg","datePublished":"2012-03-14T13:37:32+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#primaryimage","url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg","contentUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/111.jpg","width":425,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/les-propheties-bibliques-sur-mohammed-partie-1-de-4-le-temoignage-des-erudits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les proph\u00e9ties bibliques sur Mohammed (partie 1 de 4): le t\u00e9moignage des \u00e9rudits"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media\/137"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}