{"id":145,"date":"2012-03-15T08:08:42","date_gmt":"2012-03-15T08:08:42","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2012\/03\/15\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/"},"modified":"2012-03-15T08:08:42","modified_gmt":"2012-03-15T08:08:42","slug":"allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/","title":{"rendered":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum  As-souha\u00efb\u00e2ny"},"content":{"rendered":"<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Au nom d\u2019Allah Cl\u00e9ment et mis\u00e9ricordieux<\/p>\n<p>La louange appartient \u00e0 Allah et que la pri\u00e8re et le salut d\u2019Allah soient sur son Proph\u00e8te, ainsi que sur ses compagnons et tous ceux qui lui seront alli\u00e9s.<br \/>En outre :<br \/>On trouve dans le hadith d\u2019apr\u00e8s le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui qui dit : \u00ab Allah fera mis\u00e9ricorde \u00e0 ceux qui sont mis\u00e9ricordieux \u00bb (rapport\u00e9 par Boukh\u00e2ry)<br \/>Y a-t-il d\u2019autre r\u00e9compense pour le bien, que le bien ? Celui qui sera mis\u00e9ricordieux avec les cr\u00e9atures, alors le Cr\u00e9ateur le sera avec lui. Le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui, a dit : \u00ab Le Mis\u00e9ricordieux fait mis\u00e9ricorde \u00e0 celui qui fait preuve de mis\u00e9ricorde. Donc, faites mis\u00e9ricorde \u00e0 toutes cr\u00e9atures sur terre pour que Celui qui est au ciel vous fasse mis\u00e9ricorde \u00bb (rapport\u00e9 par boukh\u00e2ry).<br \/>La r\u00e9tribution correspond \u00e0 l\u2019action, Allah se comportera avec son serviteur comme lui se comportera avec Ses serviteurs. Donc, comporte-toi avec autrui comme tu voudrais qu\u2019Allah se comporte envers toi Allah dit :<br \/> \u00ab \u2026 mais si vous (les) excusez, passez sur (leurs) fautes et (leur) pardonnez, sachez qu\u2019Allah est Celui qui pardonne et Tr\u00e8s Mis\u00e9ricordieux \u00bb (la grande perte v.14)<\/span><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><br \/><span style=\"color: #008000;\">Et Il dit :<br \/>\u00ab \u2026 Qu\u2019ils pardonnent et excusent. N\u2019aimez-vous pas qu\u2019Allah vous pardonne ? \u00bb (la lumi\u00e8re v.22)<\/span><\/p>\n<p>D\u00e9sire ardemment apaiser les difficult\u00e9s des gens pour qu\u2019Allah apaise les tiennes. Le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui a dit : \u00ab Celui qui apaise la peine d\u2019un musulman, Allah lui apaisera une peine parmi les peines du Jour de la r\u00e9surrection \u00bb (rapport\u00e9 par Boukh\u00e2ry).<br \/>Il dit encore que la pri\u00e8re et le salut d\u2019Allah soient sur lui : \u00ab Celui qui vient au secours d\u2019un homme en d\u00e9tresse, Allah lui retirera une peine parmi les peines du Jour de la r\u00e9surrection \u00bb (rapport\u00e9 par Ahmad).<br \/>Aide les gens dans leurs besoins, Allah te viendra en aide. Le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui, a dit : \u00ab Allah vient en aide au serviteur tant que ce dernier vient en aide \u00e0 son fr\u00e8re \u00bb, \u00ab celui qui est s\u2019occupe des besoins de son fr\u00e8re alors Allah sera s\u2019occupera de ses besoins (rapport\u00e9 par moslim).<br \/>Sois un soulagement pour les n\u00e9cessiteux, Allah te soulagera. Le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui a dit : \u00ab Celui qui soulage un n\u00e9cessiteux, alors Allah le soulagera dans cette vie et dans l\u2019au-del\u00e0 \u00bb (rapport\u00e9 par Moslim), et il dit encore : \u00ab avant vous, vivait un marchand qui accordait des pr\u00eats aux gens et lorsqu\u2019il voyait parmi eux un n\u00e9cessiteux, il disait \u00e0 ses employ\u00e9s : pardonnez-lui, peut-\u00eatre qu\u2019Allah nous pardonnera, et Allah lui pardonna \u00bb (rapport\u00e9 par Boukh\u00e2ry).<br \/>Sois doux avec les serviteurs d\u2019Allah, alors tu seras inclus dans l\u2019invocation du Proph\u00e8te (que la pri\u00e8re et le salut d\u2019Allah soient sur lui) qui dit : \u00ab \u00d4 Allah ! Celui qui est doux avec ma communaut\u00e9, sois doux avec lui, et celui qui blesse ma communaut\u00e9 blesse-le \u00bb (rapport\u00e9 par Ahmad). Il dit encore (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab Allah est doux, et Il aime la douceur, et Il donne par la douceur ce qu\u2019Il ne donne par la rudesse \u00bb(rapport\u00e9 par Moslim) et il dit aussi (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab celui qui est priv\u00e9 de douceur est priv\u00e9 de tout bien \u00bb (rapport\u00e9 par Moslim).<br \/>Dissimule les d\u00e9fauts des gens, Allah dissimulera les tiens. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab celui qui dissimule les d\u00e9fauts d\u2019un musulman, Allah dissimulera les siens dans la vie d\u2019ici-bas et dans l\u2019au-del\u00e0 \u00bb (rapport\u00e9 par Moslim), et il dit encore (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab celui qui dissimule les secrets de son fr\u00e8re musulman, Allah dissimulera les siens le Jour de la r\u00e9surrection \u00bb (rapport\u00e9 par Ibn\u00fb M\u00e2jah)<br \/>Ne tiens pas compte des erreurs de ton fr\u00e8re, Allah ne tiendra pas compte des tiennes. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab celui qui ne tient pas compte (des erreurs) d\u2019un musulman, Allah ne tiendra pas compte de ses erreurs \u00bb (rapport\u00e9 par Ab\u00fb daw\u00fbd).<br \/>Nourris les musulmans, Allah te nourrira. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab tout croyant qui nourrit un croyant affam\u00e9, Allah le nourrira des fruits du paradis \u00bb (rapport\u00e9 par Tirmidh\u00ee).<br \/>Abreuve les musulmans, Allah t\u2019abreuvera. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab tout croyant qui abreuve un croyant assoiff\u00e9, Allah l\u2019abreuvera du nectar cachet\u00e9 le Jour de la r\u00e9surrection \u00bb (rapport\u00e9 par Tirmidh\u00ee).<br \/>V\u00eatis les musulmans, Allah te v\u00eatira. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab tout croyant qui v\u00eatit une personne nue, Allah le v\u00eatira d\u2019habits verts du paradis \u00bb (rapport\u00e9 Tirmidh\u00ee).<br \/>Donc, Allah se comportera envers toi comme tu te comporteras avec autrui. Choisis, donc, pour toi-m\u00eame la mani\u00e8re avec laquelle tu aimerais qu\u2019Allah se comporte avec toi. Agis de cette mani\u00e8re tu en r\u00e9colteras la r\u00e9compense.<\/p>\n<p>Prends garde de ne pas brutaliser les gens, car Allah te ch\u00e2tiera. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab Allah ch\u00e2tie ceux qui ch\u00e2tient les gens dans la vie d\u2019ici-bas \u00bb (rapport\u00e9 par Moslim). Allah dit :<\/p>\n<p>\u00ab Et rappelez-vous, lorsque Nous vous avons d\u00e9livr\u00e9s des gens de Pharaon, qui vous infligeaient le pire ch\u00e2timent \u00bb (la vache v.49)<br \/>\u00ab Et le jour o\u00f9 l\u2019Heure arrivera (il sera dit) : faites entrer les gens de Pharaon au plus dur des ch\u00e2timents \u00bb (Celui qui pardonne v.46)<\/p>\n<p>Prends garde d\u2019\u00eatre dur avec les serviteurs d\u2019Allah sinon te sera atteinte l\u2019invocation du Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab \u00d4 Allah ! Celui qui re\u00e7oit autorit\u00e9 sur ma communaut\u00e9 puis est dur avec elle, sois dur avec lui, et celui qui re\u00e7oit autorit\u00e9 sur ma communaut\u00e9 puis est doux avec elle, sois doux avec lui \u00bb (rapport\u00e9 par Moslim). <br \/>Ne fais pas de mal aux musulmans en espionnant sans cesse leurs intimit\u00e9s. Le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab celui qui guette sans cesse l\u2019intimit\u00e9 de son fr\u00e8re musulman, Allah guettera la sienne. Celui dont Allah guette son intimit\u00e9 au point de l\u2019humilier au plein c\u0153ur de sa demeure \u00bb (rapport\u00e9 par Tirmidh\u00ee), \u00ab celui qui d\u00e9voile l\u2019intimit\u00e9 de son fr\u00e8re musulman, Allah d\u00e9voilera la sienne au point de l\u2019humilier au plein c\u0153ur de sa maison \u00bb (rapport\u00e9 par Ibn\u00fb M\u00e2jah).<br \/>Ne prive pas les musulmans de ta mis\u00e9ricorde, car le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab celui qui ne fait pas mis\u00e9ricorde envers les gens, Allah Tout-Puissant ne lui fera pas mis\u00e9ricorde \u00bb (rapport\u00e9 par Moslim). Il dit encore (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab nul n\u2019est priv\u00e9 de mis\u00e9ricorde sauf le mis\u00e9rable \u00bb (rapport\u00e9 par Tirmidh\u00ee).<br \/>En conclusion, quel que soit ton comportement envers les gens, tu trouveras chez Allah une r\u00e9tribution \u00e9quitable. <br \/>Ibn\u00fb Qayim a dit : \u00ab Allah est g\u00e9n\u00e9reux, et Il aime celui qui est g\u00e9n\u00e9reux parmi ses cr\u00e9atures. Il est savant, et Il aime les savants. Il est capable et il aime le courageux et Il est beau et il aime la beaut\u00e9. Il est (qu\u2019Il soit exalt\u00e9 et glorifi\u00e9) mis\u00e9ricordieux et Il l\u2019aime ceux qui le sont, et Il fait mis\u00e9ricorde \u00e0 ceux qui sont mis\u00e9ricordieux parmi ses cr\u00e9atures. Il est celui qui cache (les d\u00e9fauts), et Il aime celui qui ne d\u00e9voile pas les d\u00e9fauts de ses serviteurs. Il est cl\u00e9ment, et Il aime celui qui l\u2019est avec ses serviteurs. Il est celui qui pardonne, et Il aime celui qui pardonne ses serviteurs. Il est infiniment bon, et Il aime celui qui l\u2019est envers ses serviteurs. Par contre, Il d\u00e9teste le rude et le brutal au c\u0153ur dur et au tr\u00e8s mauvais comportement. Il est doux, et Il aime la douceur. Il est indulgent, et Il aime l\u2019indulgence. Il est bienfaisant, et il aime la bienfaisance et les bienfaisants. Il est juste, et Il aime la justice, et Il accepte les excuses, et Il aime ceux qui acceptent les excuses de ses serviteurs \u00bb.<\/p>\n<p>Ainsi, Il r\u00e9tribue ses serviteurs suivant qu\u2019il ait ou pas ces comportements cit\u00e9s plus haut. Celui, donc, qui est cl\u00e9ment, Il sera cl\u00e9ment avec lui, et celui qui pardonne, Il lui pardonnera, et celui qui fait gr\u00e2ce, Il lui fera gr\u00e2ce, et celui qui est honn\u00eate, Il se comportera avec lui avec honn\u00eatet\u00e9, et celui qui est doux avec ses serviteurs, Il le sera envers lui, et celui qui fait mis\u00e9ricorde envers Ses cr\u00e9atures, Il le sera envers lui, et celui qui est bon avec eux, Il le sera avec lui, et celui qui est g\u00e9n\u00e9reux avec ses cr\u00e9atures, Il le sera avec lui, et celui qui leur est utile, Il le sera pour lui, et celui qui cache (leurs p\u00e9ch\u00e9s), Il cachera les siens, et celui qui leur pardonne, Il le pardonnera, et celui qui guette l\u2019intimit\u00e9 de ses cr\u00e9atures, Il guettera la sienne, et celui qui divulgue (leurs p\u00e9ch\u00e9s), Il divulguera les siens et l\u2019humiliera, et celui qui prive Ses cr\u00e9atures de ses biens, Il le privera de Ses biens, et celui qui se dresse contre Allah, Allah se dressera contre lui, et celui qui dupe, Il le dupera, et celui qui berne, Il le bernera.<br \/>Ainsi, celui qui appliquera un comportement sur Ses cr\u00e9atures, Allah appliquera sur lui exactement le m\u00eame comportement dans la vie d\u2019ici-bas et dans l\u2019au-del\u00e0. Allah sera envers Sa cr\u00e9ature comme elle sera envers autrui.<br \/>Ce que tu as fait pour les autres on le fera donc pour toi, et sois comme tu\u00a0 souhaites, Allah sera avec toi tel que tu l\u2019es envers Lui et ses cr\u00e9atures.<br \/>D\u00e9sire ardemment rendre service aux serviteurs d\u2019Allah, et ceci, conform\u00e9ment \u00e0 la parole du Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) : \u00ab celui qui peut d\u2019entre-vous rendre service \u00e0 son fr\u00e8re, qu\u2019il le fasse donc \u00bb (rapport\u00e9 par Moslim), et d\u00e9sire \u00eatre bon envers eux, car Allah aime les bienfaisants.<br \/>Sois paisible, doux et calme envers eux, car le Proph\u00e8te (que la pri\u00e8re et le salut d&rsquo;Allah soient sur lui) a dit : \u00ab sera priv\u00e9 du feu \u00e0 toute personne paisible, douce, calme et proche des gens \u00bb (rapport\u00e9 par Ahmad).<br \/>Fais gr\u00e2ce envers les cr\u00e9atures, oublie (leurs m\u00e9chancet\u00e9s), excuse leurs et pardonne leurs. Ainsi, il se peut qu\u2019Allah te fasse gr\u00e2ce et te pardonne, Allah ne laisse pas perdre la r\u00e9compense de celui qui fait le bien.<\/p>\n<p>Notre derni\u00e8re invocation est la louange appartient \u00e0 Allah et que la pri\u00e8re et le salut d&rsquo;Allah soient sur notre proph\u00e8te Muhammad ainsi que sur sa famille et tous ses compagnons.<\/p>\n<p><span style=\"color: #ff0000;\">Traduit par Abu Hamza Al-Germ\u00e2ny<\/p>\n<p>Publi\u00e9 par le bureau de pr\u00eache de Rabwah (Riyadh)<br \/>www.islamhouse.com <br \/>L\u2019islam \u00e0 la port\u00e9e de tous !<br \/><\/span><br \/><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au nom d\u2019Allah Cl\u00e9ment et mis\u00e9ricordieux La louange appartient \u00e0 Allah et que la pri\u00e8re et le salut d\u2019Allah soient sur son Proph\u00e8te, ainsi que sur ses compagnons et tous ceux qui lui seront alli\u00e9s.En outre :On trouve dans le hadith d\u2019apr\u00e8s le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui qui &hellip;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-145","post","type-post","status-publish","format-standard","hentry","category-la-realite-de-lislam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Au nom d\u2019Allah Cl\u00e9ment et mis\u00e9ricordieux La louange appartient \u00e0 Allah et que la pri\u00e8re et le salut d\u2019Allah soient sur son Proph\u00e8te, ainsi que sur ses compagnons et tous ceux qui lui seront alli\u00e9s.En outre :On trouve dans le hadith d\u2019apr\u00e8s le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui qui &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-15T08:08:42+00:00\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny\",\"datePublished\":\"2012-03-15T08:08:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/\"},\"wordCount\":2026,\"commentCount\":0,\"articleSection\":[\"La r\u00e9alit\u00e9 de l'Islam\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/\",\"name\":\"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"datePublished\":\"2012-03-15T08:08:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/","og_locale":"fr_FR","og_type":"article","og_title":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L'islam est la verit\u00e9","og_description":"Au nom d\u2019Allah Cl\u00e9ment et mis\u00e9ricordieux La louange appartient \u00e0 Allah et que la pri\u00e8re et le salut d\u2019Allah soient sur son Proph\u00e8te, ainsi que sur ses compagnons et tous ceux qui lui seront alli\u00e9s.En outre :On trouve dans le hadith d\u2019apr\u00e8s le Proph\u00e8te que la pri\u00e8re et le salut d\u2019Allah soient sur lui qui &hellip;","og_url":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2012-03-15T08:08:42+00:00","author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny","datePublished":"2012-03-15T08:08:42+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/"},"wordCount":2026,"commentCount":0,"articleSection":["La r\u00e9alit\u00e9 de l'Islam"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/","url":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/","name":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"datePublished":"2012-03-15T08:08:42+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/allah-se-comportera-avec-toi-comme-tu-te-comportes-avec-autrui-ecrit-par-abdelqayoum-as-souhaibany\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Allah se comportera avec toi comme tu te comportes avec autrui \u00c9crit par Abdelqayoum As-souha\u00efb\u00e2ny"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}