{"id":163,"date":"2012-03-18T12:16:44","date_gmt":"2012-03-18T12:16:44","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2012\/03\/18\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/"},"modified":"2012-03-18T12:16:44","modified_gmt":"2012-03-18T12:16:44","slug":"lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/","title":{"rendered":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-162\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg\" border=\"0\" width=\"466\" height=\"498\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">Marie<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/> \u00ab <span style=\"color: #008000;\">Certes, Allah a pr\u00e9f\u00e9r\u00e9 Adam, No\u00e9, la famille d\u2019Abraham et la famille d\u2019Imran \u00e0 (toutes Ses) cr\u00e9atures. Ils \u00e9taient descendants les uns des autres. Allah entend tout et Il est Omniscient. (Rappelle-toi) quand la femme d\u2019Imran dit: \u00ab Seigneur, je T\u2019ai d\u00e9di\u00e9 ce qui est dans mon ventre [pour \u00eatre d\u00e9vou\u00e9 \u00e0 Ton service et \u00e0 Ton adoration]. Veuilles l\u2019accepter. Certes, Toi, et Toi seul entend tout et sait tout. \u00bb Puis, lorsqu\u2019elle eut accouch\u00e9, elle dit : \u00ab Seigneur ! Voil\u00e0 que j\u2019ai accouch\u00e9 d\u2019une fille. \u00bb Allah savait mieux que quiconque de ce dont elle avait accouch\u00e9 ; le gar\u00e7on n\u2019est point comme la fille. \u00ab Je l\u2019ai nomm\u00e9e Marie et certes, je demande Ta protection, pour elle et pour sa descendance, contre Satan le banni<\/span>. \u00bb (Coran 3:33-36) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">Son enfance <\/span><\/strong><br \/> \u00ab <span style=\"color: #008000;\">Et son Seigneur l\u2019agr\u00e9a parfaitement et la fit grandir de la meilleure mani\u00e8re. Et Il en confia la garde \u00e0 Zacharie. Chaque fois que celui-ci entrait dans le sanctuaire o\u00f9 elle se trouvait, il trouvait pr\u00e8s d\u2019elle de la nourriture. \u00ab \u00d4 Marie ! D\u2019o\u00f9 te vient cette nourriture ? \u00bb, lui demanda-t-il un jour. Elle r\u00e9pondit: \u00ab Cela me vient de Allah. Allah donne sans compter \u00e0 qui Il veut<\/span>. \u00bb (Coran 3:37) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">Sa pi\u00e9t\u00e9<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> \u00ab <span style=\"color: #008000;\">Et un jour, les anges dirent \u00e0 Marie : \u00ab \u00d4 Marie! Certes, Allah t\u2019a \u00e9lue et purifi\u00e9e, et t\u2019a pr\u00e9f\u00e9r\u00e9e \u00e0 (toutes) les femmes de la cr\u00e9ation. \u00d4 Marie! Ob\u00e9is \u00e0 ton Seigneur, prosterne-toi et incline-toi avec ceux qui s\u2019inclinent (en pri\u00e8re). \u00bb Ce sont l\u00e0 des nouvelles de l\u2019inconnaissable que Nous (te) r\u00e9v\u00e9lons, (\u00f4 Mohammed). Tu n\u2019\u00e9tais pas l\u00e0 lorsqu\u2019ils jet\u00e8rent leurs calames pour d\u00e9cider qui se chargerait de Marie. Tu n\u2019\u00e9tais pas l\u00e0 non plus lorsqu\u2019ils se querell\u00e8rent [\u00e0 ce sujet]<\/span>. \u00bb (Coran 3:42-44) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">La bonne nouvelle d\u2019un enfant \u00e0 na\u00eetre<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> \u00ab <span style=\"color: #008000;\">Et quand les anges dirent : \u00ab \u00d4 Marie! Allah t\u2019annonce la bonne nouvelle d\u2019une Parole de Sa part. Son nom sera le Messie, J\u00e9sus, fils de Marie, illustre en ce monde comme dans l\u2019au-del\u00e0 et l\u2019un des rapproch\u00e9s (de Allah). Il parlera aux gens d\u00e8s le berceau. Et en son \u00e2ge m\u00fbr, il sera du nombre des vertueux. \u00bb Elle dit : \u00ab Seigneur! Comment pourrais-je avoir un enfant alors qu\u2019aucun homme ne m\u2019a touch\u00e9e? \u00bb Il dit: \u00ab Ce sera ainsi. Allah cr\u00e9e ce qu\u2019Il veut. Quand Il d\u00e9cr\u00e8te une chose, Il dit seulement \u00ab Sois! \u00bb et elle est aussit\u00f4t. Allah lui enseignera les \u00c9critures et la sagesse, ainsi que la Torah et l\u2019\u00c9vangile. \u00ab Il l\u2019enverra comme messager aux enfants d\u2019Isra\u00ebl (et il leur dira) : \u00ab En v\u00e9rit\u00e9, je viens \u00e0 vous avec un signe de la part de votre Seigneur. Pour vous, je fa\u00e7onne la glaise et lui fais prendre la forme d\u2019un oiseau; puis, je souffle dedans et, par la permission d\u2019Allah, cela devient un v\u00e9ritable oiseau. Je gu\u00e9ris l\u2019aveugle-n\u00e9 et le l\u00e9preux, et je ressuscite les morts par la permission d\u2019Allah. Et je suis \u00e0 m\u00eame de vous dire ce que vous venez de manger tout comme ce que vous gardez en r\u00e9serve dans vos maisons. Dans tout cela, il y a certes un signe, pour vous, si vous \u00eates croyants. Et (je viens) vous confirmer ce qu\u2019il y avait avant moi, dans la Torah, et je vous rends licite une partie de ce qui vous \u00e9tait interdit. Je viens \u00e0 vous avec un signe de la part de votre Seigneur; alors craignez Allah et ob\u00e9issez-moi. Certes, Allah est mon Seigneur et votre Seigneur; alors adorez-Le. Voil\u00e0 le droit chemin. \u00bb (Coran 3:45-51) <br \/>\u00ab Et fait mention de Marie, dans le Livre, quand elle alla s\u2019isoler, loin de sa famille, dans un lieu situ\u00e9 \u00e0 l\u2019est. Elle \u00e9tendit un voile entre elle et le monde. Nous lui envoy\u00e2mes Notre esprit, qui avait rev\u00eatu pour elle une forme humaine accomplie. Elle dit : \u00ab Je me r\u00e9fugie contre toi aupr\u00e8s du Mis\u00e9ricordieux! Si tu crains Allah, [ne m\u2019approche point]! \u00bb[1] Il dit : \u00ab Je ne suis qu\u2019un messager de ton Seigneur, venu t\u2019annoncer la naissance d\u2019un fils pur. \u00bb Elle dit : \u00ab Comment pourrais-je avoir un fils alors qu\u2019aucun homme ne m\u2019a (jamais) touch\u00e9e et que je ne suis point une femme de m\u0153urs l\u00e9g\u00e8res? \u00bb Il dit : \u00ab Ainsi sera-t-il. Cela M\u2019est facile, a dit ton Seigneur. Et Nous ferons de lui un signe pour les gens et une mis\u00e9ricorde \u00e9manant de Nous. C\u2019est une affaire d\u00e9j\u00e0 d\u00e9cr\u00e9t\u00e9e.<\/span> \u00bb[2]\u00a0\u00a0\u00a0 (Coran 19:16-21) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">L\u2019immacul\u00e9e conception <\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> \u00ab <span style=\"color: #008000;\">Et celle qui \u00e9tait rest\u00e9e chaste, (Marie) : Nous insuffl\u00e2mes en elle un souffle de vie venant de Notre esprit et f\u00eemes d\u2019elle, ainsi que de son fils, un signe pour (toute) l\u2019humanit\u00e9. <\/span>\u00bb[3] (Coran 21:91) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">La naissance de J\u00e9sus <\/span><\/strong><br \/> \u00ab <span style=\"color: #008000;\">Elle devint donc enceinte de l\u2019enfant et se retira en un lieu \u00e9loign\u00e9. Saisie par les douleurs de l\u2019enfantement, elle alla se r\u00e9fugier au pied d\u2019un palmier. Elle dit : \u00ab Ah! Que je fusse morte avant cet instant! Et que je fusse totalement oubli\u00e9e! \u00bb Une voix l\u2019appela, d\u2019au-dessous d\u2019elle : \u00ab Ne t\u2019afflige pas. Ton Seigneur a mis une source \u00e0 tes pieds. Et secoue vers toi le tronc du palmier; il en tombera des dattes fra\u00eeches et m\u00fbres. Mange et bois, et r\u00e9jouis-toi. Si tu vois quelqu\u2019un d\u2019entre les humains, dis-lui : \u00ab J\u2019ai fait v\u0153u de je\u00fbne, \u00e0 mon Seigneur; je ne peux donc parler \u00e0 aucun \u00eatre humain, aujourd\u2019hui. \u00bb Puis elle revint aupr\u00e8s des siens, portant son b\u00e9b\u00e9. Ils lui dirent : \u00ab \u00d4 Marie! Tu as fait l\u00e0 une chose \u00e9tonnante! \u00d4 s\u0153ur d\u2019Aaron! Ton p\u00e8re n\u2019\u00e9tait pas un homme mauvais et ta m\u00e8re n\u2019\u00e9tait pas une femme l\u00e9g\u00e8re. \u00bb Mais elle pointa du doigt le nouveau-n\u00e9. \u00ab Comment, s\u2019\u00e9tonn\u00e8rent-ils, parlerions-nous \u00e0 un enfant encore au berceau? \u00bb Mais (ce dernier) dit : \u00ab Je suis vraiment le serviteur de Allah. Il m\u2019a donn\u00e9 le Livre et m\u2019a fait proph\u00e8te;<span style=\"color: #000000;\">[4]<\/span> Il a fait de moi une source de b\u00e9n\u00e9diction o\u00f9 que je sois, et Il m\u2019a enjoint la pri\u00e8re et la zakat tant que je vivrai. Il m\u2019a rendu d\u00e9vou\u00e9 envers ma m\u00e8re et Il ne m\u2019a fait ni insolent ni mis\u00e9rable. Que la paix soit sur moi le jour o\u00f9 je naquis, le jour o\u00f9 je mourrai et le jour o\u00f9 je serai ressuscit\u00e9! \u00bb <span style=\"color: #000000;\">(Coran 19:22-33) <\/span><br \/> \u00ab Certes, pour Allah, J\u00e9sus est comme Adam, qu\u2019Il cr\u00e9a de poussi\u00e8re (de la terre), puis lui dit : \u00ab Sois! \u00bb et il fut. \u00bb[5] <span style=\"color: #000000;\">(Coran 3:59)<\/span> <br \/>\u00ab Et du fils de Marie et de sa m\u00e8re, Nous avons fait un signe. Et Nous leur avons donn\u00e9 refuge sur une colline dot\u00e9e d\u2019un p\u00e2turage et d\u2019un ruisseau<\/span>. \u00bb[6] (Coran 23:50) <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong><span style=\"color: #0000ff;\">L\u2019excellence de Marie <\/span><\/strong><br \/> \u00ab <span style=\"color: #008000;\">Et pour ceux qui croient, Allah cite en exemple la femme de Pharaon quand elle dit: \u00ab Seigneur ! Construis-moi une maison aupr\u00e8s de Toi, dans le Jardin, (au Paradis), et sauve-moi de Pharaon et de son \u0153uvre. Sauve-moi de (ce) peuple injuste. \u00bb De m\u00eame, Marie, la fille d\u2019Imran, qui avait pr\u00e9serv\u00e9 sa chastet\u00e9; Nous insuffl\u00e2mes en elle de Notre Esprit. Elle accepta comme v\u00e9ridiques les paroles de son Seigneur, de m\u00eame que Ses \u00c9critures, et elle fut du nombre des serviteurs ob\u00e9issants<\/span>. \u00bb\u00a0 (Coran 66:11-12)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> <br \/>Foot notes: <br \/>[1] Le Mis\u00e9ricordieux est l\u2019un des noms d\u2019Allah, dans le Coran. <br \/>[2] J\u00e9sus est un signe de la puissance d\u2019Allah, Allah ayant d\u00e9montr\u00e9 aux gens qu\u2019Il pouvait le cr\u00e9er sans p\u00e8re, comme Il avait cr\u00e9\u00e9 Adam sans parents. J\u00e9sus est aussi un signe qu\u2019Allah est parfaitement capable de ressusciter tous les hommes apr\u00e8s leur mort, puisque Celui qui cr\u00e9e \u00e0 partir du n\u00e9ant peut tr\u00e8s bien ramener \u00e0 la vie. Il sera \u00e9galement un signe du Jour du Jugement, lorsqu\u2019il reviendra sur terre et tuera l\u2019ant\u00e9christ, \u00e0 la fin des temps. <br \/>[3] Comme Allah a \u00e9t\u00e9 capable de cr\u00e9er Adam sans p\u00e8re ni m\u00e8re, Il a parfaitement pu cr\u00e9er J\u00e9sus sans p\u00e8re. Lorsque Allah d\u00e9cide d\u2019une chose, Il n\u2019a qu\u2019\u00e0 dire \u00ab Sois! \u00bb et elle est aussit\u00f4t. Allah est capable de toute chose. <br \/>[4] La position de proph\u00e8te est la plus honorable qu\u2019un \u00eatre humain puisse atteindre. Le proph\u00e8te est celui qui re\u00e7oit des r\u00e9v\u00e9lations d\u2019Allah par l\u2019interm\u00e9diaire de l\u2019ange Gabriel. <br \/>[5] Adam fut cr\u00e9\u00e9 lorsque Allah dit : \u00ab Sois! \u00bb et ce, sans p\u00e8re ni m\u00e8re. Ainsi fut cr\u00e9\u00e9 J\u00e9sus, par le Verbe d\u2019Allah. Si sa naissance miraculeuse devait faire de lui un \u00eatre divin, alors Adam aurait bien plus m\u00e9rit\u00e9 ce titre, puisqu\u2019il est n\u00e9 sans parents, tandis que J\u00e9sus avait une m\u00e8re. Alors comme Adam n\u2019\u00e9tait pas de nature divine, J\u00e9sus ne l\u2019\u00e9tait pas non plus. Mais ils \u00e9taient tous deux d\u2019humbles serviteurs d\u2019Allah. <br \/>[6] C\u2019est l\u00e0 que Marie donna naissance \u00e0 J\u00e9sus. <br \/><\/span><\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">IslamReligion.com<\/span><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marie \u00ab Certes, Allah a pr\u00e9f\u00e9r\u00e9 Adam, No\u00e9, la famille d\u2019Abraham et la famille d\u2019Imran \u00e0 (toutes Ses) cr\u00e9atures. Ils \u00e9taient descendants les uns des autres. Allah entend tout et Il est Omniscient. (Rappelle-toi) quand la femme d\u2019Imran dit: \u00ab Seigneur, je T\u2019ai d\u00e9di\u00e9 ce qui est dans mon ventre [pour \u00eatre d\u00e9vou\u00e9 \u00e0 Ton &hellip;<\/p>\n","protected":false},"author":7,"featured_media":162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jesus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Marie \u00ab Certes, Allah a pr\u00e9f\u00e9r\u00e9 Adam, No\u00e9, la famille d\u2019Abraham et la famille d\u2019Imran \u00e0 (toutes Ses) cr\u00e9atures. Ils \u00e9taient descendants les uns des autres. Allah entend tout et Il est Omniscient. (Rappelle-toi) quand la femme d\u2019Imran dit: \u00ab Seigneur, je T\u2019ai d\u00e9di\u00e9 ce qui est dans mon ventre [pour \u00eatre d\u00e9vou\u00e9 \u00e0 Ton &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-18T12:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1\",\"datePublished\":\"2012-03-18T12:16:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/\"},\"wordCount\":1579,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/jesus.jpg\",\"articleSection\":[\"Christ\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/\",\"name\":\"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/jesus.jpg\",\"datePublished\":\"2012-03-18T12:16:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/jesus.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/jesus.jpg\",\"width\":425,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L'islam est la verit\u00e9","og_description":"Marie \u00ab Certes, Allah a pr\u00e9f\u00e9r\u00e9 Adam, No\u00e9, la famille d\u2019Abraham et la famille d\u2019Imran \u00e0 (toutes Ses) cr\u00e9atures. Ils \u00e9taient descendants les uns des autres. Allah entend tout et Il est Omniscient. (Rappelle-toi) quand la femme d\u2019Imran dit: \u00ab Seigneur, je T\u2019ai d\u00e9di\u00e9 ce qui est dans mon ventre [pour \u00eatre d\u00e9vou\u00e9 \u00e0 Ton &hellip;","og_url":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2012-03-18T12:16:44+00:00","og_image":[{"width":425,"height":283,"url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1","datePublished":"2012-03-18T12:16:44+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/"},"wordCount":1579,"commentCount":0,"image":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg","articleSection":["Christ"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/","url":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/","name":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1 - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg","datePublished":"2012-03-18T12:16:44+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#primaryimage","url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg","contentUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/jesus.jpg","width":425,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/lhistoire-de-jesus-et-de-marie-telle-que-relatee-dans-le-coran-part-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019histoire de J\u00e9sus et de Marie telle que relat\u00e9e dans le Coran: Part 1"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media\/162"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}