{"id":174,"date":"2012-03-22T11:48:09","date_gmt":"2012-03-22T11:48:09","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2012\/03\/22\/la-terre-fait-bouger-les-montagnes\/"},"modified":"2012-03-22T11:48:09","modified_gmt":"2012-03-22T11:48:09","slug":"la-terre-fait-bouger-les-montagnes","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/","title":{"rendered":"La Terre Fait Bouger Les Montagnes"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-173\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg\" border=\"0\" width=\"461\" height=\"286\" \/><\/p>\n<p style=\"text-align: justify;\">Finalement les scientifiques ont prouv\u00e9 que les montagnes bougent tr\u00e8s lentement, ce mouvement a \u00e9t\u00e9 d\u00e9crit dans le coran prouvant ainsi la saintet\u00e9 de ce livre sacr\u00e9.\u2026. <br \/>Dans une recherche scientifique, les savants ont d\u00e9montr\u00e9 que le satellite appartenant \u00e0 la NASA, a d\u00e9tect\u00e9 les mouvements des montagnes en surface de la terre! <br \/>La cause de ces mouvements, est que les montagnes baignent sur une surface plus lourde soit, la deuxi\u00e8me couche des sept qui forment la terre, c\u2019est une couche visqueuse tr\u00e8s chaude. <br \/>L\u2019\u00e9corce terrestre et la couche situ\u00e9e juste en dessous, sont compos\u00e9es de plusieurs \u00e9tages qui bougent continuellement, entra\u00eenant depuis des millions d\u2019ann\u00e9es, des confrontements imperceptibles ainsi que l\u2019apparition de nouvelles montagnes, ces mouvements sont dus \u00e0 de forts courants de chaleur qui prennent naissance en dessous de ces couches. <br \/>La recherche publi\u00e9e dans la revue : \u00ab La Nature Am\u00e9ricaine \u00bb, prouve que la deuxi\u00e8me et la troisi\u00e8me couche terrestre, poussent fortement l\u2019\u00e9corce terrestre superficielle, ce qui entraine le mouvement des montagnes, ce ph\u00e9nom\u00e8ne est tr\u00e8s lent et ne peut se voir \u00e0 l\u2019\u0153il nu, seuls des appareillages tr\u00e8s sensibles et pr\u00e9cis peuvent le d\u00e9celer. <br \/>Ce discret mouvement des montagnes dont parlent les scientifiques en 2010, le saint coran l\u2019a pr\u00e9dit 14 si\u00e8cles auparavant. <br \/>Le Tout-Puissant dit : \u00ab<span style=\"color: #008000;\"> Et tu verras les montagnes \u2013 tu les crois fig\u00e9es \u2013 alors qu\u2019elles passent comme des nuages. Telle est l\u2019\u0153uvre d\u2019Allah qui a tout fa\u00e7onn\u00e9 \u00e0 la perfection. Il est Parfaitement Connaisseur de ce que vous faites<\/span> \u00bb An-Naml (les fourmis 88). Ce verset Coranique nous apprend avec la plus grande clart\u00e9 et avec une pr\u00e9cision scientifique absolue ce qu\u2019est, le mouvement des montagnes. N\u2019est ce pas l\u00e0 un miracle certain qui t\u00e9moigne du miracle du Coran lui-m\u00eame ?! <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/><span style=\"color: #ff0000;\">Ecrit par: Abduldaem Al-Kaheel\u00a0\u00a0\u00a0\u00a0\u00a0 www.kaheel7.com\/fr <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalement les scientifiques ont prouv\u00e9 que les montagnes bougent tr\u00e8s lentement, ce mouvement a \u00e9t\u00e9 d\u00e9crit dans le coran prouvant ainsi la saintet\u00e9 de ce livre sacr\u00e9.\u2026. Dans une recherche scientifique, les savants ont d\u00e9montr\u00e9 que le satellite appartenant \u00e0 la NASA, a d\u00e9tect\u00e9 les mouvements des montagnes en surface de la terre! La cause &hellip;<\/p>\n","protected":false},"author":7,"featured_media":173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-miracles-du-coran"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Terre Fait Bouger Les Montagnes - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Terre Fait Bouger Les Montagnes - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Finalement les scientifiques ont prouv\u00e9 que les montagnes bougent tr\u00e8s lentement, ce mouvement a \u00e9t\u00e9 d\u00e9crit dans le coran prouvant ainsi la saintet\u00e9 de ce livre sacr\u00e9.\u2026. Dans une recherche scientifique, les savants ont d\u00e9montr\u00e9 que le satellite appartenant \u00e0 la NASA, a d\u00e9tect\u00e9 les mouvements des montagnes en surface de la terre! La cause &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-22T11:48:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"454\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"La Terre Fait Bouger Les Montagnes\",\"datePublished\":\"2012-03-22T11:48:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/\"},\"wordCount\":330,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/1.jpg\",\"articleSection\":[\"Miracles du coran\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/\",\"name\":\"La Terre Fait Bouger Les Montagnes - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/1.jpg\",\"datePublished\":\"2012-03-22T11:48:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/1.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/1.jpg\",\"width\":454,\"height\":340,\"caption\":\"1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/la-terre-fait-bouger-les-montagnes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Terre Fait Bouger Les Montagnes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Terre Fait Bouger Les Montagnes - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/","og_locale":"fr_FR","og_type":"article","og_title":"La Terre Fait Bouger Les Montagnes - L'islam est la verit\u00e9","og_description":"Finalement les scientifiques ont prouv\u00e9 que les montagnes bougent tr\u00e8s lentement, ce mouvement a \u00e9t\u00e9 d\u00e9crit dans le coran prouvant ainsi la saintet\u00e9 de ce livre sacr\u00e9.\u2026. Dans une recherche scientifique, les savants ont d\u00e9montr\u00e9 que le satellite appartenant \u00e0 la NASA, a d\u00e9tect\u00e9 les mouvements des montagnes en surface de la terre! La cause &hellip;","og_url":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2012-03-22T11:48:09+00:00","og_image":[{"width":454,"height":340,"url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"La Terre Fait Bouger Les Montagnes","datePublished":"2012-03-22T11:48:09+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/"},"wordCount":330,"commentCount":0,"image":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg","articleSection":["Miracles du coran"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/","url":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/","name":"La Terre Fait Bouger Les Montagnes - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg","datePublished":"2012-03-22T11:48:09+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#primaryimage","url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg","contentUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/1.jpg","width":454,"height":340,"caption":"1"},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/la-terre-fait-bouger-les-montagnes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Terre Fait Bouger Les Montagnes"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media\/173"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}