{"id":187,"date":"2012-03-25T11:49:20","date_gmt":"2012-03-25T11:49:20","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2012\/03\/25\/evitez-la-trinite\/"},"modified":"2012-03-25T11:49:20","modified_gmt":"2012-03-25T11:49:20","slug":"evitez-la-trinite","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/","title":{"rendered":"\u00e9vitez la trinit\u00e9"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: large;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-186\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg\" border=\"0\" width=\"660\" height=\"474\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\"><span style=\"font-family: times new roman,times;\"><strong>Allah est Unique<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\"><span style=\"font-family: times new roman,times;\"><strong>Les Chr\u00e9tiens doivent \u00e9viter une conception confuse de la religion \u00e0 travers la croyance de la trinit\u00e9<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">(Notre Seigneur transcende toutes les d\u00e9clarations dans lesquelles nous avons exprim\u00e9 les points de vue erron\u00e9s des Chr\u00e9tiens et qui ne sont pas conformes au respect)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Certains Chr\u00e9tiens, influenc\u00e9s par les erreurs d\u2019orientations et de fausses interpr\u00e9tations qui continuent depuis des si\u00e8cles, sont strictement d\u00e9vou\u00e9s \u00e0 l\u2019erreur de la \u00ab\u00a0trinit\u00e9\u00a0\u00bb. Au lieu de dire, \u00ab\u00a0Allah est Un\u00a0\u00bb, ils ont abandonn\u00e9 la croyance monoth\u00e9iste qui repr\u00e9sente le fondement de la loi du Proph\u00e8te Mo\u00efse (psl) et du Proph\u00e8te J\u00e9sus (psl). A cause de cette croyance erron\u00e9e, ils ont commenc\u00e9 \u00e0 consid\u00e9rer le Proph\u00e8te J\u00e9sus (psl) comme divin, du moins \u00e0 leurs yeux (Allah est certainement bien au-dessus de tout cela) et de cette fa\u00e7on ils sont tomb\u00e9s dans une grave et s\u00e9rieuse erreur.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Il est essentiel pour les Chr\u00e9tiens sinc\u00e8res qui croient en Allah et ont confiance en Lui d\u2019abandonner d\u2019urgence cette grave erreur. Allah le Tout-Puissant r\u00e9v\u00e8le dans le Coran qu\u2019en raison de cette chose abominable invent\u00e9e, l\u2019assertion qui est exprim\u00e9e, les cieux s&rsquo;entrouvrent, la terre se fendra et les montagnes s&rsquo;\u00e9crouleront: Et ils ont dit : \u00ab\u00a0Le Tout Mis\u00e9ricordieux S&rsquo;est attribu\u00e9 un enfant !\u00a0\u00bb Vous avancez certes l\u00e0 une chose abominable !<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Peu s&rsquo;en faut que les cieux ne s&rsquo;entrouvrent \u00e0 ces mots, que la terre ne se fende et que les montagnes ne s&rsquo;\u00e9croulent, du fait qu&rsquo;ils ont attribu\u00e9 un enfant au Tout Mis\u00e9ricordieux, alors qu&rsquo;il ne convient nullement au Tout Mis\u00e9ricordieux d&rsquo;avoir un enfant !<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"><span style=\"color: #008000;\">Tous ceux qui sont dans les cieux et sur la terre se rendront aupr\u00e8s du Tout Mis\u00e9ricordieux, [sans exceptions], en serviteurs<\/span>. (Sourate Maryam, 88-93)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\"><strong><span style=\"font-family: times new roman,times;\">Les Chr\u00e9tiens sinc\u00e8res doivent mettre fin \u00e0 cette confusion<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Les passages de l\u2019Evangile concernant l\u2019unicit\u00e9 d\u2019Allah sont explicites. Notre Seigneur Tout-Puissant r\u00e9v\u00e8le dans l\u2019Evangile, ainsi que dans le Coran et la Torah, qu\u2019Il est le Seul et l\u2019Unique Seigneur. Encore dans l\u2019Evangile, il est explicitement d\u00e9clar\u00e9 que le Proph\u00e8te J\u00e9sus (psl) \u00e9tait un serviteur et qu\u2019il avait des caract\u00e9ristiques humaines, qu\u2019il mangeait, qu\u2019il dormait, qu\u2019il se fatiguait et qu\u2019il se reposait, qu\u2019il priait Allah. L&rsquo;erreur de la trinit\u00e9, qui fut d\u00e9lib\u00e9r\u00e9ment ajout\u00e9e par des forces diverses au Christianisme, est inacceptable pour toutes les trois religions divines.Tous les Chr\u00e9tiens sinc\u00e8res qui peuvent appr\u00e9cier \u00e0 Sa juste valeur Allah le Tout-Puissant et comprendre correctement l\u2019essence de l\u2019Evangile et son message peuvent clairement voir que la croyance en la trinit\u00e9 est une grave erreur, qu\u2019elle est une explication extr\u00eamement malhonn\u00eate de la v\u00e9ritable situation et que notre Seigneur Tout-Puissant est bien au-del\u00e0 d\u2019une telle description.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">En raison de ce point de vue non-sinc\u00e8re, la religion simple, accessible, claire et immacul\u00e9e qu\u2019Allah a cr\u00e9\u00e9 a \u00e9t\u00e9 rendue confuse et incompr\u00e9hensible. Plut\u00f4t que d\u2019adorer Allah directement, divers interm\u00e9diaires pr\u00e9sum\u00e9s et des sauveurs qui soi-disant \u00e9tablissent des contacts avec Allah furent invent\u00e9s \u00e0 travers la croyance de la trinit\u00e9.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">A cause de ces explications confuses et incompr\u00e9hensibles qui constituent le fondement de l\u2019erreur de la trinit\u00e9, les Chr\u00e9tiens en question d\u00e9fendent l\u2019existence d\u2019une divinit\u00e9 qui est incompr\u00e9hensible et ineffable (Allah est certainement bien au-dessus de tout cela) et ils ne peuvent pas comprendre le genre de Cr\u00e9ateur qu\u2019ils adorent et sont incapables de produire une quelconque explication satisfaisante. Ils pr\u00e9tendent croire en une Divinit\u00e9 (Allah), mais en fait ils adoptent trois divinit\u00e9s au moyen d\u2019interpr\u00e9tations forc\u00e9es (Allah est certainement bien au-dessus de tout cela). Cependant, m\u00eame ces explications et interpr\u00e9tations confuses suffisent \u00e0 montrer \u00e0 quel point la trinit\u00e9 est une erreur.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Allah le Tout-Puissant n\u2019a jamais cr\u00e9\u00e9 une telle religion confuse et incompr\u00e9hensible. Ce n\u2019est pas ce qu\u2019Allah veut des croyants vertueux. Utiliser des interm\u00e9diaires afin d\u2019\u00e9tablir un contact avec Allah, de pr\u00e9tendre qu\u2019on ne peut pas \u00e9tablir de contact avec Allah tant que le Proph\u00e8te J\u00e9sus (psl) n\u2019est pas l\u2019interm\u00e9diaire et chercher \u00e0 d\u00e9crire Allah comme s\u2019Il avait des faiblesses (Allah est certainement bien au-dessus de tout cela), tout ceci est \u00e9quivalent \u00e0 rentier Allah.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><strong><span style=\"color: #0000ff;\"><span style=\"font-family: times new roman,times;\">Toutes les entit\u00e9s sont des manifestations d\u2019Allah et Allah cerne toutes choses<\/span><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> G\u00e9n\u00e9ralement, les Chr\u00e9tiens en question comprennent mal le sujet de la manifestation. Pour cette raison, ce sujet doit \u00eatre expliqu\u00e9 en d\u00e9tail : toutes les nettes sont des manifestations s\u00e9par\u00e9es de notre Seigneur tout puissant. C\u2019est une grave erreur de consid\u00e9rer quoi que ce soit comme \u00e9tant ind\u00e9pendant d\u2019Allah (Allah est certainement bien au-dessus de cela), cela signifie ne pas pouvoir appr\u00e9cier la puissance, la force et la grandeur d\u2019Allah. Allah le Tout-Puissant est infini. Pr\u00e9tendre qu\u2019il y a des entit\u00e9s en dehors d\u2019Allah qui est infiniment Grand et Puissant, veut dire rejeter le caract\u00e8re infini d\u2019Allah et par cons\u00e9quent ne pas L\u2019appr\u00e9cier \u00e0 Sa juste valeur.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Certains Chr\u00e9tiens ne consid\u00e8rent le Proph\u00e8te J\u00e9sus (psl) que comme une manifestation d\u2019Allah et disent qu\u2019il serait irrespectueux de parler d\u2019autres entit\u00e9s en tant que manifestations d\u2019Allah, et que cela serait \u00e9quivalent \u00e0 ne pas Le comprendre. Mais c\u2019est une tromperie. C\u2019est une autre de ces mauvaises interpr\u00e9tations ajout\u00e9es ult\u00e9rieurement au Christianisme afin de soi-disant renforcer leur croyance en la trinit\u00e9 et rendre la religion compliqu\u00e9e. L\u2019infinit\u00e9 est un attribut d\u2019Allah le Tout-Puissant et tout ce qui existe est cr\u00e9e en tant que manifestation, c\u2019est-a-dire une \u00ab\u00a0apparition\u00a0\u00bb de l\u2019existence infinie d\u2019Allah le tout-puissant.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">En cons\u00e9quence de cette interpr\u00e9tation fausse, les Chr\u00e9tiens en question pensent que \u00ab\u00a0la manifestation\u00a0\u00bb est la m\u00eame chose que \u201cl\u2019Etre d\u2019Allah\u201d. C\u2019est pourquoi ils parlent du Proph\u00e8te J\u00e9sus (psl) comme \u00e9tant \u201cune manifestation\u201d, en d\u2019autres termes ils lui attribuent un statut divin (Allah est certainement bien au-dessus de cela).C\u2019est encore une incapacit\u00e9 \u00e0 appr\u00e9cier la grandeur et la puissance d\u2019Allah.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Allah le Tout-Puissant est en dehors du temps et de l\u2019espace. L\u2019Etre d\u2019Allah est totalement diff\u00e9rent. Les manifestations ne sont que des \u2018\u2019apparitions\u2019\u2019 d\u2019Allah. Elles ne sont pas Son Etre Tout-Puissant Lui-m\u00eame. Notre Seigneur Tout-Puissant n\u2019est pas s\u00e9par\u00e9 de Ses cr\u00e9ations. Toutes les entit\u00e9s, tout ce qui existe dans l\u2019univers, petit ou grand, sont des \u00ab\u00a0apparitions\u00a0\u00bb d\u2019Allah. Les \u00eatres humains ne peuvent jamais voir l\u2019Etre d\u2019Allah. Mais ils sont en contact permanent avec Ses manifestations. Ils sont eux-m\u00eames des manifestations de Lui.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Par cons\u00e9quent, comme toutes les autres entit\u00e9s, le Proph\u00e8te J\u00e9sus (psl) est une manifestation de notre Seigneur Tout-Puissant. Cela ne veut pas dire, comme les Chr\u00e9tiens en question l\u2019imaginent, qu\u2019Allah S\u2019est incarn\u00e9 en le Proph\u00e8te J\u00e9sus (psl) (Allah est certainement bien au-dessus de cela). Comme toutes les autres entit\u00e9s qui sont des manifestations d\u2019Allah, le proph\u00e8te j\u00e9sus (psl) est une \u00ab\u00a0apparition\u00a0\u00bb d\u2019Allah. C\u2019est ce que signifie la manifestation. Les Chr\u00e9tiens en question interpr\u00e8tent les d\u00e9clarations du Proph\u00e8te J\u00e9sus (psl) dans ce sens, sans prendre en compte cet aspect cach\u00e9. Cependant quand ils regardent d\u2019une mani\u00e8re attentive, rationnelle et compatible avec la cr\u00e9ation d\u2019Allah, ils verront que dans ces passages le Proph\u00e8te J\u00e9sus (psl) dit qu\u2019il est une manifestation d\u2019Allah, tout comme les autres entit\u00e9s.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">D\u2019autres passages de l\u2019Evangile expriment \u00e9galement que tous les \u00eatres humains et toutes les entit\u00e9s existantes sont des manifestations d\u2019Allah. Certains de ceux-ci sont comme suit :<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Apr\u00e8s leur arriv\u00e9e, ils convoqu\u00e8rent l&rsquo;\u00c9glise, et ils racont\u00e8rent tout ce que Allah avait fait avec eux, et comment Il avait ouvert aux nations la porte de la foi. (Les Actes, 14 :27)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Arriv\u00e9s \u00e0 J\u00e9rusalem, ils furent re\u00e7us par l&rsquo;\u00c9glise, les ap\u00f4tres et les anciens, et ils racont\u00e8rent tout ce qu\u2019Allah avait fait avec eux. (Les actes, 15 :4)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Il est avant toutes choses, et toutes choses subsistent en Lui. (Colossiens, 1 :17)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">A la diff\u00e9rence des croyances des Chr\u00e9tiens en question, voir et accepter que toutes les entit\u00e9s sont des manifestations d\u2019Allah signifie louer et appr\u00e9cier comme il se doit l\u2019existence infinie et toute puissante d\u2019Allah. \u00c7a veut dire comprendre qu\u2019Allah cerne toutes choses et tous lieux, que rien n\u2019est loin de Lui, qu\u2019il est le Seigneur de la terre et du ciel et de tous les mondes. Cela signifie \u00eatre capable d\u2019appr\u00e9cier la puissance, la force, la grandeur et le caract\u00e8re infini d\u2019Allah le tout-puissant, qui est infiniment puissant, grand et omniscient. C\u2019est louer Allah. Les d\u00e9clarations faites par les Chr\u00e9tiens en question contiennent des erreurs graves. Dans un verset du Coran Allah dit : <span style=\"color: #008000;\">Allah ! Point de divinit\u00e9 \u00e0 part Lui, le Vivant, Celui qui subsiste par lui-m\u00eame \u00ab\u00a0al-Qayyum\u00a0\u00bb. Ni somnolence ni sommeil ne Le saisissent. A lui appartient tout ce qui est dans les cieux et sur la terre. Qui peut interc\u00e9der aupr\u00e8s de Lui sans Sa permission? Il conna\u00eet leur pass\u00e9 et leur futur. Et, de Sa science, ils n&#8217;embrassent que ce qu&rsquo;Il veut. Son Tr\u00f4ne \u2018Kursiy\u2019 d\u00e9borde les cieux et la terre, dont la garde ne Lui co\u00fbte aucune peine. Et Il est le Tr\u00e8s Haut, le Tr\u00e8s Grand<\/span>. (Sourate al-Baqarah, 255)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\"><strong><span style=\"font-family: times new roman,times;\">Allah est partout, Il voit et entend \u00e0 chaque moment<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Les Chr\u00e9tiens qui sont tomb\u00e9s dans l\u2019erreur de la trinit\u00e9 doivent r\u00e9fl\u00e9chir plus rationnellement et profond\u00e9ment sur l\u2019existence majestueuse d\u2019Allah et Sa qualit\u00e9 de Seigneur. Parce que les Chr\u00e9tiens en question font une grave erreur en imaginant qu\u2019Allah est dans le ciel, loin d\u2019eux et sans lien avec ce qu\u2019ils font (Allah est certainement bien au-dessus de cela). C\u2019est la principale raison pour laquelle ils utilisent des interm\u00e9diaires pour adorer ou prier Allah, ils pensent que notre Seigneur n\u2019entend pas leurs pri\u00e8res (Allah est certainement bien au-dessus de cela) et n\u2019arrivent pas \u00e0 saisir le concept de manifestation d\u2019Allah.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Le fait est qu\u2019Allah est partout. La puissance de notre Seigneur embrasse chaque endroit. Allah poss\u00e8de la connaissance de toute chose se trouvant dans les cieux, sur la terre, dans l\u2019espace, sous terre et entre les nuages, et Il conna\u00eet chaque endroit. Allah le Tout-Puissant rappelle \u00e0 Ses serviteurs qu\u2019Il est plus pr\u00e8s d\u2019eux que leur veine jugulaire :<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"><span style=\"color: #008000;\">Nous avons effectivement cr\u00e9\u00e9 l&rsquo;homme et Nous savons ce que son \u00e2me lui sugg\u00e8re et Nous sommes plus pr\u00e8s de lui que sa veine jugulaire<\/span>. (Sourate Qaf, 16)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Etant donn\u00e9 que toute chose est une manifestation d\u2019Allah, tous les yeux Lui appartiennent. Il entend tout \u00e0 chaque instant, et sait ce que les gens pensent cach\u00e9 au fond d\u2019eux. Personne n\u2019a le pouvoir de faire quoi que ce soit sans qu\u2019Allah le sache. Dans un verset du Coran, Allah le Tout-Puissant dit ainsi : \u00a0<span style=\"color: #008000;\">Et supporte patiemment la d\u00e9cision de ton Seigneur. Car en v\u00e9rit\u00e9, tu es sous Nos yeux. Et c\u00e9l\u00e8bre la gloire de ton Seigneur quand tu te l\u00e8ves<\/span>. (Sourate at-Tur, 48)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Il n&rsquo;y a pas besoin d&rsquo;interm\u00e9diaires pour prier Allah le Tout-Puissant et faire appel \u00e0 Lui. Allah est Celui Qui sait ce qu&rsquo;une personne d\u00e9sire, tous les d\u00e9sirs qu&rsquo;il a dans son c\u0153ur, le contenu de leur poitrine, m\u00eame les choses les plus secr\u00e8tes :<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"><span style=\"color: #008000;\">A Lui appartient ce qui est dans les cieux, sur la terre, ce qui est entre eux et ce qui est sous le sol humide. Et si tu \u00e9l\u00e8ves la voix, Il conna\u00eet certes les secrets, m\u00eames les plus cach\u00e9s.<\/span> (Sourate Ta-Ha, 6-7)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Les gens n\u2019ont pas la puissance de voir et de comprendre l\u2019Etre d\u2019Allah le Tout-Puissant. Mais Allah a connaissance de ce que voient tous les yeux. Il voit et entend tout, et tout se produit sous Sa connaissance. Il est le Quatri\u00e8me de trois personnes (Sourate al-Mujadalah, 7) et pas une feuille ne tombe qu\u2019Il ne le sache (Sourate al-Anam, 59).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\">Allah le Tout-Puissant dit : <span style=\"color: #008000;\">Les regards ne peuvent l&rsquo;atteindre, cependant qu&rsquo;Il saisit tous les regards. Et Il est le Doux, le Parfaitement Connaisseur<\/span>. (Sourate al-Anam, 103)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><strong><span style=\"color: #0000ff;\"><span style=\"font-family: times new roman,times;\">Les Chr\u00e9tiens sinc\u00e8res ne devraient pas penser qu\u2019Allah est loin d\u2019eux<\/span><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Quand les Chr\u00e9tiens qui adh\u00e8rent \u00e0 l\u2019erreur de la trinit\u00e9 r\u00e9aliseront bien qu\u2019Allah est avec eux \u00e0 tout moment et en tous lieux, qu\u2019Allah les voit et les entend partout et qu\u2019Allah est plus pr\u00e8s d\u2019eux que leur veine jugulaire, ils r\u00e9aliseront \u00e9galement qu\u2019ils sont tomb\u00e9s dans une grave erreur. Allah n\u2019est pas loin d\u2019eux. Allah n\u2019est pas une entit\u00e9 \u00e0 qui on doit parvenir par des interm\u00e9diaires. Allah est partout. Il n\u2019y a rien qui lui soit cache.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> Les Chr\u00e9tiens sinc\u00e8res doivent consid\u00e9rer les passages de l\u2019Evangile de ce point de vue. Ils doivent garder \u00e0 l\u2019esprit que les paroles d\u2019Allah peuvent avoir des sens tr\u00e8s profonds et doivent les interpr\u00e9ter avec tous leurs sens cach\u00e9s. Ils doivent se rendre compte du fait qu\u2019Allah les entend et voit \u00e0 chaque instant et qu\u2019Il est avec eux \u00e0 tout instant et qu\u2019Allah le Tout-Puissant cerne tous les lieux. Par cons\u00e9quent, ils doivent comprendre qu\u2019Allah n\u2019a pas cr\u00e9\u00e9 une religion confuse et incompr\u00e9hensible pour eux. Allah est unique. il entend tous les appels. son pouvoir est tr\u00e8s grand. C\u2019est une grande erreur d\u2019attribuer une divinit\u00e9 \u00e0 un \u00eatre humain qui est une manifestation d\u2019Allah. Ceci, comme r\u00e9v\u00e9l\u00e9 dans le Coran, est une tr\u00e8s grande impudence, \u00e0 faire d\u00e9placer les montagnes. Les Chr\u00e9tiens sinc\u00e8res doivent \u00eatre conscients de cette attitude erron\u00e9e qu\u2019ils ont adopt\u00e9e et abandonner ces croyances superstitieuses et se tourner sinc\u00e8rement vers Le Seul et Unique, Allah. Allah est Celui Qui pardonne ceux qui prennent conscience de leurs erreurs et se repentent. Il est Celui Qui couvre leurs p\u00e9ch\u00e9s.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\" dir=\"rtl\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\"><span style=\"font-family: times new roman,times;\">lundi, 22 ao\u00fbt 2011<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\" dir=\"rtl\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\"><span style=\"font-family: times new roman,times;\">Harun yahya<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: times new roman,times;\"> <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allah est Unique Les Chr\u00e9tiens doivent \u00e9viter une conception confuse de la religion \u00e0 travers la croyance de la trinit\u00e9 (Notre Seigneur transcende toutes les d\u00e9clarations dans lesquelles nous avons exprim\u00e9 les points de vue erron\u00e9s des Chr\u00e9tiens et qui ne sont pas conformes au respect) Certains Chr\u00e9tiens, influenc\u00e9s par les erreurs d\u2019orientations et de &hellip;<\/p>\n","protected":false},"author":7,"featured_media":186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jesus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00e9vitez la trinit\u00e9 - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00e9vitez la trinit\u00e9 - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Allah est Unique Les Chr\u00e9tiens doivent \u00e9viter une conception confuse de la religion \u00e0 travers la croyance de la trinit\u00e9 (Notre Seigneur transcende toutes les d\u00e9clarations dans lesquelles nous avons exprim\u00e9 les points de vue erron\u00e9s des Chr\u00e9tiens et qui ne sont pas conformes au respect) Certains Chr\u00e9tiens, influenc\u00e9s par les erreurs d\u2019orientations et de &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-25T11:49:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"\u00e9vitez la trinit\u00e9\",\"datePublished\":\"2012-03-25T11:49:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/\"},\"wordCount\":2498,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/22.jpg\",\"articleSection\":[\"Christ\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/\",\"name\":\"\u00e9vitez la trinit\u00e9 - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/22.jpg\",\"datePublished\":\"2012-03-25T11:49:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/22.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2012\\\/03\\\/22.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/evitez-la-trinite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00e9vitez la trinit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00e9vitez la trinit\u00e9 - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00e9vitez la trinit\u00e9 - L'islam est la verit\u00e9","og_description":"Allah est Unique Les Chr\u00e9tiens doivent \u00e9viter une conception confuse de la religion \u00e0 travers la croyance de la trinit\u00e9 (Notre Seigneur transcende toutes les d\u00e9clarations dans lesquelles nous avons exprim\u00e9 les points de vue erron\u00e9s des Chr\u00e9tiens et qui ne sont pas conformes au respect) Certains Chr\u00e9tiens, influenc\u00e9s par les erreurs d\u2019orientations et de &hellip;","og_url":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2012-03-25T11:49:20+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"\u00e9vitez la trinit\u00e9","datePublished":"2012-03-25T11:49:20+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/"},"wordCount":2498,"commentCount":0,"image":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg","articleSection":["Christ"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/","url":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/","name":"\u00e9vitez la trinit\u00e9 - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg","datePublished":"2012-03-25T11:49:20+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/evitez-la-trinite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#primaryimage","url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg","contentUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2012\/03\/22.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/evitez-la-trinite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00e9vitez la trinit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=187"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media\/186"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}