{"id":36,"date":"2011-01-25T14:30:35","date_gmt":"2011-01-25T14:30:35","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2011\/01\/25\/qui-est-barnabe\/"},"modified":"2011-01-25T14:30:35","modified_gmt":"2011-01-25T14:30:35","slug":"qui-est-barnabe","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/","title":{"rendered":"Qui est Barnab\u00e9"},"content":{"rendered":"<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: medium;\">Barnab\u00e9 est l&rsquo;un des premiers \u00e0 annoncer l&rsquo;Evangile. Il \u00e9tait originaire de Chypre, Converti tr\u00e8s t\u00f4t, Il a accompagn\u00e9 J\u00e9sus-Christ depuis le d\u00e9but de sa mission, avant qu&rsquo;il choisit ses douze ap\u00f4tres. Son nom \u00e9tait Joseph, mais les Ap\u00f4tres lui donneront celui de Barnab\u00e9 qui signifie \u00a0\u00bb fils d&rsquo;encouragement \u00ab\u00a0. (Actes 4:36).<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: medium;\">Lorsque J\u00e9sus annon\u00e7a a ses disciples qu il se trouvait parmi eux celui qui devait le trahir, \u00a0\u00bb Barnab\u00e9 interrogea secr\u00e8tement J\u00e9sus en pleurant : \u00abMa\u00eetre, Satan ne me trompera-t-il? Serai-je donc r\u00e9prouv\u00e9? \u00bb J\u00e9sus r\u00e9pondit : \u00abNe t&rsquo;attriste pas, Barnab\u00e9, car ceux que Dieu a choisis avant la cr\u00e9ation du monde, ne p\u00e9riront pas! R\u00e9jouis-toi parce que ton nom est inscrit au livre de la vie.\u00bb\u00a0\u00bb (Barnab\u00e9 19)<br \/>Il fut l&rsquo;un des premiers \u00e0 vendre ses biens et \u00e0 faire profiter l&rsquo;Eglise naissante du montant de cette vente (Actes 4:37). Il se trouvait parmi les Ap\u00f4tres dans le C\u00e9nacle lors de l&rsquo;\u00e9pisode de la Pentec\u00f4te.<br \/>\u00ab\u00a0Il \u00e9tait un homme de bien, plein d&rsquo;Esprit Saint et de foi.\u00a0\u00bb (Actes 11:24).<br \/>C&rsquo;est lui qui pr\u00e9sentera Paul, apr\u00e8s sa conversion, \u00e0 Pierre et Jacques. Il travaillera un an avec Paul \u00e0 Antioche o\u00f9, dit-on, ses discours attiraient le peuple qui le consid\u00e9rait comme investi du Saint-Esprit. C&rsquo;est \u00e0 cette \u00e9poque que les adeptes du Christ commencent \u00e0 porter le nom de \u00ab\u00a0chr\u00e9tiens\u00a0\u00bb. Paul et Barnab\u00e9 sont alors d\u00e9sign\u00e9s pour devenir les ap\u00f4tres des Gentils.<br \/>La derni\u00e8re chose que l&rsquo;on sait de la vie de Barnab\u00e9, c&rsquo;est qu&rsquo;apr\u00e8s s&rsquo;\u00eatre s\u00e9par\u00e9 de Paul, il est parti en Chypre. Les textes choisis comme canoniques dans le Nouveau testament raconte la cause de leur s\u00e9paration que Barnab\u00e9 \u00a0\u00bb voulait emmener aussi Jean, surnomm\u00e9 Marc; alors que Paul jugea plus convenable de ne pas prendre avec eux celui qui l es avait quitt\u00e9s depuis la Pamphylie, et qui ne les avait point accompagn\u00e9s dans leur \u0153uvre. Et Barnab\u00e9 prenant Marc avec lui, s&#8217;embarqua pour l&rsquo;\u00eele de Chypre\u00a0\u00bb. (Actes 15:36-39). Apr\u00e8s cette s\u00e9paration on entend plus parler de Barnab\u00e9! Juste de Paul.<br \/>Mais d&rsquo;apr\u00e8s l&rsquo;\u00e9vangile de Barnab\u00e9 la raison semble \u00eatre bien diff\u00e9rente, il s&rsquo;agit d&rsquo;une divergence dans la foi entre les deux, Paul a commenc\u00e9 \u00e0 pr\u00eacher une autre doctrine que celle que pr\u00eachait Barnab\u00e9, comme le dit celui-ci dans le premier chapitre de son \u00e9vangile \u00ab\u00a0&#8230;. pr\u00eachent une doctrine fort impie: ils appellent J\u00e9sus fils de Dieu, rejettent la circoncision, alliance de Dieu \u00e0 jamais, et autorisent toute sorte d&rsquo;aliments impurs. Parmi eux, Paul lui-m\u00eame est dans l&rsquo;erreur \u00ab\u00a0. Aussi dans le dernier chapitre: \u00a0\u00bb d&rsquo;autres, et parmi eux se trouve Paul, tromp\u00e9 lui aussi, pr\u00eachaient et pr\u00eachent encore maintenant que J\u00e9sus est le fils de Dieu. Quant \u00e0 nous, nous pr\u00eachons \u00e0 ceux qui craignent Dieu tout ce qu&rsquo;il a \u00e9crit pour qu&rsquo;ils soient sauv\u00e9s au dernier jour du jugement de Dieu. Amen! \u00ab\u00a0<br \/>Suivez nous pour avoir le texte int\u00e9gral de l&rsquo;\u00e9vangile de Barnab\u00e9<br \/><\/span><\/span><a href=\"http:\/\/www.ebnmaryam.com\/\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: medium;\">http:\/\/www.ebnmaryam.com\/<\/span><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barnab\u00e9 est l&rsquo;un des premiers \u00e0 annoncer l&rsquo;Evangile. Il \u00e9tait originaire de Chypre, Converti tr\u00e8s t\u00f4t, Il a accompagn\u00e9 J\u00e9sus-Christ depuis le d\u00e9but de sa mission, avant qu&rsquo;il choisit ses douze ap\u00f4tres. Son nom \u00e9tait Joseph, mais les Ap\u00f4tres lui donneront celui de Barnab\u00e9 qui signifie \u00a0\u00bb fils d&rsquo;encouragement \u00ab\u00a0. (Actes 4:36). Lorsque J\u00e9sus annon\u00e7a &hellip;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-bibel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui est Barnab\u00e9 - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui est Barnab\u00e9 - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Barnab\u00e9 est l&rsquo;un des premiers \u00e0 annoncer l&rsquo;Evangile. Il \u00e9tait originaire de Chypre, Converti tr\u00e8s t\u00f4t, Il a accompagn\u00e9 J\u00e9sus-Christ depuis le d\u00e9but de sa mission, avant qu&rsquo;il choisit ses douze ap\u00f4tres. Son nom \u00e9tait Joseph, mais les Ap\u00f4tres lui donneront celui de Barnab\u00e9 qui signifie \u00a0\u00bb fils d&rsquo;encouragement \u00ab\u00a0. (Actes 4:36). Lorsque J\u00e9sus annon\u00e7a &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-25T14:30:35+00:00\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"Qui est Barnab\u00e9\",\"datePublished\":\"2011-01-25T14:30:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/\"},\"wordCount\":516,\"commentCount\":0,\"articleSection\":[\"Gospel- Bible\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/\",\"name\":\"Qui est Barnab\u00e9 - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"datePublished\":\"2011-01-25T14:30:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/qui-est-barnabe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui est Barnab\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui est Barnab\u00e9 - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/","og_locale":"fr_FR","og_type":"article","og_title":"Qui est Barnab\u00e9 - L'islam est la verit\u00e9","og_description":"Barnab\u00e9 est l&rsquo;un des premiers \u00e0 annoncer l&rsquo;Evangile. Il \u00e9tait originaire de Chypre, Converti tr\u00e8s t\u00f4t, Il a accompagn\u00e9 J\u00e9sus-Christ depuis le d\u00e9but de sa mission, avant qu&rsquo;il choisit ses douze ap\u00f4tres. Son nom \u00e9tait Joseph, mais les Ap\u00f4tres lui donneront celui de Barnab\u00e9 qui signifie \u00a0\u00bb fils d&rsquo;encouragement \u00ab\u00a0. (Actes 4:36). Lorsque J\u00e9sus annon\u00e7a &hellip;","og_url":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2011-01-25T14:30:35+00:00","author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"Qui est Barnab\u00e9","datePublished":"2011-01-25T14:30:35+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/"},"wordCount":516,"commentCount":0,"articleSection":["Gospel- Bible"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/qui-est-barnabe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/","url":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/","name":"Qui est Barnab\u00e9 - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"datePublished":"2011-01-25T14:30:35+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/qui-est-barnabe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/qui-est-barnabe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Qui est Barnab\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}