{"id":74,"date":"2011-11-01T08:53:11","date_gmt":"2011-11-01T08:53:11","guid":{"rendered":"http:\/\/localhost\/rs\/fr\/2011\/11\/01\/les-vertus-du-vinaigre\/"},"modified":"2011-11-01T08:53:11","modified_gmt":"2011-11-01T08:53:11","slug":"les-vertus-du-vinaigre","status":"publish","type":"post","link":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/","title":{"rendered":"Les vertus du vinaigre"},"content":{"rendered":"<h2><span style=\"color: #0000ff;\"><em><strong><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Les vertus du vinaigre<\/span><\/span><\/strong><\/em><\/span><\/h2>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-72\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg\" border=\"0\" width=\"109\" height=\"154\" \/><br \/><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">elon le Hadith rapport\u00e9 par Mouslim (4\/16) et Ahmed (3\/103), le Proph\u00e8te Mohamed\u00a0 (b\u00e9n\u00e9diction et salut soient sur lui) a dit\u00a0: \u00ab\u00a0Quelle excellente sauce qu\u2019est le vinaigre\u00a0!\u00a0\u00bb\u00a0<span style=\"color: #0000ff;\">(La traduction du Hadith).<\/span><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Il a dit aussi<span style=\"color: #0000ff;\"> (b\u00e9n\u00e9diction et salut soient sur lui)\u00a0: \u00ab\u00a0que Allah le Tr\u00e8s Haut b\u00e9nisse le vinaigre parce que c\u2019\u00e9tait la sauce des proph\u00e8tes avant moi\u00a0\u00bb. Rapport\u00e9 par Ibn Madja (3318)<\/span> et Dhaif al-Djami (5973).<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Les bienfaits du vinaigre ont \u00e9t\u00e9 prouv\u00e9s scientifiquement\u00a0: Il r\u00e9duit le niveau des <img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-73\" src=\"http:\/\/localhost\/rs\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/po.jpg\" border=\"0\" style=\"float: right; margin: 15px;\" width=\"425\" height=\"283\" srcset=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/po.jpg 425w, https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/po-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/>graisses dans le sang, si on en assaisonne une salade verte par exemple\u00a0; car il contient de l\u2019acide ac\u00e9tique qui entre en interaction avec les prot\u00e9ines, les graisses et les hydrates de carbone et aboutit \u00e0 la formation d\u2019une mol\u00e9cule scientifiquement appel\u00e9e l\u2019Acetoacetate.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Ajouter le vinaigre r\u00e9guli\u00e8rement aux repas, de pr\u00e9f\u00e9rence le vinaigre de Cidre de pomme, \u00e0 titre d\u2019indication\u00a0en assaisonnant une salade verte ou en diluant une cuiller\u00e9e \u00e0 caf\u00e9 dans un verre d\u2019eau, r\u00e9duit consid\u00e9rablement le niveau de graisses dans le corps humain et aide \u00e0 pr\u00e9venir les maladies cardiovasculaires, en convertissant l\u2019exc\u00e8s de graisses en Acetoacetate\u00a0; ce dernier qui entre dans le m\u00e9tabolisme alimentaire.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Aussi, le Proph\u00e8te (b\u00e9n\u00e9diction et salut soient sur lui) mangeait-Il du vinaigre avec de l\u2019huile. Durant l\u2019ann\u00e9e des <span style=\"color: #0000ff;\">\u00ab\u00a0cendres\u00a0\u00bb<\/span>[1], Omar Ibn Khattab (qu&rsquo;Allah soit satisfait de lui) ne mangeait que du vinaigre et de l\u2019huile, et n\u2019a jamais mang\u00e9 de la viande sauf si les pauvres des musulmans en soient rassasi\u00e9s.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Le vinaigre de Cidre de pomme reste ainsi le meilleur\u00a0: Il contient, outre l\u2019acide ac\u00e9tique, des acides organiques qui entre dans le m\u00e9tabolisme alimentaire et des min\u00e9raux indispensables pour le corps humain.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Le livre du Docteur Jaffr\u00e8s \u00ab\u00a0M\u00e9decine Populaire\u00a0\u00bb qualifie le vinaigre d\u2019un excellent antiseptique pour le syst\u00e8me digestif et d\u2019un anti-inflammatoire naturel pour les reins et la vessie.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong><span style=\"color: #0000ff;\">Source<\/span> :<\/strong> \u00ab\u00a0Gu\u00e9rir gr\u00e2ce aux v\u00e9g\u00e9taux et \u00e0 la m\u00e9decine proph\u00e9tique\u00a0\u00bb. Docteur Abd Albasset Mohamed. Professeur de la bact\u00e9riologie et de la microbiologie dans plusieurs universit\u00e9s en \u00c9gypte.<strong> <\/strong><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Traduit par: Youssef Daou<\/span><\/span><\/p>\n<hr width=\"33%\" size=\"1\" \/>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">[1] &#8211; Une ann\u00e9e o\u00f9 les musulmans avaient v\u00e9cu une disette \u00e0 l\u2019\u00e9poque du r\u00e8gne de Omar Ibn Alkhattab<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les vertus du vinaigre elon le Hadith rapport\u00e9 par Mouslim (4\/16) et Ahmed (3\/103), le Proph\u00e8te Mohamed\u00a0 (b\u00e9n\u00e9diction et salut soient sur lui) a dit\u00a0: \u00ab\u00a0Quelle excellente sauce qu\u2019est le vinaigre\u00a0!\u00a0\u00bb\u00a0(La traduction du Hadith). Il a dit aussi (b\u00e9n\u00e9diction et salut soient sur lui)\u00a0: \u00ab\u00a0que Allah le Tr\u00e8s Haut b\u00e9nisse le vinaigre parce que c\u2019\u00e9tait &hellip;<\/p>\n","protected":false},"author":7,"featured_media":72,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-74","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-miracles-du-coran"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les vertus du vinaigre - L&#039;islam est la verit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vertus du vinaigre - L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Les vertus du vinaigre elon le Hadith rapport\u00e9 par Mouslim (4\/16) et Ahmed (3\/103), le Proph\u00e8te Mohamed\u00a0 (b\u00e9n\u00e9diction et salut soient sur lui) a dit\u00a0: \u00ab\u00a0Quelle excellente sauce qu\u2019est le vinaigre\u00a0!\u00a0\u00bb\u00a0(La traduction du Hadith). Il a dit aussi (b\u00e9n\u00e9diction et salut soient sur lui)\u00a0: \u00ab\u00a0que Allah le Tr\u00e8s Haut b\u00e9nisse le vinaigre parce que c\u2019\u00e9tait &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;islam est la verit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-01T08:53:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"126\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"Les vertus du vinaigre\",\"datePublished\":\"2011-11-01T08:53:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/\"},\"wordCount\":407,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2011\\\/11\\\/jk.jpg\",\"articleSection\":[\"Miracles du coran\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/\",\"name\":\"Les vertus du vinaigre - L'islam est la verit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2011\\\/11\\\/jk.jpg\",\"datePublished\":\"2011-11-01T08:53:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2011\\\/11\\\/jk.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2011\\\/11\\\/jk.jpg\",\"width\":126,\"height\":190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/les-vertus-du-vinaigre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les vertus du vinaigre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/\",\"name\":\"L'islam est la verit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"url\":\"https:\\\/\\\/r-islam.com\\\/fr\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les vertus du vinaigre - L'islam est la verit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/","og_locale":"fr_FR","og_type":"article","og_title":"Les vertus du vinaigre - L'islam est la verit\u00e9","og_description":"Les vertus du vinaigre elon le Hadith rapport\u00e9 par Mouslim (4\/16) et Ahmed (3\/103), le Proph\u00e8te Mohamed\u00a0 (b\u00e9n\u00e9diction et salut soient sur lui) a dit\u00a0: \u00ab\u00a0Quelle excellente sauce qu\u2019est le vinaigre\u00a0!\u00a0\u00bb\u00a0(La traduction du Hadith). Il a dit aussi (b\u00e9n\u00e9diction et salut soient sur lui)\u00a0: \u00ab\u00a0que Allah le Tr\u00e8s Haut b\u00e9nisse le vinaigre parce que c\u2019\u00e9tait &hellip;","og_url":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/","og_site_name":"L'islam est la verit\u00e9","article_published_time":"2011-11-01T08:53:11+00:00","og_image":[{"width":126,"height":190,"url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ahmed Abdallah","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"Les vertus du vinaigre","datePublished":"2011-11-01T08:53:11+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/"},"wordCount":407,"commentCount":0,"image":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg","articleSection":["Miracles du coran"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/","url":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/","name":"Les vertus du vinaigre - L'islam est la verit\u00e9","isPartOf":{"@id":"https:\/\/r-islam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg","datePublished":"2011-11-01T08:53:11+00:00","author":{"@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"breadcrumb":{"@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#primaryimage","url":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg","contentUrl":"https:\/\/r-islam.com\/fr\/wp-content\/uploads\/sites\/5\/2011\/11\/jk.jpg","width":126,"height":190},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/fr\/les-vertus-du-vinaigre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les vertus du vinaigre"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/fr\/#website","url":"https:\/\/r-islam.com\/fr\/","name":"L'islam est la verit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/r-islam.com\/fr\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","url":"https:\/\/r-islam.com\/fr\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media\/72"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/fr\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}