{"id":1026,"date":"2017-06-05T09:03:35","date_gmt":"2017-06-05T09:03:35","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2017\/06\/05\/il-rame-nello-spazio-cosmico\/"},"modified":"2017-06-05T09:03:35","modified_gmt":"2017-06-05T09:03:35","slug":"il-rame-nello-spazio-cosmico","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/","title":{"rendered":"Il rame nello spazio cosmico"},"content":{"rendered":"<p style=\"direction: ltr; unicode-bidi: embed; text-align: center;\"><strong><span style=\"color: #0000ff; font-size: 14pt; font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1024\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg\" alt=\"\" width=\"464\" height=\"328\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg 720w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito-300x212.jpg 300w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/span><\/strong><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: center;\"><strong><span style=\"color: #0000ff; font-size: 14pt; font-family: 'times new roman', times;\">Il rame nello spazio cosmico<\/span><\/strong><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">Ci sono dei meteoriti incandescenti che emettono luce verde\u00a0 quando attraversano l\u2019atmosfera terrestre\u00a0 perch\u00e9? Gli scienziati hanno studiato questo fenomeno ed hanno scoperto che questi meteoriti contengono il rame, che si scioglie ed evapora durante l&#8217;attrito atmosferico a causa della velocit\u00e0 tremenda<span dir=\"RTL\">.<\/span><\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">Queste sono le immagini di alcuni meteoriti che emettono luce verde per la presenza del rame fra i loro componenti, gli scienziati dicono che la fusione del rame, in questo modo, genera energia termica tremenda raggiunge una temperatura di pi\u00f9 di duemila gradi Celsius<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1025\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/442.jpg\" alt=\"\" width=\"650\" height=\"261\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/442.jpg 650w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/442-300x120.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">il fenomeno dei meteoriti che contengono rame e presenti nello spazio \u00e8 stato scoperto solo di recente &#8230; Ma Allah L&#8217;Onnipotente\u00a0 ci ha parlato, nel Sacro Corano,\u00a0 di tali meteoriti con riferimento all&#8217;elemento di rame in esso.<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"color: #008000; font-size: 14pt; font-family: 'times new roman', times;\">&#8221; O consesso dei d\u00e8moni e degli uomini, se potrete varcare i limiti dei cieli e\u00a0della terra, fatelo. Non fuggirete senza un&#8217;autorit\u00e0 [proveniente da Allah].<\/span><br \/><span style=\"font-size: 14pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\"> . Quale dunque dei benefici del vostro Signore negherete?\u00a0\u00a0Sar\u00e0 inviata contro entrambi fiamma ardente e rame fuso e non sarete\u00a0soccorsi.&#8221;<\/span> [Corano 55:33-35]<\/span><\/p>\n<p dir=\"RTL\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8220;\u064a\u064e\u0627 \u0645\u064e\u0639\u0652\u0634\u064e\u0631\u064e \u0627\u0644\u0652\u062c\u0650\u0646\u0651\u0650 \u0648\u064e \u0627\u0644\u0652\u0625\u0650\u0646\u0652\u0633\u0650 \u0625\u0650\u0646\u0650 \u0627\u0633\u0652\u062a\u064e\u0637\u064e\u0639\u0652\u062a\u064f\u0645\u0652 \u0623\u064e\u0646\u0652 \u062a\u064e\u0646\u0652\u0641\u064f\u0630\u064f\u0648\u0627 \u0645\u0650\u0646\u0652 \u0623\u064e\u0642\u0652\u0637\u064e\u0627\u0631\u0650 \u0627\u0644\u0633\u0651\u064e\u0645\u064e\u0627\u0648\u064e\u0627\u062a\u0650 \u0648\u064e \u0627\u0644\u0652\u0623\u064e\u0631\u0652\u0636\u0650 \u0641\u064e\u0627\u0646\u0652\u0641\u064f\u0630\u064f\u0648\u0627 \u0644\u064e\u0627 \u062a\u064e\u0646\u0652\u0641\u064f\u0630\u064f\u0648\u0646\u064e \u0625\u0650\u0644\u0651\u064e\u0627 \u0628\u0650\u0633\u064f\u0644\u0652\u0637\u064e\u0627\u0646\u064d * \u0641\u064e\u0628\u0650\u0623\u064e\u064a\u0651\u0650 \u0622\u0644\u064e\u0627\u0621\u0650 \u0631\u064e\u0628\u0651\u0650\u0643\u064f\u0645\u064e\u0627 \u062a\u064f\u0643\u064e\u0630\u0651\u0650\u0628\u064e\u0627\u0646\u0650 * \u064a\u064f\u0631\u0652\u0633\u064e\u0644\u064f \u0639\u064e\u0644\u064e\u064a\u0652\u0643\u064f\u0645\u064e\u0627 \u0634\u064f\u0648\u064e\u0627\u0638\u064c \u0645\u0650\u0646\u0652 \u0646\u064e\u0627\u0631\u064d \u0648\u064e \u0646\u064f\u062d\u064e\u0627\u0633\u064c \u0641\u064e\u0644\u064e\u0627 \u062a\u064e\u0646\u0652\u062a\u064e\u0635\u0650\u0631\u064e\u0627\u0646\u0650<\/span><span dir=\"LTR\">]\u00a0 <span style=\"color: #008000;\">&#8220;<\/span><\/span>\u0627\u0644\u0631\u062d\u0645\u0646: 33-355<span dir=\"LTR\">[<\/span><\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">La parola araba &#8221; <span dir=\"RTL\" style=\"color: #008000;\">\u0634\u064f\u0648\u064e\u0627\u0638\u064c<\/span>&#8221; &#8220;<span style=\"color: #008000;\"><em>shwaz<\/em><\/span>&#8221; che significa &#8221; una fiamma senza fumo&#8221; si considera un miracolo in se stesso, perch\u00e9 non si pu\u00f2 formare il fumo senza ossigeno. E nello spazio cosmico come sappiamo non c&#8217;\u00e8 ossigeno e quindi non si pu\u00f2 formare il fumo.<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">ma proviene una scintilla violento come un tifone di fuoco che \u00e8 formato a causa\u00a0 della fusione ed evaporazione del rame &#8230; il fumo che sappiamo consiste principalmente del primo e del secondo anidride carbonica e altri componenti della cui composizione l&#8217;ossigeno fa parte .<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">La nostra domanda per gli scettici sul Sacro Corano: come il nostro profeta -pace e benedizione su di lui- ha saputo che il rame esiste nello spazio cosmicoe la sua combustione\u00a0 si considera un tipo di grave tormento? E da dove ha portato la parola (&#8220;<span style=\"color: #339966;\"><em><span dir=\"RTL\">\u0634\u064f\u0648\u064e\u0627\u0638\u064c<\/span><\/em><\/span>&#8221; &#8220;<span style=\"color: #0000ff;\"><strong><em>shwaz<\/em><\/strong><\/span>&#8221; ) che \u00e8 molto adatta ad esprimere la combustione del rame nello spazio cosmico dove non c&#8217;\u00e8 ossigeno,\u00a0 quindi \u00a0,solo, \u00a0genera una palla di fuoco che si brucia senza fumo\u00a0 ..<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\"> Alla fine non possiamo dire che &#8220;subhanallah&#8221; Gloria ad Allah\u00a0 !<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">Traduzione : Ahmad Abdullah<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">www.r-islam.com\/it<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">la fonte del testo originale :<\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed; text-align: justify;\"><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">http:\/\/www.kaheel7.com\/ar\/index.php\/2010-02-02-20-06-04\/1985-2017-01-19-21-28-03<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il rame nello spazio cosmico Ci sono dei meteoriti incandescenti che emettono luce verde\u00a0 quando attraversano l\u2019atmosfera terrestre\u00a0 perch\u00e9? Gli scienziati hanno studiato questo fenomeno ed hanno scoperto che questi meteoriti contengono il rame, che si scioglie ed evapora durante l&#8217;attrito atmosferico a causa della velocit\u00e0 tremenda. Queste sono le immagini di alcuni meteoriti che &hellip;<\/p>\n","protected":false},"author":6,"featured_media":1024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il rame nello spazio cosmico - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Il rame nello spazio cosmico II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il rame nello spazio cosmico - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Il rame nello spazio cosmico II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-05T09:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Il rame nello spazio cosmico\",\"datePublished\":\"2017-06-05T09:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/ilramesito.jpg\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/\",\"name\":\"Il rame nello spazio cosmico - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/ilramesito.jpg\",\"datePublished\":\"2017-06-05T09:03:35+00:00\",\"description\":\"Il rame nello spazio cosmico II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/ilramesito.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/06\\\/ilramesito.jpg\",\"width\":720,\"height\":509},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-rame-nello-spazio-cosmico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il rame nello spazio cosmico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il rame nello spazio cosmico - II vero Islam II vero Islam","description":"Il rame nello spazio cosmico II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/","og_locale":"it_IT","og_type":"article","og_title":"Il rame nello spazio cosmico - II vero Islam II vero Islam","og_description":"Il rame nello spazio cosmico II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/","og_site_name":"II vero Islam","article_published_time":"2017-06-05T09:03:35+00:00","og_image":[{"width":720,"height":509,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Il rame nello spazio cosmico","datePublished":"2017-06-05T09:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/","url":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/","name":"Il rame nello spazio cosmico - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg","datePublished":"2017-06-05T09:03:35+00:00","description":"Il rame nello spazio cosmico II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/06\/ilramesito.jpg","width":720,"height":509},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-rame-nello-spazio-cosmico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il rame nello spazio cosmico"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/1026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=1026"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/1026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/1024"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=1026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=1026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=1026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}