{"id":103,"date":"2018-11-05T08:31:00","date_gmt":"2018-11-05T08:31:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2018\/11\/05\/islam-religione-e-politica\/"},"modified":"2018-11-05T08:31:00","modified_gmt":"2018-11-05T08:31:00","slug":"islam-religione-e-politica","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/","title":{"rendered":"Islam: religione e politica"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-102\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png 500w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica-300x300.png 300w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><strong><span style=\"color: #0000ff;\"><span style=\"font-family: 'times new roman', times;\">Islam: religione e politica<\/span><\/span><\/strong><\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><span style=\"font-family: 'times new roman', times;\"><span style=\"color: #0000ff;\">L&#8217;Islam \u00e8 soltanto una religione della salvezza o \u00e8 anche una religione preoccupata della politica, e quindi della societ\u00e0?\u00a0<\/span><\/p>\n<p>Il Profeta Mohammed&#8221; pace e benedizione su di lui&#8221; fu un leader religioso e politico, prima alla Mecca e poi a Medina. E l&#8217;intima connessione di religione e politica nell&#8217;Islam emerge anche dall&#8217;analisi &#8211; dello storico americano John O. Voli &#8211; dei primi califfati musulmani. Dalla pratica politica e dalla storia di questo primo periodo dell&#8217;Islam infatti si possono cogliere come predominanti quattro correnti di pensiero religioso ma anche politico: l\u2019\u00abadattamentismo\u00bb, il conservatorismo, il fondamentalismo e il personalismo. Quattro sfaccettature dell&#8217;ideologia islamica che vivono e si riscontrano anche nella pratica attuale.<\/p>\n<p><strong><span style=\"color: #0000ff;\">Ma l&#8217;Islam \u00e8 una religione della salvezza o una religione che si occupa d\u00ec politica?\u00a0<\/span><\/strong><\/p>\n<p>Questa, \u00e8 una domanda troppo semplice, che falsa il problema e non riesce a far capire l&#8217;ampiezza delle questioni e la loro importanza attuale.<\/p>\n<p>Il problema, infatti, va posto in una prospettiva geografica e storica ampia. Se teniamo conto di questo ampliarsi, sia nel tempo che nello spazio, del problema delle religioni oggi, riusciremo a capire che il ritorno del religioso nel mondo contemporaneo \u00e8 imposto da un numero di societ\u00e0 nuove che si affermano storicamente. Ciascuna di queste societ\u00e0 ha una sua tradizione religiosa che costituisce il solo linguaggio, la sola ideologia per le masse popolari e ne esprime la condizione storica.<\/p>\n<p>Le popolazioni d&#8217;Africa, le popolazioni d&#8217;Asia, non hanno a loro disposizione, per costruire una societ\u00e0, per risolvere i loro problemi, l&#8217;ideologia laica, per esempio, che \u00e8 stata forgiata nell&#8217;Europa Occidentale e che \u00e8 divenuta in questa parte del mondo un sostituto dell&#8217;ideologia religiosa. <\/p>\n<p>Quindi tenendo conto di questo contesto si pu\u00f2 ancora formulare la domanda per l&#8217;Islam &#8211; come per il cristianesimo o il buddismo o qualsiasi altra religione-: \u00e8 una religione della salvezza o una religione che organizza la &#8220;citt\u00e0&#8221;, o tutte e due le cose assieme? <\/p>\n<p>In realt\u00e0 ogni religione, fin dalle sue origini, si sforza di rispondere a dei bisogni umani pratici. Voglio dire, ad esempio, che ogni religione tenta di rispondere all&#8217;aspirazione dell&#8217;uomo a vivere eternamente. E l&#8217;Islam si inscrive appunto nel quadro delle religioni monoteiste le quali, tutte, mettono l&#8217;accento sull&#8217;immortalit\u00e0 dell&#8217;uomo.<\/p>\n<p>A partire dal Corano stesso, noi troviamo uno sforzo da parte del Profeta per risolvere certi problemi pratici di organizzazione della &#8220;citt\u00e0&#8221;\u00bb.<\/p>\n<p>Intervista di M. Arosio al prof. Mohammed Arkoun da: Islam. Religione e Societ\u00e0, ERI, 1980<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><span style=\"font-family: 'times new roman', times;\"><strong><span style=\"color: #0000ff;\">Mohammed&#8221; pace e benedizione su di lui&#8221;: La Mecca e Medina<\/span><\/strong><\/p>\n<p>&#8211; In quali termini la storiografia Islamica prospetta i rapporti tra la dimensione pi\u00f9 squisitamente profetico-religiosa dell&#8217;esperienza di Muhammad e il ruolo svolto da\u00a0lui come Profeta, alle origini dell&#8217;Islam, nella sua qualit\u00e0 di grande leader politico-militare e di legislatore. Dal momento che l&#8217;esperienza originaria di Muhammad e la sua stessa figura hanno assunto -e non poteva essere diversamente- una funzione esemplare e paradigmatica per tutta la storia dell&#8217;Islam.<\/p>\n<p>&#8211; Indubbiamente Muhammad &#8221; pace e benedizione su di lui&#8221; rimane, non soltanto il personaggio chiave per capire le origini dell&#8217;Islam, ma anche la figura esemplare a cui l&#8217;Islam si \u00e8 sempre rifatto e continua a rifarsi tuttora in tutti gli ambiti del suo manifestarsi storico. <\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><span style=\"font-family: 'times new roman', times;\">\u00a0Ma, va detto subito che nessuno nega che la sua esperienza pi\u00f9 squisitamente religiosa del\u00a0profeta\u00a0Muhammad &#8221; pace e benedizione su di lui&#8221; si \u00e8 intrecciata con il suo impegno di grande leader carismatico e di abile uomo politico, che \u00e8 riuscito, per la prima volta, a mettere pace fra tutte le trib\u00f9 della penisola arabica e ad avviare prospettive di unit\u00e0 per i suoi connazionali.<\/p>\n<p><\/span><\/span><\/span><\/span><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><span style=\"font-family: 'times new roman', times;\"><br \/>In occasione del congresso islamico-cristiano di Cordova nel marzo 1977, nella relazione del professor &#8216;Abd al-&#8216;Az\u00ecz K\u00e0mil, ex vice primo ministro dell&#8217;Egitto. Costui sosteneva che Muhammad era stato un perfetto Ministro degli Interni, un perfetto Ministro degli Esteri, un perfetto Ministro delle Finanze e, per finire, un comandante in campo perfetto. E concludeva: \u00ab<span style=\"color: #800080;\">\u00c8 naturale. Nella stanza di ogni profeta ci dev&#8217;essere una spada<\/span>\u00bb.<\/p>\n<p><span style=\"color: #0000ff;\">&#8211; Come concludere allora anche per capire certi fenomeni dell&#8217;Islam attuale?<\/span><\/p>\n<p>&#8211; Direi che bisogna partire dal presupposto che non \u00e8 possibile negare il rapporto di continuit\u00e0 che intercorre tra l&#8217;esperienza meccana e quella medinese. In definitiva, si pu\u00f2 affermare con onest\u00e0 che Medina realizza pienamente la norma gi\u00e0 prevista alla Mecca. Per essi, dunque, Medina non \u00e8 soltanto un avatar della storia, ma costituisce la realizzazione dell&#8217;Islam nella sua pienezza. Medina, anzi, rappresenta per essi lo stato ideale, il modello a cui dovrebbe ispirarsi, nella sua sostanza, ogni stato musulmano moderno. <\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><span style=\"font-family: 'times new roman', times;\">\u00a0Non dovremo mai dimenticare infatti che per i veri credenti musulmani Muhammad &#8221; pace e benedizione su di lui&#8221; rimane, innanzi tutto, il modello pi\u00f9 perfetto di una profonda esperienza religiosa che essi si sforzano di imitare con venerazione. <\/p>\n<p>Intervista di Mario Arosio al prof. Maurice Borrmans (docente di Lingua Araba, Diritto musulmano, Spiritualit\u00e0 Islamica al Pontificio Istituto di Studi Arabi di Roma) da: Islam. Religione e Societ\u00e0, ERI, 1980<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large; color: #ff0000;\"><span style=\"font-family: 'times new roman', times;\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: 'times new roman', times;\">tratto da: <span style=\"line-height: 16px;\">arab.it<\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Islam: religione e politica L&#8217;Islam \u00e8 soltanto una religione della salvezza o \u00e8 anche una religione preoccupata della politica, e quindi della societ\u00e0?\u00a0 Il Profeta Mohammed&#8221; pace e benedizione su di lui&#8221; fu un leader religioso e politico, prima alla Mecca e poi a Medina. E l&#8217;intima connessione di religione e politica nell&#8217;Islam emerge anche &hellip;<\/p>\n","protected":false},"author":6,"featured_media":102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-verita-dell-isalm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Islam: religione e politica - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Islam: religione e politica II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Islam: religione e politica - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Islam: religione e politica II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-05T08:31:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Islam: religione e politica\",\"datePublished\":\"2018-11-05T08:31:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/\"},\"wordCount\":816,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/11\\\/11religpolitica.png\",\"articleSection\":[\"La verit\u00e0 dell'Isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/\",\"name\":\"Islam: religione e politica - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/11\\\/11religpolitica.png\",\"datePublished\":\"2018-11-05T08:31:00+00:00\",\"description\":\"Islam: religione e politica II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/11\\\/11religpolitica.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/11\\\/11religpolitica.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/islam-religione-e-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Islam: religione e politica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Islam: religione e politica - II vero Islam II vero Islam","description":"Islam: religione e politica II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/","og_locale":"it_IT","og_type":"article","og_title":"Islam: religione e politica - II vero Islam II vero Islam","og_description":"Islam: religione e politica II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/","og_site_name":"II vero Islam","article_published_time":"2018-11-05T08:31:00+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Islam: religione e politica","datePublished":"2018-11-05T08:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/"},"wordCount":816,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png","articleSection":["La verit\u00e0 dell'Isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/","url":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/","name":"Islam: religione e politica - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png","datePublished":"2018-11-05T08:31:00+00:00","description":"Islam: religione e politica II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/islam-religione-e-politica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/11\/11religpolitica.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/islam-religione-e-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Islam: religione e politica"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/102"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}