{"id":184,"date":"2017-04-10T00:14:00","date_gmt":"2017-04-10T00:14:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2017\/04\/10\/il-ritorno-all-islam-di-adriana\/"},"modified":"2017-04-10T00:14:00","modified_gmt":"2017-04-10T00:14:00","slug":"il-ritorno-all-islam-di-adriana","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/","title":{"rendered":"Il Ritorno all&#8217;Islam di Adriana"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-183\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png\" alt=\"\" width=\"720\" height=\"406\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png 720w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22-300x169.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">Il Ritorno all&#8217;Islam di Adriana<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Nel Nome di Allah, il Compassionevole, il Misericordioso<\/span>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Mi chiamo Adriana, vengo da un padre non credente ed una madre molto credente e praticante cattolica. Ogni domenica andavo in chiesa e fin da piccola pregavo Allah che mi proteggesse che mi desse la vera felicit\u00e0, che mi guidasse nella verit\u00e0 della strada giusta, ho sempre avuto una adorazione un amore particolare per Allah. finch\u00e9 un giorno verso i dodici o tredici anni ebbi il mio primo sogno,sognai che ero in mezzo a delle persone vestite di lungo, le donne avevano il capo coperto, ma non erano suore, parlavano una lingua che io non capivo, ma nel sogno rispondevo a loro ed ero felice di stare con loro, mi trovavo bene, cercavo i miei genitori le mie sorelle, mio fratello, ma non li vedevo e mi spaventava, mi chiedevo chi erano perch\u00e9 vestiti in quel modo.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">questo sogno lo feci per una settimana che alla fine spaventata chiesi a mia madre il significato lei mi rispose solo che era un segno da Allah che quando era il momento avrei capito.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">e cos\u00ec non ci pensai &#8230; feci tanti altri ogni,ma non mi spaventavano, le parole di mia madre mi calmavano.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">e cos\u00ec passarono gli anni, io frequentavo le case della carit\u00e0, le parrocchie, scuola di suore, quando aiutavo queste persone era come che mi avvicinasse a Lui, il Supremo, ed ero felice di dentro, serenit\u00e0 immensa, perch\u00e9 aiutando le persone come handicappati, semplicemente imboccarli, aiutarli a vestirsi a lavarsi ,la ricompensa pi\u00f9 bella era un loro semplice sorriso, \u00e8 il dono pi\u00f9 bello che si poteva avere, sentirsi vicino al Sublime. E cos\u00ec decisi di farmi suora, ma suora missionaria, il dono pi\u00f9 bello che potevo dare ad Allah, offrirmi a Lui. Ma c&#8217;era qualcosa di dentro che mi frenava &#8230; non capivo &#8230; quante notti a piangere con le mani rivolte all&#8217;Altissimo e chiedere perch\u00e9 di questo tormento dentro di me, eppure io amavo Allah, pi\u00f9 di me stessa, cosa era che non andava di me? Un prete missionario che mi seguiva mi diceva che questo mio tormento era perch\u00e9 non riuscivo a credere nella trinit\u00e0, infatti &#8230; non s\u00f2 spiegarmi perch\u00e9 &#8230; fin da piccola per me Allah \u00e9 Unico non ha figli ed non e&#8217; stato generato, e cos\u00ec mi mettevo sempre pi\u00f9 in crisi, perch\u00e9 non ero una buona credente.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">finch\u00e9 un giorno mentre frequentavo l&#8217;universit\u00e0 conobbi un ragazzo arabo, un musulmano, che io non sapevo nemmeno che esistesse la religione musulmana, mi incurios\u00ec, mi piaceva sentire parlare dell&#8217;islam, come ogni frase ricordava il nostro Signore, ed lui non era una credente praticante, e cos\u00ec cercai di capire, ma dentro ero in conflitto, vedevo che l&#8217;Islam mi allontanava dalla cattolicesimo, stavo male,mi sembrava di far torto ad Allah.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">che quando decidemmo di sposarci, lui mi disse che non poteva sposarmi io con religione cristiana, ma non voleva cheio diventassi musulmana senza capire, e cos\u00ec mi diede tanti libri ed stava a me a decidere, solo a me!<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">un periodo di vero conflitto spirituale, non capivo troppa confusione, avevo paura di far una passo sbagliato, avevo paura del giudizio di Allah, ed una notte sognai che salivo una scala ed questi i gradini di dietro scomparivano mentre quelli davanti aumentavano andavo sempre pi\u00f9 in alto, sentivo di dentro che sapevo quale era la mia decisione.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">E cos\u00ec mi feci aiutare sempre dal mio prete spirituale, che leggendo i libricini della religione musulmana mi propose un &#8220;gioco&#8221; che consisteva nel farmi 10 domande riguardanti le due religioni, lui non mi diceva cosa diceva la cattolica o cosa diceva la musulmana, per non influenzarmi, ed io secondo il mio cuore dovevo scegliere la risposta, ebbene le 10 risposte erano tutte rivolte a ci\u00f2 che diceva l&#8217;islam, il prete pianse,pianse tantissimo e con le lacrime agli occhi mi disse &#8220;vai per la tura strada, noi abbiamo perso una vera credente!&#8221;<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">e cos\u00ec mi sposai con il rito musulmano dichiarando di entrare nell&#8217;Islam, senza che la mia famiglia sapesse(avendo una sorella suora e zia suora), e per motivi familiari venni io con mio figlio da soli qui in un paesino di Palestina (arabi del 48), paese musulmano, non capivo la lingua ma ero felice, le perone che vidi nel sogno quando ero piccola erano qui, e pian piano imparai la lingua,imparai la preghiera ed il ramadan ed molto importante a vestirmi come Allah desidera, non e&#8217; stato difficile, perch\u00e9 quando lo si fa per amor di Allah niente \u00e9 difficile, alhamdillilah.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">E cos\u00ec inviai una casetta ai miei genitori per dire della mia conversione, ma loro ebbero una reazione un po&#8217; difficile, mi dissero che per loro io ero morta, che non esistevo pi\u00f9, ma nonostante questa reazione io mi sentivo felice di dentro, serena, tranquilla,sapevo che non camminavo in una strada sbagliata anche se \u00e9 difficile perdere la propria famiglia, e mi dispiaceva solo che non mi capissero, ed una sera piangendo rivolgendomi ad Allah il Sublime mi addormentai e vidi un uomo vestito di bianco, non vidi il viso, ma sentii che era una persona molto importante, la gente intorno lo chiamavano,ma io non sentii il suo nome chiedevo alle persone chi era, ma nessuno mi dava la risposta, mi dicevano semplicemente che io sapevo, ed io piangendo chiesi a questo uomo di non andarsene di non abbandonarmi e lui si avvicin\u00f2 a me,sentii che mi sorrise,ma non vedevo il suo volto,mi disse &#8220;stai tranquilla anche se pensi che il mondo intero non ti capisca, io sar\u00f2 sempre vicino a te per darti forza, coraggio fede e la vera felicit\u00e0 che non e&#8217; la terrena&#8221;<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">mi svegliai all&#8217;improvviso sudavo, le lacrime agli occhi un pianto non di paura,ma di felicit\u00e0, una felicit\u00e0 che solo Allah pu\u00f2 dare!<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">e dal quel giorno anche se la mia famiglia non mi rispetta non mi considera, non mi pesa sono felice ,io li rispetto e sperando che un giorno capiranno e si uniranno al nostro Unico Allah il Misericordioso.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">sono 20 anni che vivo in questo paese ed ogni sera prima di coricarmi oltre alle invocazioni ad Allah, lo ringrazio del dono pi\u00f9 bello che mi possa aver offerto, non ci sono parole, solo ricordarlo nel pregare, leggere il sacro Corano, la gioia del Ramadan e essere riuscita ad andare al pellegrinaggio minore che mi ha rafforzato il mio credo, la mia fede, il mio amore per l\u2019Altissimo, il Sublime.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Io nel mio semplice dico solo grazie ad Allah di avermi donato la fede, la felicit\u00e0 interiore e di essere musulmana.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Adriana<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">la fonte<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">convertirsi-islam<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ritorno all&#8217;Islam di Adriana &nbsp; Nel Nome di Allah, il Compassionevole, il Misericordioso&nbsp; Mi chiamo Adriana, vengo da un padre non credente ed una madre molto credente e praticante cattolica. Ogni domenica andavo in chiesa e fin da piccola pregavo Allah che mi proteggesse che mi desse la vera felicit\u00e0, che mi guidasse nella &hellip;<\/p>\n","protected":false},"author":6,"featured_media":183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donne-si-sono-convertiti-all-isalm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Ritorno all&#039;Islam di Adriana - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Il Ritorno all&#039;Islam di Adriana II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Ritorno all&#039;Islam di Adriana - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Il Ritorno all&#039;Islam di Adriana II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T00:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Il Ritorno all&#8217;Islam di Adriana\",\"datePublished\":\"2017-04-10T00:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/\"},\"wordCount\":1121,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/04\\\/22.png\",\"articleSection\":[\"Donne si sono convertiti all'isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/\",\"name\":\"Il Ritorno all'Islam di Adriana - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/04\\\/22.png\",\"datePublished\":\"2017-04-10T00:14:00+00:00\",\"description\":\"Il Ritorno all'Islam di Adriana II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/04\\\/22.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/04\\\/22.png\",\"width\":720,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-ritorno-all-islam-di-adriana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Ritorno all&#8217;Islam di Adriana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Ritorno all'Islam di Adriana - II vero Islam II vero Islam","description":"Il Ritorno all'Islam di Adriana II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/","og_locale":"it_IT","og_type":"article","og_title":"Il Ritorno all'Islam di Adriana - II vero Islam II vero Islam","og_description":"Il Ritorno all'Islam di Adriana II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/","og_site_name":"II vero Islam","article_published_time":"2017-04-10T00:14:00+00:00","og_image":[{"width":720,"height":406,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Il Ritorno all&#8217;Islam di Adriana","datePublished":"2017-04-10T00:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/"},"wordCount":1121,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png","articleSection":["Donne si sono convertiti all'isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/","url":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/","name":"Il Ritorno all'Islam di Adriana - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png","datePublished":"2017-04-10T00:14:00+00:00","description":"Il Ritorno all'Islam di Adriana II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/04\/22.png","width":720,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-ritorno-all-islam-di-adriana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il Ritorno all&#8217;Islam di Adriana"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/183"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}