{"id":219,"date":"2017-03-11T00:14:00","date_gmt":"2017-03-11T00:14:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2017\/03\/11\/il-volo-degli-uccelli-2\/"},"modified":"2017-03-11T00:14:00","modified_gmt":"2017-03-11T00:14:00","slug":"il-volo-degli-uccelli-2","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/","title":{"rendered":"IL VOLO DEGLI UCCELLI"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-218\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png\" alt=\"\" width=\"720\" height=\"515\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png 720w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo-300x215.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">IL VOLO DEGLI UCCELLI<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Per quanto riguarda il volo degli uccelli il Corano dice: <span style=\"color: #008080;\">&#8221; Non hanno visto gli uccelli sottomessi [ad Allah] nello spazio del cielo, dove solo Allah li sostiene? In ci\u00f2 sono segni per coloro che credono.&#8221;<\/span> [ Corano 16:79 ]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Un messaggio simile \u00e8 ripetuto nel Corano nel seguente versetto: <span style=\"color: #008080;\">&#8221; Non hanno visto, sopra di loro, gli uccelli spiegare e ripiegare le ali? Non li sostiene altri che il Compassionevole. In verit\u00e0 Egli osserva ogni cosa. &#8220;<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">[ Corano 67:19 ]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La parola araba <em>amsaka <\/em>letteralmente significa, &#8216; mettere sulla sua mano, tenere, trattenere qualcuno &#8216; che esprima l&#8217;idea che Allah tiene l&#8217;uccello nella Sua forza.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> Questi versetti sollecitano la dipendenza estremamente vicina del comportamento degli uccelli su ordini Divini. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">I dati scientifici moderni hanno indicato il grado di perfezione raggiunto da determinata specie di uccelli riguardo alla programmazione dei loro movimenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">\u00c8 soltanto l&#8217;esistenza di un programma migratore nel codice genetico degli uccelli che possono spiegare il viaggio lungo e complicato che gli uccelli molto giovani, senza alcun&#8217;esperienza precedente e senza alcuna guida, possono compire. Possono inoltre rinviare al punto di partenza in una data definita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il prof. Hamburger nel suo libro &#8216;Forza e Fragilit\u00e0 &#8216;d\u00e0 l\u2019esempio &#8216; dell\u2019 uccello mutton&#8217; che vive nel Pacifico dopo il suo viaggio oltre 15.000 miglia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Fa questo viaggio durante 6 mesi e torna al punto di partenza con un massimo di una settimana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> Le istruzioni altamente complicate per un tal viaggio devono essere contenute nelle cellule nervose degli uccelli. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Definitivamente sono programmate. Non dovremmo riflettere sull&#8217;identit\u00e0 di questo &#8216;programmatore &#8216;?<\/span><\/p>\n<p style=\"margin: 0px 0px 15px; padding: 0px; border: 0px; outline: 0px; text-align: justify; color: #666666; font-family: Helvetica, Arial, FreeSans, sans-serif; line-height: 20.390625px;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; background-color: transparent; color: #ff0000;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: large; background-color: transparent; background-position: initial initial; background-repeat: initial initial;\">Traduzione di<br \/>Mamdouh AbdEl Kawi Dello Russo<\/span><\/span><\/p>\n<p style=\"margin: 0px 0px 15px; padding: 0px; border: 0px; outline: 0px; color: #666666; font-family: Helvetica, Arial, FreeSans, sans-serif; line-height: 20.390625px; text-align: justify !important;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; background-color: transparent; font-family: 'times new roman', times;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: large; background-color: transparent; background-position: initial initial; background-repeat: initial initial;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: 18px; background-color: transparent; color: #ff0000; background-position: initial initial; background-repeat: initial initial;\">la fonte:<br \/><\/span><\/span><\/span><\/p>\n<p style=\"margin: 0px 0px 15px; padding: 0px; border: 0px; outline: 0px; color: #666666; font-family: Helvetica, Arial, FreeSans, sans-serif; line-height: 20.390625px; text-align: justify !important;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; background-color: transparent; font-family: 'times new roman', times;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: large; background-color: transparent; background-position: initial initial; background-repeat: initial initial;\"><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: 18px; background-color: transparent; color: #ff0000; background-position: initial initial; background-repeat: initial initial;\">islamic-invitation<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL VOLO DEGLI UCCELLI Per quanto riguarda il volo degli uccelli il Corano dice: &#8221; Non hanno visto gli uccelli sottomessi [ad Allah] nello spazio del cielo, dove solo Allah li sostiene? In ci\u00f2 sono segni per coloro che credono.&#8221; [ Corano 16:79 ] Un messaggio simile \u00e8 ripetuto nel Corano nel seguente versetto: &#8221; &hellip;<\/p>\n","protected":false},"author":6,"featured_media":218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"IL VOLO DEGLI UCCELLI II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"IL VOLO DEGLI UCCELLI II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-11T00:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"IL VOLO DEGLI UCCELLI\",\"datePublished\":\"2017-03-11T00:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/\"},\"wordCount\":264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/03\\\/volo.png\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/\",\"name\":\"IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/03\\\/volo.png\",\"datePublished\":\"2017-03-11T00:14:00+00:00\",\"description\":\"IL VOLO DEGLI UCCELLI II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/03\\\/volo.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/03\\\/volo.png\",\"width\":720,\"height\":515},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-volo-degli-uccelli-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL VOLO DEGLI UCCELLI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam","description":"IL VOLO DEGLI UCCELLI II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/","og_locale":"it_IT","og_type":"article","og_title":"IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam","og_description":"IL VOLO DEGLI UCCELLI II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/","og_site_name":"II vero Islam","article_published_time":"2017-03-11T00:14:00+00:00","og_image":[{"width":720,"height":515,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"IL VOLO DEGLI UCCELLI","datePublished":"2017-03-11T00:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/"},"wordCount":264,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/","url":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/","name":"IL VOLO DEGLI UCCELLI - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png","datePublished":"2017-03-11T00:14:00+00:00","description":"IL VOLO DEGLI UCCELLI II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/03\/volo.png","width":720,"height":515},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-volo-degli-uccelli-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"IL VOLO DEGLI UCCELLI"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=219"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/218"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}