{"id":252,"date":"2017-05-29T00:25:00","date_gmt":"2017-05-29T00:25:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2017\/05\/29\/lislam-e-religione-e-stile-di-vita\/"},"modified":"2017-05-29T00:25:00","modified_gmt":"2017-05-29T00:25:00","slug":"lislam-e-religione-e-stile-di-vita","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/","title":{"rendered":"l\u2019Islam \u00e8 religione e stile di vita!"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-251\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png\" alt=\"\" width=\"720\" height=\"759\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png 720w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita-285x300.png 285w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">l\u2019Islam \u00e8 religione e stile di vita!<\/span> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">V.Y. (Amina V.) Ex cattolica.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> Insegnante. Dotata di una grande convinzione e di una fede stimolante, il suo percorso verso l\u201fIslam \u00e8 per vari motivi interessante. Convertita all\u201fIslam nel 1984 <\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">di quel percorso dice: \u201cHo vissuto la mia infanzia e la mia adolescenza nel Delfinato, nella Francia metropolitana, una provincia dove non avevo alcun contatto con l\u2019Islam.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Ho sempre avuto una gran sete di spiritualit\u00e0, fui una fervente praticante, che frequentava la chiesa molto regolarmente fino a 14\/15 anni. Alcuni elementi \u201cperturbatori\u201d intaccavano tuttavia, questo fervore religioso. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Facevo dei sogni strani, contrari alla morte di Ges\u00f9 in croce, per esempio (Corano 4\/157). &#8216;<span style=\"color: #008000;\">&#8216; e &nbsp;dissero:&#8221; Abbiamo ucciso il Messia Ges<\/span><span style=\"font-size: large; text-align: justify;\"><span style=\"color: #008000;\">\u00f9 figlio di Maria ,il Messaggero di Allah !. invece non l&#8217;hanno n\u00e9 ucciso, n\u00e9 crociffsso, ma cos\u00ec parve loro. Coloro che sono in discordia a questo proposito , restano nel dubbio : non hanno altra scienza e non seguono altro che la congettura. per certo non lo hanno ucciso &#8220;<\/span> <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Trovavo il vino, durante la messa, un rito malsano, visto le devastazioni a cui portava l\u2019alcolismo, come giustificare questa pratica nella mia vita religiosa? C\u2019era inoltre, il concetto della trinit\u00e0 di Dio, gli intermediari (il clero e\/o i santi), le molteplici statue, quando la Bibbia vieta ogni rappresentazione di Dio (Esodo 34\/17 \u2013 Levitico 19\/4 \u2013 26\/1ecc). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Queste diverse constatazioni, tra le altre, mi portarono alla rottura con la chiesa. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Dopo il mio diploma di maturit\u00e0, andai a Reunion presso la famiglia, per fare il mio primo anno di medicina.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> Studiai, uno dopo l\u2019altro, il Buddismo e l\u2019Induismo. Poi l\u2019Islam, ma semplicemente per confermare i pregiudizi negativi che avevo&#8230; Perch\u00e9 avevo un\u2019amica che si era convertita &#8230;.all\u2019Islam, ed io non arrivavo a capirlo, questo! Come una donna, moderna o meno, possa convertirsi a &#8230;\u201dquello\u201d?! No, l\u2019Islam, no! Ma mi sbagliavo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">E pi\u00f9 studiavo, pi\u00f9 l\u2019impressione della verit\u00e0 si rafforzava. I miei studi, per esempio, mi chiarirono l\u2019interdizione coranica della consumazione del maiale; nel corso, alla facolt\u00e0 di medicina, appresi che la carne del maiale era la pi\u00f9 nociva, e che se anche cotta, o addirittura carbonizzata, restava sempre malsana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Poi, un giorno, in assenza della mia amica, volli provare il suo tappeto per la preghiera, giusto per vedere, per curiosit\u00e0. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Fu il catalizzatore!! Immediatamente, seppi con certezza che l\u2019Islam era la Mia religione! Era il mese di giugno, nel 1984, avevo allora 18 anni! \u00c8 impossibile descrivere con le parole ci\u00f2 che provai in quel momento, le porole non potevano sopportare il peso di queste sensazioni.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> La pratica venne in seguito, parallelamente allo studio approfondito della mia religione. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Io sono, oggi, come un pesce nel suo mare. Tuttavia, ho un rimpianto, quello di non aver conosciuto prima l\u2019Islam.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"> Tutto ci\u00f2, pu\u00f2 sembrare strano, addirittura anedottico&#8230; ma non tanto. Perch\u00e9 dovete sapere, che questo non imped\u00ec in seguito, a mia cognata, poi a mio fratello, seguito dopo un p\u00f2 da mia sorella, tutti viventi in Francia, di scegliere, essi stessi, l\u2019Islam come religione e stile di vita!\u201d<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\">la fonte<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\">islamhouse<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>l\u2019Islam \u00e8 religione e stile di vita! V.Y. (Amina V.) Ex cattolica. Insegnante. Dotata di una grande convinzione e di una fede stimolante, il suo percorso verso l\u201fIslam \u00e8 per vari motivi interessante. Convertita all\u201fIslam nel 1984 &nbsp; di quel percorso dice: \u201cHo vissuto la mia infanzia e la mia adolescenza nel Delfinato, nella Francia &hellip;<\/p>\n","protected":false},"author":6,"featured_media":251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donne-si-sono-convertiti-all-isalm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-29T00:25:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"l\u2019Islam \u00e8 religione e stile di vita!\",\"datePublished\":\"2017-05-29T00:25:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/05\\\/stilevita.png\",\"articleSection\":[\"Donne si sono convertiti all'isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/\",\"name\":\"l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/05\\\/stilevita.png\",\"datePublished\":\"2017-05-29T00:25:00+00:00\",\"description\":\"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/05\\\/stilevita.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2017\\\/05\\\/stilevita.png\",\"width\":720,\"height\":759},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/lislam-e-religione-e-stile-di-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"l\u2019Islam \u00e8 religione e stile di vita!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam","description":"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/","og_locale":"it_IT","og_type":"article","og_title":"l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam","og_description":"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/","og_site_name":"II vero Islam","article_published_time":"2017-05-29T00:25:00+00:00","og_image":[{"width":720,"height":759,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"l\u2019Islam \u00e8 religione e stile di vita!","datePublished":"2017-05-29T00:25:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png","articleSection":["Donne si sono convertiti all'isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/","url":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/","name":"l\u2019Islam \u00e8 religione e stile di vita! - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png","datePublished":"2017-05-29T00:25:00+00:00","description":"l\u2019Islam \u00e8 religione e stile di vita! II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2017\/05\/stilevita.png","width":720,"height":759},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/lislam-e-religione-e-stile-di-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"l\u2019Islam \u00e8 religione e stile di vita!"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=252"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/251"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}