{"id":309,"date":"2013-05-01T13:46:39","date_gmt":"2013-05-01T13:46:39","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2013\/05\/01\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/"},"modified":"2013-05-01T13:46:39","modified_gmt":"2013-05-01T13:46:39","slug":"verona-moschea-e-centro-culturale-islamico-che-funziona-2","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/","title":{"rendered":"Verona, Moschea e centro culturale islamico che funziona"},"content":{"rendered":"<p style=\"margin: 15px 0px; padding: 0px; font-size: 13px; line-height: 19.5px; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-305\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg\" border=\"0\" width=\"269\" height=\"187\" \/><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; font-size: 13px; line-height: 19.5px; text-align: justify;\"><strong><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Primo Forum \u201c la famiglia islamica\u201d benemerito centro culturale islamico di Verona 16 dic 2012<\/span><\/span><\/strong><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Il centro culturale islamico di Verona ci insegna quale fondamentale funzione, in seno alla comunit\u00e0, debba avere le Moschea ed il suo ufficio annesso, soprattutto in un paese di minoranza islamica.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Holiday Inn hotel, il primo forum sulla famiglia islamica.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Una sala congresso perfettamente preparata, relatori emozionanti, un pubblico in grande empatia, un\u2019atmosfera accogliente, e famiglie felici, l\u2019 esatto opposto di quello che si propaganda contro il matrimonio islamico e soprattutto quello tra culture miste; questo il risultato di una piacevole educativa domenica, lo scorso 16 dicembre.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Perch\u00e9 questa Moschea merita una grande attenzione ed i nostri complimenti?<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Le due conferenze, sull\u2019importanza della misericordia e dell\u2019amore coniugale, di Umar A.F. e di P.K. Dal Monte hanno sottolineato ampiamente l\u2019importanza dell\u2019affetto tra gli sposi, quindi i vicendevoli doveri e diritti per una sana convivenza familiare, logicamente serena nell\u2019Islam con la benedizione del Creatore, contenuti conosciuti, ma espressi volutamente a sottolinearne lo scopo primario dell\u2019incontro che non era solo quello di ascoltare delle lezioni, bens\u00ec di sentirsi attivi e responsabili in un percorso di maturazione.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">(Corano XXX 21. {<span style=\"color: #003300;\">Fa parte dei Suoi segni l\u2019aver creato da voi, per voi, delle spose, affinch\u00e9 riposiate presso di loro, e ha stabilito tra voi amore e tenerezza. Ecco davvero dei segni per coloro che riflettono<\/span>}<br style=\"margin: 0px; padding: 0px;\" \/>I relatori hanno ben spiegato che nel Corano e quindi nello studio dell\u2019 islam ci sono gli strumenti per non sbagliare e vivere ogni situazione nel rispetto degli altri ed avere successo nei rapporti interpersonali.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Il momento clou del forum \u00e8 stato durante le partecipazione degli invitati, che si sono alzati uno alla volta dalla platea presentandosi e parlando del loro matrimonio, e questa \u00e8 stata la componente di successo dell\u2019evento stesso, e la risposta alla nostra domanda.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Le circa 30 famiglie musulmane che sedevano in sala, di nazionalit\u00e0 soprattutto miste, che hanno raccontato in breve la loro storia di incontro e matrimonio supportato dalla loro pratica religiosa e da un centro islamico attivo e degno di ogni buona nota, hanno testimoniato il lavoro importante di quest\u2019ultimo, del suo direttivo e del suo Imam dott. Anwar, che ha condotto la parte didattica dei lavori.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Una parola davvero significativa \u00e8 stata quella gli ospiti in platea, invitati a raccontarsi brevemente, dopo aver loro chiesto di parlare del rispettivo marito o moglie entrando nel merito dell\u2019amore per questo o quella; ed \u00e8 stato lo stesso Imam Anwar che aprendo le presentazioni ha confermato pubblicamente di essere molto innamorato della moglie che era seduta in platea, a stupire positivamente e invogliare soprattutto i fratelli.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Questa proposta psicologica ha emozionato e invitato il pubblico a sciogliersi brevemente, proprio in virt\u00f9 dell\u2019affetto verso la sposa o lo sposo, sentimento troppo stesso schiacciato da un malsano pudore o da un\u2019educazione maschilista pre-islamica.<br style=\"margin: 0px; padding: 0px;\" \/>Quindi della capacit\u00e0 e necessit\u00e0 di tali complimenti ne abbiamo parlato diffusamente dopo esserci ascoltati.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Abbiamo constatato innanzitutto moltissime conversioni di italiane sposate a stranieri musulmani, e tutte queste sorelle ringraziavano il supporto della comunit\u00e0 veronese e della Moschea come una \u201ccasa-famiglia\u201d che le ha accolte e seguite, verso l\u2019acculturazione prima di tutto, e quindi verso la definitiva scelta religiosa.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Conversioni di fede cos\u00ec numerose, anche grazie ad un clima che incoraggia e invita, ci spingono a domandarci dunque quanta importanza debba avere la \u201cda\u2019wa\u201d (invito alla conoscenza dell\u2019islam), laddove abbiamo sempre riscontrato che se \u00e8 attiva porta evidentemente a grandi risultati, come ne \u00e8 un esempio conosciuto quella nel Regno Unito.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Se la scelta definitiva \u00e8 nelle mani dell\u2019Onnipotente, l\u2019invito sano \u00e8 certamente un dovere di ogni musulmano, e il supporto dottrinale un obbligo di ogni comunit\u00e0, e da convertiti noi ricordiamo quante volte avremmo avuto bisogno di questo aiuto, ma non lo abbiamo trovato.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Soprattutto evidenziamo la necessit\u00e0 di un supporto attivo in lingua italiana alle tante conversioni di donne italiane che spesso non hanno nei loro mariti stranieri interlocutori validi per la mancanza della conoscenza linguistica.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Dopo la pausa per le preghiere e un gradito the con i pasticcini, abbiamo seguito la proiezione della lezione in italiano e arabo, dell\u2019imam Anwar e dei fratelli Mohsen e Ashraf, che hanno spiegato prima di tutto le differenze oggettive, biologiche e caratteriali dei due sessi, poi invitato la platea a riflettere su quelle comportamentali, spiegando che spesso la causa dei litigi tra coniugi \u00e8 proprio il fraintendimento degli intenti per ignoranza sulle differenze comunicative uomo\/donna che portano ad aspettarsi una risposta ben precisa, la quale \u00e8 impossibile avere perch\u00e9 non fa parte delle capacit\u00e0 del partner che \u00e8 di sesso opposto.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Gli uomini cercano risposte concrete alle domande e vengono sconcertati dai segnali femminili che non sanno decifrare; viceversa le donne si aspettano possibilmente solo di essere ascoltate e quando pongono raffiche di domande non pretendono le risposte; l\u2019uomo prende per suo dovere trovare soluzioni a tutto, ed essendo incapace di risolvere ogni quesito si agita.<br style=\"margin: 0px; padding: 0px;\" \/>La donna invece vorrebbe solo essere ascoltata e confortata, in realt\u00e0 non le importa trovare la soluzione, ma solo essere compresa nel suo scoraggiamento e possibilmente coccolata.<br style=\"margin: 0px; padding: 0px;\" \/>La moglie riversa ogni suo sconforto sul marito che entra in casa stanco dal lavoro e prende queste lamentele come sue colpe e l\u2019incapacit\u00e0 di risolverle come una sconfitta.<br style=\"margin: 0px; padding: 0px;\" \/>I coniugi parlano due lingue diverse e finiscono con il non capirsi, irritarsi e poi litigare.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">La continuazione del forum metter\u00e0 ancora in rilievo queste incapacit\u00e0 e ci aiuter\u00e0 a troverare soluzioni \u201cscientifiche\u201d che nascono dallo studio della religione islamica, per non fraintendere la comunicazione, per migliorare la comprensione dei segnali, e portare alla consapevolezza e una serena convivenza se Dio vuole.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; line-height: 19.5px; text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">La lode spetta ad Allah Signore dei mondi.<\/span><\/span><\/p>\n<p style=\"margin: 15px 0px; padding: 0px; font-size: 13px; line-height: 19.5px; text-align: justify;\"><span style=\"color: #000080;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Cinzia A.R.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primo Forum \u201c la famiglia islamica\u201d benemerito centro culturale islamico di Verona 16 dic 2012 Il centro culturale islamico di Verona ci insegna quale fondamentale funzione, in seno alla comunit\u00e0, debba avere le Moschea ed il suo ufficio annesso, soprattutto in un paese di minoranza islamica. Holiday Inn hotel, il primo forum sulla famiglia islamica. &hellip;<\/p>\n","protected":false},"author":6,"featured_media":305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Verona, Moschea e centro culturale islamico che funziona II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Verona, Moschea e centro culturale islamico che funziona II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-01T13:46:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"269\" \/>\n\t<meta property=\"og:image:height\" content=\"187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Verona, Moschea e centro culturale islamico che funziona\",\"datePublished\":\"2013-05-01T13:46:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/\"},\"wordCount\":961,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/05\\\/verona.jpg\",\"articleSection\":[\"Le Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/\",\"name\":\"Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/05\\\/verona.jpg\",\"datePublished\":\"2013-05-01T13:46:39+00:00\",\"description\":\"Verona, Moschea e centro culturale islamico che funziona II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/05\\\/verona.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/05\\\/verona.jpg\",\"width\":269,\"height\":187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verona, Moschea e centro culturale islamico che funziona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam","description":"Verona, Moschea e centro culturale islamico che funziona II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/","og_locale":"it_IT","og_type":"article","og_title":"Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam","og_description":"Verona, Moschea e centro culturale islamico che funziona II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/","og_site_name":"II vero Islam","article_published_time":"2013-05-01T13:46:39+00:00","og_image":[{"width":269,"height":187,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Verona, Moschea e centro culturale islamico che funziona","datePublished":"2013-05-01T13:46:39+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/"},"wordCount":961,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg","articleSection":["Le Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/","url":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/","name":"Verona, Moschea e centro culturale islamico che funziona - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg","datePublished":"2013-05-01T13:46:39+00:00","description":"Verona, Moschea e centro culturale islamico che funziona II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/05\/verona.jpg","width":269,"height":187},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/verona-moschea-e-centro-culturale-islamico-che-funziona-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Verona, Moschea e centro culturale islamico che funziona"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=309"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/305"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}