{"id":441,"date":"2022-07-30T12:06:00","date_gmt":"2022-07-30T12:06:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2022\/07\/30\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/"},"modified":"2022-07-30T12:06:00","modified_gmt":"2022-07-30T12:06:00","slug":"l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/","title":{"rendered":"L&#8217;Islam vieta la carne di maiale perch\u00e9 causa delle malattie"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-440\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg\" alt=\"\" border=\"0\" width=\"425\" height=\"283\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg 425w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">Le malattie causate dalla carne di maiale <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il maiale \u00e8 impuro cos\u00ec pure la sua carne\u00a0 \u00a0nel corano ci sono tanti versi che ne parlano per esempio :\u00a0<span style=\"color: #339966;\">\u00ab In verit\u00e0, vi sono state vietate le bestie morte, il sangue, la carne di porco\u00bb<\/span> [Corano 2\u00a0:173].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #339966;\">\u00abDi&#8217;: \u201cIn quello che mi \u00e8 stato rivelato, non trovo altri interdetti a proposito del cibo, se non l&#8217;animale morto, il sangue effuso e la carne di porco &#8211; che \u00e8 immonda\u00bb<\/span> [Corano 6:<\/span><span style=\"font-size: large; line-height: 1.3em;\">145].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Nel libro \u201cThe Westminster dictionary of the bible\u201d alla voce (pork\/porco) c\u2019\u00e8 scritto:<br \/> \u201cIl maiale \u00e8 una bestia immonda, non disdegna di nutrirsi di rifiuti e carogne e si suppone che il consumo della sua carne provochi malattie della pelle\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">L\u2019elenco dei germi nel maiale, che provocano malattie \u00e8 molto lungo, ed alcuni germi, o parassiti sono addirittura mortali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Nella carne di maiale si trova un protozoo ciliato (organismo vivente unicellulare microscopico), il verme solitario del maiale, e la trichina (un verme parassita che produce la trichinosi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Questa malattia si trasmette per ingestione di carne cruda, o poco cotta di maiale) contenente larve incestate, le quali, dopo l&#8217;uscita dalle loro crisalidi, si insediano nelle pareti dell\u2019intestino tenue.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Poi si trova il verme parassita, tutti conosciuti come agenti patogeni di gravi malattie che il maiale ha in comune con l\u2019uomo. Il protozoo ciliato pu\u00f2 causare una dissenteria incurabile che porta alla morte dell\u2019uomo. Fino ad oggi non hanno trovato una cura.<br \/> Anche la carne ovina e la carne di bue, sono sede di microrganismi (germi patogeni) che provocano malattie, e anche i legumi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La carne di maiale tuttavia contiene il maggior numero di germi con il pi\u00f9 alto potenziale di patogeni.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Spesso \u00e8 si \u00e8 detto che i maiali ai giorni nostri sono allevati con condizioni igieniche, e la carne non fa male come un tempo, ed \u00e8 un alimento sano e nutriente.<br \/> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Tutte le citazioni si riferiscono ai maiali allevati in quelle condizioni igieniche e portano i germi, sono scoperte fatte nel passato recente quando i maiali erano allevati secondo metodi scientifici moderni. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Tutte le fattorie oggi usano igiene ma il risultato \u00e8 sempre lo stesso. Ed anche se in futuro troveranno un modo per annullare gli effetti patogeni dei germi ecc., ci\u00f2 non toglier\u00e0 alla carne di maiale la caratteristica di portatore di malattie anche mortali.<\/p>\n<p> Il Washington post, nel suo numero del 31 Maggio 1952 ha pubblicato un articolo del Dott. Glen Shepered e dice:<br \/> \u201cNegli USA e nel Canada una persona su sei ha dei vermi (trichina) nei propri muscoli per aver ingerito carne di maiale infetta da trichina. Molte persone, pur essendo contaminate, non presentano alcun sintomo e la maggior parte di coloro che ne<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">presentano guarisce lentamente. In alcuni l\u2019infezione produce la morte. Altri sono ridotti ad invalidi permanenti. Tutti consumatori di carne di maiale\u201d.<\/p>\n<p> La trichinosi, la malattia provocata dalla trichina, scoppia come un\u2019epidemia. Neanche con i metodi scientifici moderni i batteri possono essere distrutti.<\/p>\n<p> Il verme solitario infesta l\u2019intestino dell\u2019uomo, provocando vomito, nausea, alternanza di stipsi e diarrea, disturbi nervosi e dimagrimento.<\/p>\n<p> Il verme rotondo \u00e8 un parassita lungo diversi centimetri e causa gravi danni.<\/p>\n<p> Il verme ad uncino entra nella pelle attraverso le ferite o perforandola. I maiali mangiano gli escrementi umani contenenti le uova di questi parassiti, che si sviluppano nel loro corpo e si moltiplicano. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Tutto questo causa impotenza, mestruazioni irregolari, debolezza fisica, apatia ecc.<br \/> Faciolopsis buski I suoi parassiti infestano anche l\u2019uomo.<br \/> Paragonimus vive nei polmoni del maiale pu\u00f2 causare nell\u2019uomo polmonite.<br \/> Cloronorchis siniensis negli uomini causa gravi malattie del fegato e del petto.<br \/> Erisipela diminuisce l\u2019attivit\u00e0 e l\u2019appetito, portando poi alla morte, questo batterio pu\u00f2 sopravvivere a lungo nel prosciutto. Emottisi endemica Sangue dai polmoni.<br \/> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Insomma il maiale \u00e8 sempre stato portatore di malattie gravi e mortali:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><br \/> La dissenteria, La Trichinosi, Il verme solitario, Il verme rotondo, Il verme ad uncino, L\u2019itterizia, La polmonite, Il soffocamento, Il dimagrimento, L\u2019occlusione (chiusura) intestinale,Le pancreatiti acute, L\u2019ingrossamento del fegato, La diarrea, La formazione di calcoli epatici, Il cancro, L\u2019anemia , Forti febbri, L\u2019arresto della crescita dei bambini, La febbre tifoidea, Disfunzioni cardiache,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il porco, per di pi\u00f9, ha le reni mal funzionanti. Vale a dire a differenza di noi esseri umani o degli animali in genere, il suo sistema di filtraggio \u00e8 per costituzione fisica, in un certo qual senso, malato; o, per dirla con pi\u00f9 esattezza, \u00e8 poco operativo: <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">noi riusciamo a depurare il nostro corpo di circa il 94 % dell\u2019acido urico mediante i nostri reni e attraverso l\u2019urina; cos\u00ec anche tutti gli animali comuni. Il porco, invece, non riesce a espellerne tranne il 4-5 % circa. E il rimanente?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Gli rimane naturalmente nel fisico; non bisogna, insomma, stupirsi del suo veloce ingrassarsi: \u00e8 gran parte di quello che doveva finire nelle sue urine!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">L\u2019acido urico (come le altre sostanze contenute nell\u2019urina), si sa bene, \u00e8 un pericoloso veleno, veicolo di non poche malattie.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">pubblicato da\u00a0: Ahmed abdallah Hassan<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" alt=\"\" border=\"0\" width=\"150\" height=\"115\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">www.r-islam.com<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le malattie causate dalla carne di maiale Il maiale \u00e8 impuro cos\u00ec pure la sua carne\u00a0 \u00a0nel corano ci sono tanti versi che ne parlano per esempio :\u00a0\u00ab In verit\u00e0, vi sono state vietate le bestie morte, il sangue, la carne di porco\u00bb [Corano 2\u00a0:173]. \u00abDi&#8217;: \u201cIn quello che mi \u00e8 stato rivelato, non trovo &hellip;<\/p>\n","protected":false},"author":6,"featured_media":440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"L&#039;Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"L&#039;Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-30T12:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"L&#8217;Islam vieta la carne di maiale perch\u00e9 causa delle malattie\",\"datePublished\":\"2022-07-30T12:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/\"},\"wordCount\":831,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/07\\\/666.jpg\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/\",\"name\":\"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/07\\\/666.jpg\",\"datePublished\":\"2022-07-30T12:06:00+00:00\",\"description\":\"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/07\\\/666.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/07\\\/666.jpg\",\"width\":425,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Islam vieta la carne di maiale perch\u00e9 causa delle malattie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam","description":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/","og_locale":"it_IT","og_type":"article","og_title":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam","og_description":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/","og_site_name":"II vero Islam","article_published_time":"2022-07-30T12:06:00+00:00","og_image":[{"width":425,"height":283,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"L&#8217;Islam vieta la carne di maiale perch\u00e9 causa delle malattie","datePublished":"2022-07-30T12:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/"},"wordCount":831,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/","url":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/","name":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg","datePublished":"2022-07-30T12:06:00+00:00","description":"L'Islam vieta la carne di maiale perch\u00e9 causa delle malattie II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/07\/666.jpg","width":425,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/l-islam-vieta-la-carne-di-maiale-perche-causa-delle-malattie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Islam vieta la carne di maiale perch\u00e9 causa delle malattie"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/440"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}