{"id":485,"date":"2020-04-26T11:50:00","date_gmt":"2020-04-26T11:50:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2020\/04\/26\/l-universo-in-espansione\/"},"modified":"2020-04-26T11:50:00","modified_gmt":"2020-04-26T11:50:00","slug":"l-universo-in-espansione","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/","title":{"rendered":"L&#8217;UNIVERSO IN ESPANSIONE"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-484\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png 500w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione-300x300.png 300w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">L&#8217;UNIVERSO IN ESPANSIONE<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Nel 1925, un astronomo americano di nome Edwin Hubble, osserv\u00f2 l\u2019evidenza,\u00a0 cio\u00e8 che tutte le galassie stanno retrocedendo l&#8217;un l&#8217;altra, quale implica che l&#8217;universo si stia espandendo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">L&#8217;espansione dell&#8217;universo ora \u00e8 un fatto scientifico stabilito. Questo \u00e8 quanto dice il Corano per quanto riguarda lanatura dell&#8217;universo: <span style=\"color: #008000;\">&#8220;Il cielo lo abbiamo costruito con la Nostra potenza e costantemente lo estendiamo nell\u2019immensit\u00e0.&#8221;<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">[ Corano 51:47 ]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La parola araba <span style=\"color: #008000;\">m\u00fbsi&#8217;\u00fbn<\/span> \u00e8 tradotta correttamente<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">come&#8217;espandendolo &#8216;e si riferisce alla creazione dell\u2019espansione pi\u00f9 vasta dell&#8217;universo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Stephen Hawking, nel suo libro, &#8216;Breve storia del tempo &#8216;,dice\u00a0: &#8220;la scoperta che l&#8217;universo si sta espandendo fu una delle pi\u00f9 grandi rivoluzioni intellettuali del ventesimo secolo.&#8221;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">La velocit\u00e0 di espansione<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Sembra che l&#8217;universo si stia espandendo. Secondo una delle teorie, avvenne una\u00a0gigantesca esplosione. La materia, che ora sta formando l&#8217;universo, miliardi di anni fa era unita in un&#8217;unica massa cosmica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Secondo tale teoria, le galassie formatesi dal materiale esploso, continueranno a viaggiare, allontanandosi sempre pi\u00f9 le une dalle altre, a grande velocit\u00e0. La velocit\u00e0 di espansione dell&#8217;universo \u00e8 definita dalla\u00a0costante di Hubble.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Questo numero indica la velocit\u00e0 alla quale una galassia, ad una determinata distanza, si allontana da noi. Ma sapendo la velocit\u00e0 di espansione, possiamo calcolare anche il passato, per sapere quanto tempo fa l&#8217;universo ha cominciato ad espandersi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il valore della costante di Hubble fa risalire l&#8217;et\u00e0 dell&#8217;universo a poco meno di 20 miliardi di anni fa, poco pi\u00f9 della pi\u00f9 vecchia stella individuata.<br \/> La scoperta di Hubble, Humason, e Slipher \u00e8 interessante e sorprendente. Secondo la loro scoperta, pi\u00f9 lontane sono le galassie, maggiore \u00e8 il cambiamento di\u00a0lunghezza d&#8217;onda\u00a0delle\u00a0linee spettrali\u00a0rispetto alle galassie pi\u00f9 vicine.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La spiegazione pi\u00f9 comune di questo cambiamento, \u00e8 il movimento. In questo caso, l&#8217;allontanamento delle galassie dalla\u00a0Terra. Tale movimento provoca &#8220;l&#8217;effetto Doppler&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Questo significa che pi\u00f9 lontano \u00e8 la galassia, e pi\u00f9 rossa \u00e8 la sua luce. Pi\u00f9 rossa la sua luce, maggiore il cambiamento di lunghezza d&#8217;onda delle righe spettrali; e maggiore \u00e8 tale cambiamento, maggiore \u00e8 la velocit\u00e0 di fuga .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><br \/> Pertanto le galassie pi\u00f9 distanti si allontanano da noi alla maggiore velocit\u00e0. Tutte le galassie si allontanano e la loro velocit\u00e0 \u00e8 direttamente proporzionale alla loro distanza. Come si spiega questo? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La spiegazione pi\u00f9 semplice \u00e8 che l&#8217;universo si sta espandendo, sta diventando pi\u00f9 grande; e si sta espandendo uniformemente e senza cambiare forma.<br \/> Ogni galassia si allontana da tutte le altre; e osservando una galassia, ad esempio della Via Lattea, che \u00e8 la nostra galassia, ci sembra che tutto si stia allontanando da noi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><br \/> E non c&#8217;\u00e8 motivo di dire che per tutto il resto dell&#8217;universo non sia come per noi; per tutto il resto dell&#8217;universo l&#8217;immagine \u00e8 uguale.Nell&#8217;universo tutto si allontana da tutto il resto. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">E basta fare un piccolo salto per arrivare all&#8217;assunto che questa espansione \u00e8 cominciata dopo un breve momento, avvenuto miliardi di anni fa, quando l&#8217;intero universo era molto piccolo e pi\u00f9 condensato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il Corano ha accennato l&#8217;espansione dell&#8217;universo, persino prima che l\u2019uomo imparasse a costruire un telescopio!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Alcuni diranno che la presenza dei fatti astronomici nel Corano non sono una sorpresa poich\u00e9 gli arabi erano piuttosto avanti nel campo dell\u2019astronomia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Sono giusti nel riconoscere l\u2019avanzamento degli arabi nel campo dell\u2019astronomia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Tuttavia non riescono a rendersi conto che il Corano \u00e8 stato rivelato secoli prima che gli arabi si specializzassero nell&#8217;astronomia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Inoltre molti dei fatti scientifici sopra accennati che riguardano l\u2019astronomia, come l&#8217;origine dell&#8217;universo con una grande esplosione (Big Bang), non erano noti agli arabi neppure coloro che erano al massimo dell\u2019avanzamento scientifico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">I fatti scientifici accennati nel Corano non sono quindi dovuti all\u2019avanzamento degli arabi nell&#8217;astronomia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Piuttosto, \u00e8 vero il contrario. Gli arabi erano avanzati nell&#8217;astronomia, perch\u00e9 l&#8217;astronomia occupa un posto nel Corano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">La fonte : <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" border=\"0\" width=\"150\" height=\"115\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">www.r-islam.com<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;UNIVERSO IN ESPANSIONE Nel 1925, un astronomo americano di nome Edwin Hubble, osserv\u00f2 l\u2019evidenza,\u00a0 cio\u00e8 che tutte le galassie stanno retrocedendo l&#8217;un l&#8217;altra, quale implica che l&#8217;universo si stia espandendo. L&#8217;espansione dell&#8217;universo ora \u00e8 un fatto scientifico stabilito. Questo \u00e8 quanto dice il Corano per quanto riguarda lanatura dell&#8217;universo: &#8220;Il cielo lo abbiamo costruito con &hellip;<\/p>\n","protected":false},"author":6,"featured_media":484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"L&#039;UNIVERSO IN ESPANSIONE II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"L&#039;UNIVERSO IN ESPANSIONE II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-26T11:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"L&#8217;UNIVERSO IN ESPANSIONE\",\"datePublished\":\"2020-04-26T11:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/\"},\"wordCount\":620,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/04\\\/11espansione.png\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/\",\"name\":\"L'UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/04\\\/11espansione.png\",\"datePublished\":\"2020-04-26T11:50:00+00:00\",\"description\":\"L'UNIVERSO IN ESPANSIONE II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/04\\\/11espansione.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/04\\\/11espansione.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-universo-in-espansione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;UNIVERSO IN ESPANSIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam","description":"L'UNIVERSO IN ESPANSIONE II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/","og_locale":"it_IT","og_type":"article","og_title":"L'UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam","og_description":"L'UNIVERSO IN ESPANSIONE II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/","og_site_name":"II vero Islam","article_published_time":"2020-04-26T11:50:00+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"L&#8217;UNIVERSO IN ESPANSIONE","datePublished":"2020-04-26T11:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/"},"wordCount":620,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/","url":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/","name":"L'UNIVERSO IN ESPANSIONE - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png","datePublished":"2020-04-26T11:50:00+00:00","description":"L'UNIVERSO IN ESPANSIONE II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/l-universo-in-espansione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2020\/04\/11espansione.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/l-universo-in-espansione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;UNIVERSO IN ESPANSIONE"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=485"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/484"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}