{"id":497,"date":"2024-04-18T09:01:00","date_gmt":"2024-04-18T09:01:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2023\/08\/01\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/"},"modified":"2024-06-04T09:18:13","modified_gmt":"2024-06-04T09:18:13","slug":"danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/","title":{"rendered":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-496\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png\" alt=\"\" width=\"450\" height=\"450\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png 450w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art-300x300.png 300w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art-150x150.png 150w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\"><span style=\"color: #0000ff\">Danny Williams,<\/span><\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\"><span style=\"color: #0000ff\">gigante britannico del ring<\/span><\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\"><span style=\"color: #0000ff\">\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">Nato nel 1973 in Brixton a Londra , a seidici anni si \u00e8 convertito all\u2019Islam , la sua fama come pugile famoso non gli ha fatto dimenticare di cercare la via per Allah.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">Come pugile ha vinto pi\u00f9 di 31 partita per K.O.\u00a0 ha vinto\u00a0 il campionato mondiale\u00a0\u00a0 del pesi massimi nel 2004 quando ha battuto\u00a0 Mike Tyson ed ha vinto il campionato delCommonwealth nel 2005.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">. Era in Turchia,in vacanza: di quell viaggio\u00a0 dice : \u00abl\u2019albergo dove abito era di fronte a una moschea ,ho Sentito l&#8217;Adhan, la chaimata alla preghiera recitata dal Muezzin, ed \u00e8 stato come una rivelazione.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">Ero cattolico, allora. Ma avendo guardato la gente fare la preghiera , ho capito quale era la strada giusta per la mia esistenza, l&#8217;Adhan \u00e8 la cosa pi\u00f9 bella che abbia mai sentito .<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">prima del mio viaggio in Turchia ho passato degli anni studiando l\u2019islam cercando la verit\u00e0 , specialmente dopo aver fatto una chiamata con <em>Sheikh Ahmed Deedat<\/em>.,<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">E dopo aver letto un suo libro , ho scoperto tanti errori nella Bibbia e questi errori mi hanno portato a studiare l\u2019islam ed a scoprire la vera religione .<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">I miei giorni in Turchia erno bellissimi ed appena ero tornato a Londra , mi sono convertito all\u2019Islam\u00a0 nel 1999 \u00bb.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">\u00ab\u00a0sentire l&#8217;Adhan in turchia \u00e8 stata la patre finale che ha copmiuto un lungo periodo di studio l\u2019islam \u00bb<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">\u00ab\u00a0 alla mia famiglia non \u00e8 piaciuta la mia conversione all\u2019Islam , poich\u00e9 erano cristiani , e si sono sentiti imbarazzati da questo fatto. Sebbene sapesse del moi studio dell\u2019Islam.\u00a0\u00bb<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">\u00ab\u00a0La mia vita \u00e8 cambiata completamente dopo la mia conversione all\u2019islam , in meglio certo, uno di questi cambiamenti \u00e8 che la mia vita ora \u00e8 controllata da Allah e dedicata ad Allah , faccio la preghiera cinque volte al giorno specialmente\u00a0 Salat Al Fajr\u00a0 -la preghiera dell\u2019alba-sono diventato pi\u00f9 generoso\u00a0 poich\u00e9 la mia religione mi ordina di dare agli altri e di essere generoso\u00bb .<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">\u00ab\u00a0ho lasciato\u00a0 la barba crescere perch\u00e9 \u00e8 Sunna ed il nostro profeta (pace e benedizione su di lui)ci ha ordinato di lasciare la barba crescere \u00bb<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">il ptofeta Mohammad (pace sia su di lui ) dice :\u00a0<span style=\"color: #008000\">&#8221; curate con attenzione i baffi e lasciate\u00a0 la barba crescere influente &#8220;<\/span> Muslim.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\">Tony Williams ha rifiutato di togliere via la barba per participare alla partita del campionato del pesi massimi, ed ha insistito di partecipare alla partita senza togliere via la barba, il che per lui era una vittoria pi\u00f9 grande di vincere il campionato stesso.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\"><span style=\"color: #ff0000\">Traduzione di\u00a0:Ahmed Abdallh Hassan<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" alt=\"\" border=\"0\" width=\"150\" height=\"115\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: large\"><span style=\"color: #ff0000\">www.r-isalm.com<\/span><\/span><\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danny Williams, gigante britannico del ring \u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d Nato nel 1973 in Brixton a Londra , a seidici anni si \u00e8 convertito all\u2019Islam , la sua fama come pugile famoso non gli ha fatto dimenticare di cercare la via per Allah. Come pugile ha vinto &hellip;<\/p>\n","protected":false},"author":6,"featured_media":496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storie-dei-famosi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T09:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T09:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d\",\"datePublished\":\"2024-04-18T09:01:00+00:00\",\"dateModified\":\"2024-06-04T09:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/art.png\",\"articleSection\":[\"Storie dei famosi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/\",\"name\":\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/art.png\",\"datePublished\":\"2024-04-18T09:01:00+00:00\",\"dateModified\":\"2024-06-04T09:18:13+00:00\",\"description\":\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/art.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/art.png\",\"width\":450,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam","description":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/","og_locale":"it_IT","og_type":"article","og_title":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam","og_description":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %","og_url":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/","og_site_name":"II vero Islam","article_published_time":"2024-04-18T09:01:00+00:00","article_modified_time":"2024-06-04T09:18:13+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d","datePublished":"2024-04-18T09:01:00+00:00","dateModified":"2024-06-04T09:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png","articleSection":["Storie dei famosi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/","url":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/","name":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png","datePublished":"2024-04-18T09:01:00+00:00","dateModified":"2024-06-04T09:18:13+00:00","description":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d II vero Islam Storie dei famosi %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/08\/art.png","width":450,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/danny-williamsla-mia-vita-ora-e-controllata-da-allah-e-dedicata-ad-allah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Danny Williams,\u201cla mia vita ora \u00e8 controllata da Allah e dedicata ad Allah\u201d"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":1,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"predecessor-version":[{"id":1880,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/497\/revisions\/1880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/496"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}