{"id":503,"date":"2013-07-13T11:24:09","date_gmt":"2013-07-13T11:24:09","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2013\/07\/13\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/"},"modified":"2013-07-13T11:24:09","modified_gmt":"2013-07-13T11:24:09","slug":"una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/","title":{"rendered":"Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-502\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg\" border=\"0\" width=\"630\" height=\"420\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg 630w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">La famiglia norvegese composta di 5 persone ha annunciato la sua conversione all\u2019Islam dopo aver ascoltato Il Corano da una moschea limitrofo al posto\u00a0 dove abita nella Provincia\u00a0di Mu\u011fla In Turchia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il padre \u00a0\u201cFrod Sigfartsen\u201d ha detto : sono venuto inTurchia per turismo per qualche giorno ed ho preferito venire in questa zone bellissima nella Provincia\u00a0di Mu\u011fla e mi ha toccato il cuore la voce del <em>Muazen<\/em><em> <\/em><em>quando recitava sinceramente dei versetti del Corano.<\/em><em><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><em>Ed ha aggiunto il padre che lui e la<\/em><em> <\/em><em>sua famiglia sono stati notevolmente influenzati dalla voce del Muazen , perci\u00f2 sono<\/em><em> andati tutti nella moschea ed hanno chiesto all\u2019Imam\u00a0 della Moschea di spiegargli i principi dell\u2019Islam poi hanno espresso , pienamente convinti, il loro desiderio di convertirsi all&#8217;Islam. <\/em><em><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><em>Il padre ha cambiato il nome , ha scelto il nome &#8220;Ali &#8220;, sua moglie ha scelto\u00a0&#8220;ayesha&#8221;,<\/em><em> mentre per i tre figli hanno scelto &#8220;Ayhan&#8221; &#8220;Asmaa&#8221; &#8220;Aleif<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><em><span style=\"color: #ff0000;\">traduzione di :Ahmed abdallah Hassan<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" border=\"0\" width=\"150\" height=\"115\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><em><span style=\"color: #ff0000;\">www.r-islam.com<\/span><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia La famiglia norvegese composta di 5 persone ha annunciato la sua conversione all\u2019Islam dopo aver ascoltato Il Corano da una moschea limitrofo al posto\u00a0 dove abita nella Provincia\u00a0di Mu\u011fla In Turchia. Il padre \u00a0\u201cFrod Sigfartsen\u201d ha detto : sono venuto inTurchia &hellip;<\/p>\n","protected":false},"author":6,"featured_media":502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una famiglia norvegese si \u00e8 convertita all&#039;Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Una famiglia norvegese si \u00e8 convertita all&#039;Islam nel primo giorno di Ramadan in Turchia II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una famiglia norvegese si \u00e8 convertita all&#039;Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Una famiglia norvegese si \u00e8 convertita all&#039;Islam nel primo giorno di Ramadan in Turchia II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-13T11:24:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia\",\"datePublished\":\"2013-07-13T11:24:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/07\\\/notizia.jpg\",\"articleSection\":[\"Le Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/\",\"name\":\"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/07\\\/notizia.jpg\",\"datePublished\":\"2013-07-13T11:24:09+00:00\",\"description\":\"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/07\\\/notizia.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2013\\\/07\\\/notizia.jpg\",\"width\":630,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam","description":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/","og_locale":"it_IT","og_type":"article","og_title":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam","og_description":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/","og_site_name":"II vero Islam","article_published_time":"2013-07-13T11:24:09+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia","datePublished":"2013-07-13T11:24:09+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg","articleSection":["Le Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/","url":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/","name":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg","datePublished":"2013-07-13T11:24:09+00:00","description":"Una famiglia norvegese si \u00e8 convertita all'Islam nel primo giorno di Ramadan in Turchia II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2013\/07\/notizia.jpg","width":630,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/una-famiglia-norvegese-si-e-convertita-all-islam-nel-primo-giorno-di-ramadan-in-turchia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Una famiglia norvegese si \u00e8 convertita all&#8217;Islam nel primo giorno di Ramadan in Turchia"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=503"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/502"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}