{"id":507,"date":"2018-04-16T02:01:00","date_gmt":"2018-04-16T02:01:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2018\/04\/16\/il-latte-cura-per-ogni-malattia\/"},"modified":"2018-04-16T02:01:00","modified_gmt":"2018-04-16T02:01:00","slug":"il-latte-cura-per-ogni-malattia","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/","title":{"rendered":"Il latte, cura per ogni malattia"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-506\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png 500w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte-300x300.png 300w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\">Il latte, cura per ogni malattia<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><br \/> Si tratta delle innumerovoli proprieta\u2019 del latte crudo (non pastorizzato), si tratta di un\u2019intervista con Mark McAfee, il proprietario di Organic Pastures Dairy in California.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">C\u2019e\u2019 molto da imparare riguardo nutrizione, immunita\u2019 ecc\u00a0<br \/> Sapevate che ci sono molti hadith nella Sunnah che illustrano le proprieta\u2019 curative del latte puro e fresco? <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Il Profeta (pace e benedizioni su di lui) ha eplicitamente affermato che il latte ed il burro chiarificato (samn), altrimenti noto come ghee, rappresentano entrambi una cura (shifa) e un trattamento (dawaa) per le malattie.<br \/> La Medicina profetica e il Latte crudo, naturale e puro: un resoconto storico, religioso e scientifico sul latte di mucca vero, non trattato, come cura e rimedio per la salute.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Con una breve discussione sugli elementi composizionali, biochimici, nutrizionali e immunologici del latte, le circostanze sociali vigenti dietro la pastorizzazione nel 20esimo secolo da parte delle nazioni industrializzate e la superiorita\u2019 del latte vero, naturale rispetto a quello conservato e trattato.<\/p>\n<p> Da Abdullah bin-Mas\u2019ud che narro\u2019 che il Messaggero di Dio (pace e benedizioni su di lui) disse: <span style=\"color: #008000;\">\u201cIn verita\u2019 Dio l\u2019Onnipotente, non manda una malattia senza la sua cura, eccetto la morte. Dunque il latte di mucca e\u2019 buono per voi, perche\u2019 la mucca rumina su pascoli diversificati\u201d<\/span> (Tramandato da al-Hakim e dichiarato Sahih da Imam al-Albani in Sahih al-Jaami\u2019 as-Saghir (numero 1810))<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">l\u2019imam al-Albani (rahimahullah) verifico\u2019, commenta questo hadith. Ecco che se ne citano alcuni passi, elencati alla lettera \u201dayn\u201d:<br \/> \u201c\u2026.sul significato di: che si raccolgie in \u2018pascoli diversificati\u2019, significa da cio\u2019 che e\u2019 caldo, secco e umido (nella sua natura) e dunque il suo latte raggiunge un equilibrio (nella sua composizione), e quando ne mangia (di tutti i tipi di erbe) allora ne raccoglie in se\u2019 tutti i benefici .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">E questo cibo e\u2019 da Allah, non e\u2019 fine a se stesso, perche\u2019 se fosse fine a se stesso sceglierebbe un unico alimento preferito<br \/> Ed inoltre:<br \/> \u201c sul significato: che non tralascia albero, ne\u2019 arbusto, ne\u2019 erba tranne cio\u2019 che la tiene attaccata al suolo (mangiandone da li\u2019 ) per questo il suo latte e\u2019 composto di una miscela di energizzanti (elementi nutritivi) estratti dai varii arbusti e piante diversificate, e\u2019 come se si trattasse di una bibita (i cui elementi, ingredienti) siano stati messi tutti insieme e cotti (nello stomaco della mucca) e esso (cioe\u2019 il latte) e\u2019 una cura per ogni malattia\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><br \/><span style=\"color: #0000ff;\"> Altre note generali<\/span><br \/> Ecco alcune note di una certa rilevanza:<br \/> -Il vostro intestino costituisce l\u201980% del sistema immunitario. Ci sono piu\u2019 batteri nel vostro intestino che cellule nell\u2019intero organismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Questi batteri giocano un ruolo integrale e sono fondamentali per il sistema immunitario. Quest\u2019ultimo rappresenta il vostro ecosistema interno.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Lo stato in cui si trova il vostro \u201cecosistema\u201d ha una forte influenza sulla salute e sulle malattie.\u00a0<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">&#8211; Il cibo e\u2019 medicina e la medicina e\u2019 cibo. Cibi integrali naturali ed alcune attenzioni nella nostra dieta , insieme a supplementi appropriati e pertinenti, giocano un ruolo fondamentale nella prevenzione e nel respingere malanni e malattie senza le controindicazioni nocive di medicinali piuttosto forti.<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">&#8211; Le malattie croniche di oggigiorno sono spesso correlate ad una cattiva dieta, alla malnutrizione e ad uno stile di vita non corretto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Non doniamo ai nostri corpi i giusti nutrienti, in qualita\u2019 e quantita\u2019, dunque i nostri corpi falliscono. Non c\u2019e\u2019 alcun mistero in cio\u2019. E\u2019 semplice e chiaro! Non ci nutriamo piu\u2019 di cibi completi e ricchi in nutrienti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Abbiamo cibi raffinati, conservati e sterilizzati in cui la maggior parte degli ingredienti sono compromessi per sempre, se non completamente inesistenti.<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">&#8211; nel \u2018900 , il latte crudo\/non trattato e certificato era utilizzato per la nutrizione infantile mentre il latte di qualita\u2019 inferiore era destinato alla pastorizzazione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">L\u2019introduzione negli anni \u201820 (1920) del latte in polvere per bambini, porto\u2019 ad un inevitabile declino della domanda di latte crudo certificato che avanzo\u2019 con le decadi a venire.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\">Cio\u2019 viene aggiunto per citare un\u2019altra motivazione storico \/di mercato oltre a quella ben nota della Seconda Guerra Mondiale, che porto\u2019 un declino nella domanda di latte crudo.<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">La fonte:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">io-musulmana-italiana.blogspot.com<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il latte, cura per ogni malattia Si tratta delle innumerovoli proprieta\u2019 del latte crudo (non pastorizzato), si tratta di un\u2019intervista con Mark McAfee, il proprietario di Organic Pastures Dairy in California. C\u2019e\u2019 molto da imparare riguardo nutrizione, immunita\u2019 ecc\u00a0 Sapevate che ci sono molti hadith nella Sunnah che illustrano le proprieta\u2019 curative del latte puro &hellip;<\/p>\n","protected":false},"author":6,"featured_media":506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nella-sunna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il latte, cura per ogni malattia - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Il latte, cura per ogni malattia II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il latte, cura per ogni malattia - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Il latte, cura per ogni malattia II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-16T02:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Il latte, cura per ogni malattia\",\"datePublished\":\"2018-04-16T02:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/\"},\"wordCount\":689,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/04\\\/acrudolatte.png\",\"articleSection\":[\"I miracoli nella Sunna\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/\",\"name\":\"Il latte, cura per ogni malattia - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/04\\\/acrudolatte.png\",\"datePublished\":\"2018-04-16T02:01:00+00:00\",\"description\":\"Il latte, cura per ogni malattia II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/04\\\/acrudolatte.png\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2018\\\/04\\\/acrudolatte.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-latte-cura-per-ogni-malattia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il latte, cura per ogni malattia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il latte, cura per ogni malattia - II vero Islam II vero Islam","description":"Il latte, cura per ogni malattia II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/","og_locale":"it_IT","og_type":"article","og_title":"Il latte, cura per ogni malattia - II vero Islam II vero Islam","og_description":"Il latte, cura per ogni malattia II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/","og_site_name":"II vero Islam","article_published_time":"2018-04-16T02:01:00+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Il latte, cura per ogni malattia","datePublished":"2018-04-16T02:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/"},"wordCount":689,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png","articleSection":["I miracoli nella Sunna"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/","url":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/","name":"Il latte, cura per ogni malattia - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png","datePublished":"2018-04-16T02:01:00+00:00","description":"Il latte, cura per ogni malattia II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/acrudolatte.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-latte-cura-per-ogni-malattia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il latte, cura per ogni malattia"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=507"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/506"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}