{"id":66,"date":"2016-08-19T13:14:00","date_gmt":"2016-08-19T13:14:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2016\/08\/19\/la-figura-sferica-della-terra\/"},"modified":"2016-08-19T13:14:00","modified_gmt":"2016-08-19T13:14:00","slug":"la-figura-sferica-della-terra","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/","title":{"rendered":"LA FIGURA SFERICA DELLA TERRA"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-65\" style=\"border: 0px;\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg\" alt=\"\" border=\"0\" width=\"425\" height=\"284\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg 425w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-weight: bold; color: #0000ff; font-size: large; font-family: 'times new roman', times; line-height: 1.3em;\">LA FIGURA SFERICA DELLA TERRA<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\"> <\/span><br \/>Nei primi tempi, la gente credeva che la terra fosse piana. Per i secoli, gli uomini avevano paura di avventurarsi in cose assai distanti, affinch\u00e8 non sarebbero caduti nella trappola. Il signor Francis Drake era la prima persona che&nbsp; ha dimostrato che la terra \u00e8 sferica quando ha navigato intorno essa nel 1597. Prendiamo in considerazione il seguente versetto Coranico per quanto riguarda l&#8217;alternazione del giorno e della notte: <span style=\"color: #008000;\">&#8220;<\/span><\/span><\/span><\/p>\n<p style=\"direction: ltr; unicode-bidi: embed;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times; color: #339966;\">&#8220;Non hai visto come Allah ha fatto s\u00ec che la notte compenetri il giorno e il giorno compenetri la notte?<\/span><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #008000;\">&#8220;<\/span> [ Corano 31:29 ]<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/>La fusione qui significa che la notte lentamente e gradualmente cambia al giorno e viceversa. Questo fenomeno pu\u00f2 avvenire soltanto se la terra \u00e8 sferica. Se la terra fosse piana, ci sarebbe stato un cambiamento improvviso dalla notte al giorno e dal giorno alla notte.<\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> <br \/>Il seguente versetto inoltre allude alla figura sferica della terra: <span style=\"color: #008000;\">&#8221; Ha creato i cieli e la terra in tutta verit\u00e0. Arrotola la notte sul giorno e il giorno sulla notte.&#8221; <\/span><br \/>[ Corano 39:5 ] <\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/>La parola araba usata qui \u00e8 Kawwara che significa &#8216;da coincidere &#8216;o &#8216;da arrotolarsi &#8216;- il senso di un turbante intorno alla testa. La sovrapposizione o arrotolarsi del giorno e della notte pu\u00f2 avvenire soltanto se la terra \u00e8 sferica. <\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/>La terra non \u00e8 esattamente tonda come una sfera, ma geo-sferica cio\u00e8 \u00e8 appiattita ai pali. Il seguente versetto contiene una descrizione della figura della terra: <br \/><span style=\"color: #008000;\">&#8220;Dopo di ci\u00f2 ha esteso la terra.&#8221; <\/span>[ Corano 79:30 ] [la parola araba dahaha \u00e8 tradotta da A. Yusuf Ali come &#8220;distesa ampia&#8221;, che inoltre \u00e8 corretta. La parola dahaha inoltre significa un uovo di struzzo. ] <\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/>Uovo in arabo qui \u00e8 dahaha, che significa un uovo di struzzo. La figura di un uovo di struzzo assomiglia alla figura geo-sferica della terra. Cos\u00ec il Corano descrive correttamente la figura della terra, comunque la nozione prevalente quando il Corano \u00e8 stato rivelato era che la terra \u00e8 piana.<\/span><\/span><\/p>\n<p><span style=\"color: #ff0000;\">Traduzione di<\/span><br \/><span style=\"color: #ff0000;\">Mamdouh AbdEl Kawi Dello Russo<\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">la fonte<br \/><\/span><\/span><\/span><\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><span style=\"color: #ff0000;\">islamic-invitation<\/span><br \/><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA FIGURA SFERICA DELLA TERRA Nei primi tempi, la gente credeva che la terra fosse piana. Per i secoli, gli uomini avevano paura di avventurarsi in cose assai distanti, affinch\u00e8 non sarebbero caduti nella trappola. Il signor Francis Drake era la prima persona che&nbsp; ha dimostrato che la terra \u00e8 sferica quando ha navigato intorno &hellip;<\/p>\n","protected":false},"author":6,"featured_media":65,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-66","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"LA FIGURA SFERICA DELLA TERRA II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"LA FIGURA SFERICA DELLA TERRA II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-19T13:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"LA FIGURA SFERICA DELLA TERRA\",\"datePublished\":\"2016-08-19T13:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/\"},\"wordCount\":325,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/08\\\/14.jpg\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/\",\"name\":\"LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/08\\\/14.jpg\",\"datePublished\":\"2016-08-19T13:14:00+00:00\",\"description\":\"LA FIGURA SFERICA DELLA TERRA II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/08\\\/14.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/08\\\/14.jpg\",\"width\":425,\"height\":284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-figura-sferica-della-terra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA FIGURA SFERICA DELLA TERRA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam","description":"LA FIGURA SFERICA DELLA TERRA II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/","og_locale":"it_IT","og_type":"article","og_title":"LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam","og_description":"LA FIGURA SFERICA DELLA TERRA II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/","og_site_name":"II vero Islam","article_published_time":"2016-08-19T13:14:00+00:00","og_image":[{"width":425,"height":284,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"LA FIGURA SFERICA DELLA TERRA","datePublished":"2016-08-19T13:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/"},"wordCount":325,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/","url":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/","name":"LA FIGURA SFERICA DELLA TERRA - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg","datePublished":"2016-08-19T13:14:00+00:00","description":"LA FIGURA SFERICA DELLA TERRA II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2016\/08\/14.jpg","width":425,"height":284},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/la-figura-sferica-della-terra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"LA FIGURA SFERICA DELLA TERRA"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/66\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/65"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=66"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=66"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}