{"id":726,"date":"2014-02-04T10:50:26","date_gmt":"2014-02-04T10:50:26","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2014\/02\/04\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/"},"modified":"2014-02-04T10:50:26","modified_gmt":"2014-02-04T10:50:26","slug":"slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/","title":{"rendered":"Slovenia : i musulmani sloveni avranno la loro prima moschea"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-725\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg\" border=\"0\" width=\"550\" height=\"360\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg 550w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000-300x196.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Slovenia\u00a0: i musulmani sloveni avranno la loro prima moschea<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">il primo ministro sloveno&#8221; Alenka Bratu\u0161ek &#8221; ha annunciato l&#8217;inizio della costruzione della prima moschea il prossimo novembre, in risposta al desiderio dei musulmani da pi\u00f9 di quattro decenni.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Durante l&#8217;annuncio, Bratu\u0161ek ha detto: &#8220;E &#8216;una vittoria simbolica su tutte le forme di estremismo religioso&#8221;,. La moschea sar\u00e0 inaugurato nel 2016, e sar\u00e0 costruito nella capitale Lubiana, avr\u00e0 anche un centro culturale, una biblioteca e aule.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">E cos\u00ec viene realizzato il sogno di pi\u00f9 di 47mila musulmani il quale ha durato pi\u00f9 di\u00a0 quattro decenni.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Traduzione\u00a0: Ahmed Abdullah<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> www.r-islam.com<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" border=\"0\" width=\"150\" height=\"115\" \/><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">La fonte\u00a0: http:\/\/www.alukah.net\/world_muslims\/0\/65994\/<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Slovenia\u00a0: i musulmani sloveni avranno la loro prima moschea il primo ministro sloveno&#8221; Alenka Bratu\u0161ek &#8221; ha annunciato l&#8217;inizio della costruzione della prima moschea il prossimo novembre, in risposta al desiderio dei musulmani da pi\u00f9 di quattro decenni. Durante l&#8217;annuncio, Bratu\u0161ek ha detto: &#8220;E &#8216;una vittoria simbolica su tutte le forme di estremismo religioso&#8221;,. La &hellip;<\/p>\n","protected":false},"author":6,"featured_media":725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-04T10:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"Slovenia : i musulmani sloveni avranno la loro prima moschea\",\"datePublished\":\"2014-02-04T10:50:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/\"},\"wordCount\":117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/02\\\/lupida000.jpg\",\"articleSection\":[\"Le Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/\",\"name\":\"Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/02\\\/lupida000.jpg\",\"datePublished\":\"2014-02-04T10:50:26+00:00\",\"description\":\"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/02\\\/lupida000.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/02\\\/lupida000.jpg\",\"width\":550,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slovenia : i musulmani sloveni avranno la loro prima moschea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam","description":"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/","og_locale":"it_IT","og_type":"article","og_title":"Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam","og_description":"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/","og_site_name":"II vero Islam","article_published_time":"2014-02-04T10:50:26+00:00","og_image":[{"width":550,"height":360,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"Slovenia : i musulmani sloveni avranno la loro prima moschea","datePublished":"2014-02-04T10:50:26+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/"},"wordCount":117,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg","articleSection":["Le Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/","url":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/","name":"Slovenia : i musulmani sloveni avranno la loro prima moschea - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg","datePublished":"2014-02-04T10:50:26+00:00","description":"Slovenia : i musulmani sloveni avranno la loro prima moschea II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/02\/lupida000.jpg","width":550,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/slovenia-i-musulmani-sloveni-avranno-la-loro-prima-moschea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Slovenia : i musulmani sloveni avranno la loro prima moschea"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/725"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}