{"id":758,"date":"2014-03-01T08:43:11","date_gmt":"2014-03-01T08:43:11","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2014\/03\/01\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/"},"modified":"2014-03-01T08:43:11","modified_gmt":"2014-03-01T08:43:11","slug":"il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/","title":{"rendered":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-757\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo%20di%20ad%202.jpg\" border=\"0\" width=\"398\" height=\"206\" \/><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d<\/span><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> Gli Ad abitassero zone desertiche ma nel Corano Allah afferma che Egli aveva provisto <\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">il popolo di Ad con giardini e sorgenti d\u2019acqua<\/span><span style=\"color: #339966;\"> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #339966;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">\u201ce temete Colui che vi ha provvisto di ci\u00f2 che ben sapete: vi ha provvisto di bestiame e di progenie, di giardini e fonti.\u201d<\/span><\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">[Corano 26 :132-133-134]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Le Prove archeologiche mostrano che la regione dell\u2019Arabia meridionale aveva un sistema di irrigazione altamente sviluppato usato per l\u2019agricoltura nel passato.<\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">Dio ci informa che questo popolo discendese dal Profeta Nuh (No\u00e8, su di lui la pace) e che fossero alti e possenti.<\/span><span style=\"color: #339966;\"> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #339966;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">\u201cRicordatevi di quando vi design\u00f2 successori del popolo di No\u00e8 e accrebbe la vostra prestanza nel mondo. Ricordate i benefici di Allah, affinch\u00e9 possiate prosperare\u201d<\/span><\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\"> [Corano7:69]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> Dio dice:<span style=\"color: #339966;\"> \u201c senza eguali tra le contrade,\u201d<\/span> [Corano89:8],<span style=\"line-height: 1.3em;\">alludendo al fatto che nessuno ai loro tempi era alto, forte e potente quanto loro. <\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">Erano violenti e tiranni:<\/span><span style=\"color: #339966;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> \u201cE quando colpirete lo farete come tirani?\u201d<\/span><\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\"> [corano 26:130].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Avevano sconfitto altri popoli nell\u2019area: <span style=\"color: #339966;\">\u201cGli \u0091\u00c2d furono ingiustamente superbi sulla terra <\/span><\/span><\/span><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><span style=\"color: #339966;\">e dissero: \u201cChi \u00e8 pi\u00f9 forte di noi?\u201d<\/span><span style=\"line-height: 1.3em;\"> [<\/span><\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">Corano 41:15]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> <br \/> <span style=\"color: #0000ff;\"><strong>Comparate gli Ad ai ricchi e potenti di oggigiorno.<\/strong> <br \/><\/span> Gli Ad ebbero terra fertile e abbondanza di cibo e ricchezza, come le superpotenze attuali. Gli Ad costruirono edifici molto alti, usati soltanto per sfoggio, piuttosto che per necessit\u00e0.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Comparate questo con i palazzi, i grattacieli e i monumenti di oggi. Osservatene delle figure. La prosperosa citt\u00e0 di Dubai non \u00e8 lontanta dalla regione degli Ad, l\u2019architettura di uno dei suoi hotel \u00e8 stata designata puro vanto.\u00a0Gli Ad erano arroganti e credettero che nulla potesse eguagliare la loro potenza.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Comparate questo con l\u2019oppressione alla quale purtroppo si assiste nel mondo oggi, e come alcune nazioni credendo di essere le pi\u00f9 potenti, abbiano da sempre sfruttato i poveri e i deboli, senza alcuno riguardo per le leggi di Dio.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Come ci si pu\u00f2 differenziare dal popolo degli Ad? Scegliendo di obbedire a Dio.Ritornando alla loro storia, gli Ad soffrirono ad un certo punto di una grande siccit\u00e0.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Eppure ancora invitavano la punizione. <span style=\"color: #339966;\">\u201cSe sei sincero, mostraci quello di cui ci minacci.\u201d<\/span>[Corano 7:70].<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Quando videro la punizione arrivare, cio\u00e8 dei nuvoloni immensi nel cielo, pensarono si trattasse soltanto di pioggia.<span style=\"color: #339966;\"> \u201cScatenammo contro di loro un vento tempestoso, durante un giorno nefasto e interminabile; strappava gli uomini come fossero tronchi di palme sradicate.\u201d<\/span> [Corano 54:19-20].<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> Il vento paragonato ad un urlo orribile che sgorga dal cielo dur\u00f2 per ben sette giorni e sette notti, distrusse tutto lasciando salvi soltanto i credenti, e le rovine degli edifici come prova e testimonianza <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><span style=\"color: #339966;\">\u201cmentre gli \u00c2d furono distrutti da un vento mugghiante, furioso,che Allah scaten\u00f2 contro di loro per sette notti e otto giorni consecutivi. Allora avresti visto quella gente riversa in terra come tronchi cavi di palma.<\/span><span style=\"line-height: 1.3em; color: #339966;\">Ne vedi forse uno sopravvissuto?.\u201d<\/span><span style=\"line-height: 1.3em;\">[Corano 69:6-8]<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000; line-height: 1.3em;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">la fonte : www.r-islam.com<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000; line-height: 1.3em;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-151\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/09\/115.png\" border=\"0\" width=\"150\" height=\"115\" \/><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d Gli Ad abitassero zone desertiche ma nel Corano Allah afferma che Egli aveva provisto il popolo di Ad con giardini e sorgenti d\u2019acqua \u201ce temete Colui che vi ha provvisto di ci\u00f2 che ben sapete: vi ha provvisto di bestiame e di progenie, di &hellip;<\/p>\n","protected":false},"author":6,"featured_media":757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-01T08:43:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo%20di%20ad%202.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d\",\"datePublished\":\"2014-03-01T08:43:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/03\\\/popolo di ad 2.jpg\",\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/\",\"name\":\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/03\\\/popolo di ad 2.jpg\",\"datePublished\":\"2014-03-01T08:43:11+00:00\",\"description\":\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/03\\\/popolo di ad 2.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/03\\\/popolo di ad 2.jpg\",\"width\":398,\"height\":206},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam","description":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/","og_locale":"it_IT","og_type":"article","og_title":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam","og_description":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/","og_site_name":"II vero Islam","article_published_time":"2014-03-01T08:43:11+00:00","og_image":[{"width":398,"height":206,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo di ad 2.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d","datePublished":"2014-03-01T08:43:11+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo di ad 2.jpg","articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/","url":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/","name":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo di ad 2.jpg","datePublished":"2014-03-01T08:43:11+00:00","description":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo di ad 2.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2014\/03\/popolo di ad 2.jpg","width":398,"height":206},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-popolo-di-ad-tra-il-corano-e-larcheologia-parte-seconda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"il popolo di Ad tra il Corano e l\u2019archeologia\u201d parte seconda\u201d"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=758"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/757"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}