{"id":785,"date":"2014-04-05T08:39:07","date_gmt":"2014-04-05T08:39:07","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2014\/04\/05\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/"},"modified":"2014-04-05T08:39:07","modified_gmt":"2014-04-05T08:39:07","slug":"il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/","title":{"rendered":"il fenomeno del surriscaldamento globale  il problema e la soluzione nel Corano&#8221; parte seconda &#8220;"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><img decoding=\"async\" src=\"images\/stories\/Christ\/  .jpg\" border=\"0\" \/><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><strong>il fenomeno del surriscaldamento globale<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><strong>il problema e la soluzione nel Corano&#8221; parte seconda e ultima &#8220;<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Dunque i quattro risultati raggiunti dagli scienziati vertono \u00a0sull\u2019inquinamento ambientale,riguardante tutta la terra: mare, terra ferma, e aria.<\/p>\n<p> Questo surriscaldamento \u00e8 provocato anche da ci\u00f2 che l\u2019uomo ha commesso, perch\u00e9 \u00e8 lui il vero responsabile di questo fenomeno. E questo pericoloso aumento dell\u2019ossido di carbonio preannuncia la distruzione della nostra terra. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">E che vi \u00e8 la possibilit\u00e0 di poter tornare in dietro, e cio\u00e8 che vi \u00e8 un rimedio a questo danno, altrimenti le tempeste, gli uragani e anche le piogge acide e altri fenomeni continueranno a ripetersi e a lacerare la vita sulla terra.<\/p>\n<p> Probabilmente ci sorprendiamo quando scopriamo che questi risultati raggiunti dagli scienziati solo nel congresso del 2007 a cui parteciparono pi\u00f9 di 500 studiosi e specialisti in diversi settori, sono specificati nel Sacro Corano in un solo versetto.<br \/> Ammirate con me questo meraviglioso versetto, dice L\u2019Altissimo:<\/p>\n<p> 1- <span style=\"color: #008000;\">\u201cla corruzione \u00e8 apparsa sulla terra e nel mare\u201d<\/span>: allude al surriscaldamento globale, qui il Corano usa il termine \u201ccorruzione\u201d in arabo (fas\u0101d) e vuol dire rovina\/distruzione, perch\u00e9 in effetti il surriscaldamento ha rovinato il terreno, le piante, l\u2019uomo e gli animali, nel mare e nella terra ferma.<\/p>\n<p> 2- <span style=\"color: #008000;\">\u201c a causa di ci\u00f2 che hanno commesso le mani degli uomini\u201d<\/span>: sottolinea la responsabilit\u00e0 dell\u2019uomo di questa rovina.<\/p>\n<p> 3- <span style=\"color: #008000;\">\u201c affinch\u00e9 Allah faccia gustare parte di quello che hanno fatto\u201d<\/span>: allude ad un tipo di castigo affinch\u00e9 gli uomini ritornino al loro Creatore cos\u00ec li libera da questo castigo.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"> Cos\u00ec quando si prosciugano le acque e diminuiscono le scorte idriche a causa dell\u2019inquinamento e quando aumentano le catastrofi naturali come gli uragani ad esempio, e quando i venti si inquinano provocano le piogge acide ricche di gas sulfureo, non adatto n\u00e9 all\u2019irrigazione e non pu\u00f2 essere potabile, tutto ci\u00f2 \u00e8 un tipo di castigo che Allah L\u2019Altissimo ha riservato a tutti gli uomini in quanto responsabili della distruzione dell\u2019intera umanit\u00e0 e del suo habitat.\u00a0<\/p>\n<p> 4- <span style=\"color: #008000;\">\u201c forse ritorneranno [sui loro passi]?\u201d<\/span>: Allah L\u2019Altissimo annuncia la possibilit\u00e0 che l\u2019atmosfera terrestre possa ritornare alla sua naturale origine e che vi \u00e8 la possibilit\u00e0 di purificarla e restituirle il suo equilibrio naturale. Ed \u00e8 questo che gli studiosi invitano a fare oggi.<\/p>\n<p> Leggiamo bene il versetto intero<\/p>\n<p> Dice L\u2019Altissimo: <span style=\"color: #008000;\">\u201cla corruzione \u00e8 apparsa sulla terra e nel mare a causa di ci\u00f2 che hanno commesso le mani degli uomini affinch\u00e9 Allah faccia gustare parte di quello che hanno fatto forse ritorneranno [sui loro passi]?\u201d<\/span> [Corano30: 41] .<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Qui l\u2019uomo si domanda perch\u00e9 Allah L\u2019Altissimo si rivolge a noi usando il passato? perch\u00e9 ha detto <span style=\"color: #008000;\">\u201c\u00e8 apparsa\u201d<\/span> invece di dire \u201capparir\u00e0\u201d? <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">perch\u00e9 Allah L\u2019Altissimo dice sempre la verit\u00e0, e quando Il Signore dei mondi dice \u201c\u00e8 apparsa\u201d vuol dire che \u00e8 inevitabile che quel giorno arriver\u00e0 dove la terra si manifester\u00e0 nelle sue lacune e i suoi problemi d\u2019inquinamento, ed \u00e8 ci\u00f2 che oggi gli studiosi ci allarmano a proposito del surriscaldamento globale.<\/p>\n<p> Indi Allah L\u2019Altissimo ci ha dato un avvertimento attraverso questi versetti. Perch\u00e9? <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Per far s\u00ec che noi abbiamo cura della nostra terra, perch\u00e9 Allah L\u2019Altissimo vuole il bene per noi, e vuole che la nostra felicit\u00e0 in questa vita e nell\u2019aldil\u00e0. perci\u00f2 quando gli studiosi hanno rivolto l\u2019appello alla necessit\u00e0 di correggere e migliorare ci\u00f2 che \u00e8 distrutto nell\u2019ambiente, Allah L\u2019Altissimo li aveva gi\u00e0 preceduti. Cosa disse?<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><br \/> Dice L\u2019Altissimo: <span style=\"color: #008000;\">\u201cnon spargete la corruzione sulla terra, dopo che \u00e8 stata resa prospera. InvocateLo con timore e desiderio. La misericordia di Allah \u00e8 vicina a quelli che fanno il bene\u201d<\/span> [Corano7: 56] perch\u00e9 quando l\u2019uomo si rivolge sempre ad Allah L\u2019Altissimo e alla Sua misericordia trova quest\u2019ultima vicina ad esso.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">La fonte : islamlaverareligione.orgfree.com<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&#8221; parte seconda e ultima &#8220; Dunque i quattro risultati raggiunti dagli scienziati vertono \u00a0sull\u2019inquinamento ambientale,riguardante tutta la terra: mare, terra ferma, e aria. Questo surriscaldamento \u00e8 provocato anche da ci\u00f2 che l\u2019uomo ha commesso, perch\u00e9 \u00e8 lui il vero responsabile di questo fenomeno. &hellip;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-785","post","type-post","status-publish","format-standard","hentry","category-i-miracoli-nel-corano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&quot; parte seconda &quot; - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&quot; parte seconda &quot; II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&quot; parte seconda &quot; - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&quot; parte seconda &quot; II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-05T08:39:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/02\/1diffusione.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&#8221; parte seconda &#8220;\",\"datePublished\":\"2014-04-05T08:39:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/\"},\"wordCount\":639,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"articleSection\":[\"I miracoli nel Corano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/\",\"name\":\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\\\" parte seconda \\\" - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"datePublished\":\"2014-04-05T08:39:07+00:00\",\"description\":\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\\\" parte seconda \\\" II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&#8221; parte seconda &#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" - II vero Islam II vero Islam","description":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/","og_locale":"it_IT","og_type":"article","og_title":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" - II vero Islam II vero Islam","og_description":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/","og_site_name":"II vero Islam","article_published_time":"2014-04-05T08:39:07+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2023\/02\/1diffusione.png","type":"image\/png"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&#8221; parte seconda &#8220;","datePublished":"2014-04-05T08:39:07+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/"},"wordCount":639,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"articleSection":["I miracoli nel Corano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/","url":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/","name":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"datePublished":"2014-04-05T08:39:07+00:00","description":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano\" parte seconda \" II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/il-fenomeno-del-surriscaldamento-globale-il-problema-e-la-soluzione-nel-corano-parte-seconda-e-ult\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"il fenomeno del surriscaldamento globale il problema e la soluzione nel Corano&#8221; parte seconda &#8220;"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}