{"id":812,"date":"2017-07-15T00:03:00","date_gmt":"2017-07-15T00:03:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2017\/07\/15\/l-importanza-del-tawhid\/"},"modified":"2017-07-15T00:03:00","modified_gmt":"2017-07-15T00:03:00","slug":"l-importanza-del-tawhid","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/","title":{"rendered":"L&#8217;importanza del Tawhid"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<div style=\"margin: 5px 0px 20px 10px; padding: 0px; min-height: 100px; overflow: hidden; color: #141414; font-size: 13.333333969116211px; line-height: 18.488887786865234px; text-align: justify;\">\n<blockquote style=\"margin: 0px; padding: 0px; line-height: 1.4;\"><\/blockquote>\n<blockquote style=\"margin: 0px; padding: 0px; line-height: 1.4; text-align: center;\"><p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"320\" src=\"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png\" style=\" height:240px;  width:320px; \" width=\"240\" \/><\/p><\/blockquote>\n<blockquote style=\"margin: 0px; padding: 0px; line-height: 1.4; text-align: center;\"><\/blockquote>\n<blockquote style=\"margin: 0px; padding: 0px; line-height: 1.4; text-align: center;\"><\/blockquote>\n<blockquote style=\"margin: 0px; padding: 0px; line-height: 1.4;\"><p><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">1) In verit&agrave;, Allah ha creato il mondo e tutto ci&ograve; che &egrave; in esso per venerare Lui solo. Egli ha mandato il Messaggero per invitare la gente al<em>Tawhid<\/em> ed il Nobile Corano si interessa dell&rsquo;<em>Aqidah<\/em> del&nbsp;<em>Tawhid<\/em> nella maggior parte dei suoi capitoli, e spiega il male dello&nbsp;<em>Shirk<\/em> per l&rsquo;individuo e per la societ&agrave;. Lo&nbsp;<em>Shirk<\/em> &egrave; la ragione della distruzione in questa vita e la ragione della distruzione eterna nel Fuoco dell&rsquo;Aldil&agrave;.<\/p>\n<p> 2) In verit&agrave;, tutti Messaggeri iniziarono la loro chiamata con il&nbsp;<em>Tawhid<\/em>, comandati da Allah a condividerlo con la gente. Egli, l&rsquo;Altissimo, disse:<\/p>\n<p> <span style=\"color: red;\"><span style=\"color: black;\"><strong><span style=\"color: #8b0000;\">&quot;Non inviammo prima di te nessun messaggero senza rivelargli: &#39;Non c&#39;&egrave; altro dio che Me. AdorateMi!&#39; &quot;<\/span><\/strong>. Corano [21 :25]<\/span><\/span><\/p>\n<p> Il Messaggero di Allah rimase a Mecca per tredici anni invitando la gente al&nbsp;<em>Tawhid<\/em> di Allah e invit&ograve; soltanto a Lui non associandoGli nulla. Fu riguardo questo problema che Allah rivel&ograve; il seguente verso al Suo Nobile Messaggero:<\/p>\n<p> <span style=\"color: black;\"><span style=\"color: #8b0000;\"><strong>&quot;D&igrave;: <\/strong><\/span><\/span><span style=\"color: black;\"><span style=\"color: #8b0000;\"><strong>Non invoco altri che il mio Signore e non Gli associo alcunch&eacute;&quot;. Corano&quot;<\/strong><\/span> [72 :20]<\/span><\/p>\n<p> Il Nobile Messaggero allev&ograve; i suoi seguaci sul&nbsp;<em>Tawhid<\/em> dall&rsquo;infanzia e disse al figlio di suo zio, suo cugino &#39;Abdullah ibn &#39;Abbas:&nbsp;<strong>&quot;<\/strong><span style=\"color: #006400;\"><strong>Quando chiedi, chiedi ad Allah, quando cerchi aiuto, cercalo in Allah.&quot;<\/strong> <span style=\"color: black;\">[Hasan Sahih, Tirmidhi]<\/span><\/span><\/p>\n<p> Questo&nbsp;<em>Tawhid<\/em> &egrave; in realt&agrave; la religione dell&rsquo;<em>Islam<\/em>, che &egrave; costruita su di esso, ed una qualsiasi cosa diversa da esso, che non sia&nbsp;<em>Tawhid<\/em>, non &egrave; accettata da Allah.<\/p>\n<p> 3) In verit&agrave;, il Messaggero insegn&ograve; ai suoi Compagni di iniziare a chiamare le persone all&#39;Islam con il&nbsp;<em>Tawhid<\/em>, cos&igrave; disse a Mu&rsquo;adh ibn Jabal, quando lo mand&ograve; in Yemen:<\/p>\n<p> <span style=\"color: black;\"><span style=\"color: #8b0000;\"><strong>&quot;Lascia che la prima cosa alla quale li chiamerai sia la testimonianza che nessuno ha il diritto di essere lodato eccetto Allah&quot;<\/strong><\/span>Ed in un&rsquo;altra narrazione: <\/span><span style=\"color: black;\"><strong><span style=\"color: #8b0000;\">&quot; &hellip;che lodino solo Allah.&quot;<\/span><\/strong> [Bukhari e Muslim]<\/span><\/p>\n<p> 4) Il&nbsp;<em>Tawhid<\/em> &egrave; incorporato nella testimonianza che &quot;Nessuno ha il diritto di essere lodato eccetto Allah, e Muhammad &egrave; il Messaggero di Allah&quot;. Il suo significato &egrave; che non c&rsquo;&egrave; nessuno degno di essere lodato eccetto Allah, e non vi &egrave; adorazione ad eccezione di ci&ograve; col quale venne il Messaggero di Allah. Questa &egrave; la testimonianza che permette ad un non-credente di entrare nell&rsquo;Islam, dato che &egrave; la chiave per il Paradiso, e colui che lo testimonia e ci crede entra in Paradiso a meno che non lo invalidi commettendo&nbsp;<em>Shirk<\/em> o con una parola di miscredenza.<\/p>\n<p> 4) I Quraish non credenti offrirono al Messaggero di Allah la possibilit&agrave; di diventare re, ricchezza e mogli ed in cambio chiesero l&rsquo;abbandono della chiamata al&nbsp;<em>Tawhid<\/em>, e l&#39;abbandono dell&#39;attacco agli idoli. Tuttavia, egli non desiderava tutto ci&ograve;, continu&ograve; cos&igrave; la sua chiamata e sopport&ograve; l&rsquo;attacco con i suoi Compagni, fino a che la chiamata al&nbsp;<em>Tawhid <\/em>fu vittoriosa dopo tredici anni, dopo i quali Mecca fu conquistata e gli idoli distrutti. Il Messaggero di Allah recit&ograve;:<\/p>\n<p> <span style=\"color: black;\"><span style=\"color: #8b0000;\"><strong>&quot;E&#39; giunta la verit&agrave;, la falsit&agrave; &egrave; svanita &quot;. Invero la falsit&agrave; &egrave; destinata a svanire.&quot;<\/strong><\/span> Corano [17:81]<\/span><\/p>\n<p> 5) Il&nbsp;<em>Tawhid<\/em> &egrave; la preoccupazione di un Musulmano durante la sua vita, inizia la sua vita con il&nbsp;<em>Tawhid<\/em> e finisce la sua vita con il&nbsp;<em>Tawhid<\/em>. Il suo dovere nella vita &egrave; di stabilire il&nbsp;<em>Tawhid<\/em> e di chiamare ad esso, dato che il&nbsp;<em>Tawhid <\/em>unisce i credenti sotto un&#39;unica dichiarazione:<\/p>\n<p> Quindi chiediamo ad Allah di rendere la dichiarazione di&nbsp;<em>Tawhid <\/em>(La ilaha ila Allah) tra le nostre ultime parole e Gli chiediamo di unire i Musulmani sulla dichiarazione di&nbsp;<em>Tawhid<\/em>.<\/span><\/span><\/p><\/blockquote>\n<blockquote style=\"margin: 0px; padding: 0px; font-size: 11pt; font-family: Georgia, 'Times New Roman', Times, serif; line-height: 1.4;\"><p><a href=\"http:\/\/www.turntoislam.com\/forum\/forumdisplay.php?f=101\" rel=\"nofollow noopener\" style=\"color: #5e854d; padding: 0px 3px; margin: 0px -3px; border-top-left-radius: 5px; border-top-right-radius: 5px; border-bottom-right-radius: 5px; border-bottom-left-radius: 5px;\" target=\"_blank\"><strong><span style=\"font-family: Georgia;\"><span style=\"font-size: 12px;\"><span style=\"color: green;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">tratto da: TurnToIslam<\/span><\/span><\/span><\/span><\/span><\/strong><\/a><\/p><\/blockquote><\/div>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>1) In verit&agrave;, Allah ha creato il mondo e tutto ci&ograve; che &egrave; in esso per venerare Lui solo. Egli ha mandato il Messaggero per invitare la gente alTawhid ed il Nobile Corano si interessa dell&rsquo;Aqidah del&nbsp;Tawhid nella maggior parte dei suoi capitoli, e spiega il male dello&nbsp;Shirk per l&rsquo;individuo e per la societ&agrave;. Lo&nbsp;Shirk &hellip;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-812","post","type-post","status-publish","format-standard","hentry","category-la-verita-dell-isalm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;importanza del Tawhid - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"L&#039;importanza del Tawhid II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;importanza del Tawhid - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"L&#039;importanza del Tawhid II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-15T00:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"L&#8217;importanza del Tawhid\",\"datePublished\":\"2017-07-15T00:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.r-islam.com\\\/it\\\/media\\\/com_acymailing\\\/upload\\\/ssito.png\",\"articleSection\":[\"La verit\u00e0 dell'Isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/\",\"name\":\"L'importanza del Tawhid - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.r-islam.com\\\/it\\\/media\\\/com_acymailing\\\/upload\\\/ssito.png\",\"datePublished\":\"2017-07-15T00:03:00+00:00\",\"description\":\"L'importanza del Tawhid II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.r-islam.com\\\/it\\\/media\\\/com_acymailing\\\/upload\\\/ssito.png\",\"contentUrl\":\"http:\\\/\\\/www.r-islam.com\\\/it\\\/media\\\/com_acymailing\\\/upload\\\/ssito.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/l-importanza-del-tawhid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;importanza del Tawhid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'importanza del Tawhid - II vero Islam II vero Islam","description":"L'importanza del Tawhid II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/","og_locale":"it_IT","og_type":"article","og_title":"L'importanza del Tawhid - II vero Islam II vero Islam","og_description":"L'importanza del Tawhid II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/","og_site_name":"II vero Islam","article_published_time":"2017-07-15T00:03:00+00:00","og_image":[{"url":"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png","type":"","width":"","height":""}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"L&#8217;importanza del Tawhid","datePublished":"2017-07-15T00:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#primaryimage"},"thumbnailUrl":"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png","articleSection":["La verit\u00e0 dell'Isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/","url":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/","name":"L'importanza del Tawhid - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#primaryimage"},"thumbnailUrl":"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png","datePublished":"2017-07-15T00:03:00+00:00","description":"L'importanza del Tawhid II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#primaryimage","url":"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png","contentUrl":"http:\/\/www.r-islam.com\/it\/media\/com_acymailing\/upload\/ssito.png"},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/l-importanza-del-tawhid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;importanza del Tawhid"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=812"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/812\/revisions"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}