{"id":818,"date":"2022-11-04T06:22:00","date_gmt":"2022-11-04T06:22:00","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2022\/11\/04\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/"},"modified":"2022-11-04T06:22:00","modified_gmt":"2022-11-04T06:22:00","slug":"leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/","title":{"rendered":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-817\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo%20il%20corano.jpg\" alt=\"\" border=\"0\" width=\"428\" height=\"296\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Aysha Barbara \u0650Alterio&#8221;2&#8243;<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Certo, non potevo\u00a0 decidere di \u201critornare\u201d all\u2019Islam solo sulle basi di queste cose, poich\u00e9 questo, nel mio caso,\u00a0 ne aveva solo segnato un \u201cpunto a favore\u201d, e non era sufficiente per farmi affermare che io ero una musulmana.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Sono quindi passata allo studio della storia della religione cristiana, dalla morte di Cristo fino all\u2019et\u00e0 moderna,\u00a0 e a quello della storia del popolo ebraico, da Mos\u00e8 ai giorni nostri,\u00a0 sia sui testi storici\u00a0 che sui Testi Sacri integrando con ricerche personali, ho letto testi sulla vita del Profeta Muhammad (sas), fatto ricerche nel contesto politico-sociale delle trib\u00f9 arabe dal politeismo in poi.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">E ancora Torah, Vangeli, al Qur\u2019an e bibbia.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Ad un certo punto sentivo che nei principi fondamentali e nelle Sacre Scritture non vi erano, come gi\u00e0 detto, differenze sostanziali; Elohim, Dio e Allah \u00e8 sempre l\u2019UNICO stesso DIO.<\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">Ma mi accorgevo\u00a0 che leggendo il Corano qualcosa nel mio cuore era diverso, una sensazione ed una emozione che sentivo portarmi verso l\u2019Islam, inspiegabile a parole\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Certo, riconoscendo il Corano come Libro di Dio, allora il \u201critorno\u201d all\u2019Islam era compiuto, verrebbe da dire, ma per quello che mi riguardava, ero in uno stato di confusione incredibile, anche per una sorta di \u201cabitudine affettiva\u201d nei confronti del cristianesimo: la religione dei miei genitori, della mia famiglia, dei miei figli, amici e parenti. E se mi fossi sbagliata?<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Non mi restava che affidarmi a Dio, chiedere a Lui di illuminare il mio cammino, di inviarmi un segno tangibile su ci\u00f2 che avrei dovuto fare.\u00a0 Sono stati due anni di continue preghiere, invocazioni, avevo bisogno di essere guidata.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Allahu Akbar. Dio \u00e8 grande e Misericordioso.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Sempre di pi\u00f9 sentivo che l\u2019Islam era la mia strada, ma mi mancava il coraggio, forse, di fare il passo definitivo, e non ero poi cos\u00ec sicura di avere ben interpretato i segni che Dio mi aveva inviato.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Durante l\u2019ultimo Ramadan, (come quello passato), ho osservato il digiuno,\u00a0 ma questa volta pi\u00f9 che mai le mie preghiere insistevano sull\u2019essere guidata, e, dopo aver ricevuto quelli che alla luce odierna leggo come \u201csegni evidenti\u201d del suo volere, ma che io ritenevo all\u2019epoca non essere ancora sufficienti, il\u00a0 giorno dell\u2019 Aid el Fitr ( la festa dell\u2019Aid con la quale si conclude il mese di Ramadan), mentre mi recavo in centro citt\u00e0, mi sono ritrovata esattamente dalla parte opposta di dove dovevo andare.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Dopo aver deciso di parcheggiare, si avvicin\u00f2 a me un ragazzo di colore per vendermi i soliti fazzoletti. Non so come, mi sono \u201csentita\u201d chiedergli se sapeva dove fosse la moschea.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Non avevo pensato di chiederglielo, e quella domanda sorprese anche me, poich\u00e9 avevo aperto bocca solo per dire che non avevo bisogno di nulla. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Eppure\u2026<\/span><\/span><span style=\"font-family: 'times new roman', times; font-size: large; line-height: 1.3em;\">\u2026mi ritrovai in moschea e chiesi di poter recitare la Shahada, (il credo islamico), recitando il quale\u00a0 si ritorna all\u2019Islam.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Ritengo di essere stata letteralmente \u201cportata\u201d, trasportata\u00a0 da quello che amo ritenere il volere di Dio, una forza superiore, anche perch\u00e9 io stessa mentre seguivo quel ragazzo che mi accompagnava, mi sentivo come sospinta: ero come un burattino nelle mani di qualcuno che muovesse i miei fili.\u00a0 Da almeno due anni chiedevo di essere \u201cguidata\u201d, e cos\u00ec \u00e8 stato.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Nessuno potr\u00e0 mai comprendere le mie emozioni durante la recita della Shahada, nessuno mai potr\u00e0 capire cosa significhi per me essere musulmana: sentire che Dio ci ha chiamati all\u2019Islam \u00e8 una cosa meravigliosa, e solo ora, le mie passate inquietudini sono ormai lontane da me.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Cinque mesi fa ho intrapreso il mio cammino verso l\u2019Islam, e tutte le mie paure legate al fatto di dover affrontare tutti i problemi con i miei genitori, fratelli, suoceri e marito sono svanite, perch\u00e9 Dio ne ha reso loro facile l\u2019accettazione, se pur con forti divergenze, ma non con battaglie.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Se Dio ci chiama, sa di doverci rendere le cose possibili.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Io non sono niente senza Dio,\u00a0 e so di dover imparare tanto sull\u2019Islam, e di doverne capire altrettanto, so di essere come un granellino di sabbia in un grande deserto, ma con l\u2019aiuto di Dio, se Dio vuole, potr\u00f2 forse un giorno, essere degna del suo perdono.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">Il mio cammino verso l\u2019Islam \u00e8 appena iniziato.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\"><a href=\"Questi-sono-convertiti-all-isalm\/Donne-si-sono-convertiti-all-isalm\/879-Aysha-Barbara-ho-trovate-le-risposte-delle-mie-ataviche-domande-sul-cristianesimo-nel-Sacro-Corano,\">Aysha Barbara Alterio\u00a0\u00ab\u00a01\u00a0\u00bb<\/a><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">La fonte:<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"font-size: large;\"><span style=\"font-family: 'times new roman', times;\">www.huda.it<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Aysha Barbara \u0650Alterio&#8221;2&#8243; leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam Certo, non potevo\u00a0 decidere di \u201critornare\u201d all\u2019Islam solo sulle basi di queste cose, poich\u00e9 questo, nel mio caso,\u00a0 ne aveva solo segnato un \u201cpunto a favore\u201d, e non era sufficiente per farmi affermare che io ero &hellip;<\/p>\n","protected":false},"author":6,"featured_media":817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donne-si-sono-convertiti-all-isalm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T06:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo%20il%20corano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Islam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Right Islam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/\"},\"author\":{\"name\":\"Right Islam\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\"},\"headline\":\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam\",\"datePublished\":\"2022-11-04T06:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/\"},\"wordCount\":744,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/leggendo il corano.jpg\",\"articleSection\":[\"Donne si sono convertiti all'isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/\",\"name\":\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/leggendo il corano.jpg\",\"datePublished\":\"2022-11-04T06:22:00+00:00\",\"description\":\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/leggendo il corano.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/leggendo il corano.jpg\",\"width\":428,\"height\":296},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/92de7dae6e843a9ee2e94aa4a9b5133d\",\"name\":\"Right Islam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g\",\"caption\":\"Right Islam\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/it-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam","description":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/","og_locale":"it_IT","og_type":"article","og_title":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam","og_description":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/","og_site_name":"II vero Islam","article_published_time":"2022-11-04T06:22:00+00:00","og_image":[{"width":428,"height":296,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo il corano.jpg","type":"image\/jpeg"}],"author":"Right Islam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Right Islam","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/"},"author":{"name":"Right Islam","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d"},"headline":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam","datePublished":"2022-11-04T06:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/"},"wordCount":744,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo il corano.jpg","articleSection":["Donne si sono convertiti all'isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/","url":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/","name":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo il corano.jpg","datePublished":"2022-11-04T06:22:00+00:00","description":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo il corano.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2022\/11\/leggendo il corano.jpg","width":428,"height":296},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/leggendo-il-corano-qualcosa-nel-mio-cuore-diverso-inspiegabile-a-parole-mi-portava-verso-lislam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"leggendo il Corano ,qualcosa nel mio cuore diverso inspiegabile a parole mi portava verso l\u2019Islam"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/92de7dae6e843a9ee2e94aa4a9b5133d","name":"Right Islam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02bc82baefedb88212fdfbdbc558b74e6c80b15750921e0ebbcfc450427d426b?s=96&d=mm&r=g","caption":"Right Islam"},"url":"https:\/\/r-islam.com\/it\/author\/it-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/817"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}