{"id":938,"date":"2015-05-31T03:37:26","date_gmt":"2015-05-31T03:37:26","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2015\/05\/31\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/"},"modified":"2015-05-31T03:37:26","modified_gmt":"2015-05-31T03:37:26","slug":"fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/","title":{"rendered":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-937\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg 750w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff; font-size: 14pt; font-family: 'times new roman', times;\">Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff; font-size: 14pt; font-family: 'times new roman', times;\"><\/span><br \/><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">Fatima Hamed \u00e8 stata membro del Parlamento Ceuta negli ultimi anni; ora inizia la sua<\/span><br \/><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">appena In mezzo anno, Fatima Hamed Hossain ha ottenuto ci\u00f2 che pochi realizzano. Tre seggi dell&#8217;Assemblea della citt\u00e0 autonoma di Ceuta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">\u00c8 diventata anche la prima donna musulmana presentata come capo di lista per l&#8217;elezione. Il suo Movimento per la dignit\u00e0 e la cittadinanza (MDyC) ha approfondito nella societ\u00e0 Ceuta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">La lunga esperienza politica Hamed \u00e8 noto a tutta al citt\u00e0 di Ceuta. A seguito dei risultati delle elezioni, la sede della formazione socio-politica \u00e8 diventata un alveare di congratulazioni e gioia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff; font-size: 14pt; font-family: 'times new roman', times;\">I risultati sono &#8220;molto positivi&#8221;<\/span><br \/><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">Il loro capo ha sottolineato ai media locali che i risultati sono stati &#8220;molto positivi&#8221;. &#8220;Per noi, tutte le proteste e le manifestazioni sono stati tentativi di portare la voce del popolo all&#8217;Assemblea che governava per di migliorare la nostra societ\u00e0.&#8221;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'times new roman', times;\">&#8220;E &#8216;un viaggio che \u00e8 appena iniziato&#8221;, ha dichiarato Hamed, aggiungendo che lei e il suo team non stanno andando a deludere i cittadini:&#8221;Combatteremo per i pi\u00f9 bisognosi e per tutta la popolazione della citt\u00e0, per eliminare le disparit\u00e0 sociale a Ceuta e per renderla un posto migliore&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">Traduzione : Ahmed Abdullah<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-191\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/4.jpg\" alt=\"\" width=\"700\" height=\"465\" \/><br \/><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">www.r-islam.com<\/span><br \/><span style=\"color: #ff0000; font-size: 14pt; font-family: 'times new roman', times;\">la fonte: http:\/\/noticias.lainformacion.com\/elecciones-autonomicas-y-municipales-2015<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta Fatima Hamed \u00e8 stata membro del Parlamento Ceuta negli ultimi anni; ora inizia la suaappena In mezzo anno, Fatima Hamed Hossain ha ottenuto ci\u00f2 che pochi realizzano. Tre seggi dell&#8217;Assemblea della citt\u00e0 autonoma di Ceuta. \u00c8 diventata anche la prima donna musulmana &hellip;<\/p>\n","protected":false},"author":7,"featured_media":937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-31T03:37:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta\",\"datePublished\":\"2015-05-31T03:37:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/05\\\/11204945_789217867840392_8165301811933144111_n.jpg\",\"articleSection\":[\"Le Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/\",\"name\":\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/05\\\/11204945_789217867840392_8165301811933144111_n.jpg\",\"datePublished\":\"2015-05-31T03:37:26+00:00\",\"description\":\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/05\\\/11204945_789217867840392_8165301811933144111_n.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/05\\\/11204945_789217867840392_8165301811933144111_n.jpg\",\"width\":750,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"caption\":\"Ahmed Abdallah\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam","description":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/","og_locale":"it_IT","og_type":"article","og_title":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam","og_description":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/","og_site_name":"II vero Islam","article_published_time":"2015-05-31T03:37:26+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ahmed Abdallah","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta","datePublished":"2015-05-31T03:37:26+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg","articleSection":["Le Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/","url":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/","name":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg","datePublished":"2015-05-31T03:37:26+00:00","description":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/05\/11204945_789217867840392_8165301811933144111_n.jpg","width":750,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/fatima-hamed-la-prima-musulmana-che-guida-un-gruppo-parlamentare-a-ceuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Fatima Hamed, la prima musulmana che guida un gruppo parlamentare a Ceuta"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","caption":"Ahmed Abdallah"},"url":"https:\/\/r-islam.com\/it\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=938"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/937"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}