{"id":953,"date":"2015-08-23T13:22:52","date_gmt":"2015-08-23T13:22:52","guid":{"rendered":"http:\/\/localhost\/rs\/it\/2015\/08\/23\/la-moderazione-dell-islam-nella-legislazione\/"},"modified":"2015-08-23T13:22:52","modified_gmt":"2015-08-23T13:22:52","slug":"la-moderazione-dell-islam-nella-legislazione","status":"publish","type":"post","link":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/","title":{"rendered":"La moderazione dell&#8217;Islam nella legislazione"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff; font-size: 12pt; font-family: 'times new roman', times;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-952\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg\" alt=\"\" width=\"425\" height=\"283\" srcset=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg 425w, https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff; font-size: 12pt; font-family: 'times new roman', times;\">La moderazione dell&#8217;Islam nella legislazione<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Il discorso della moderazione dell&#8217;islam nella legislazione \u00e8 molto lungo perch\u00e9 contiene tutti i lati della legislazione islamica, la moderazione dell&#8217;Islam si dimostra in ogni rito lontano dall&#8217; esagerazione e dall&#8217; incuria.<\/span><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">e questo si rivela chiaro in tante questioni nella Shari&#8217;ah come :<\/span><br \/><strong><span style=\"color: #3366ff; font-size: 12pt; font-family: 'times new roman', times;\">gradazione nella legislazione:<\/span><\/strong><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">la misericordia di Allah L&#8217;Onnipotente \u2013 venuta con il profeta Muhammad pace e benedizione su di lui- consiste nel fatto che gli insegnamenti religiosi non sono stati imposti tutti a una sola volta alla gente, ma gardualmente specialmente nel caso dei divieti come togliere gli idoli che circondavano la Kaaba, i quali non sono stati tolti che nel giorno della conquista di Mecca, e come il divieto di bere il vino che \u00e8 stato imposto in modo graduale, all&#8217;inizio Allah L&#8217;Onnipotente ha fatto scendere il versetto :<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8221; Ti chiedono del vino e del gioco d&#8217;azzardo. Di&#8217;: &#8220;In entrambi c&#8217;\u00e8 un grande peccato e qualche vantaggio per gli uomini, ma in entrambi il peccato \u00e8 maggiore del beneficio!&#8230;.&#8221;<\/span> [ Corano 2:19].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Poi altro versetto <span style=\"color: #008000;\">&#8221; O voi che credete! Non accostatevi all&#8217;orazione se siete ebbri finch\u00e9 non siate in grado di capire quello che dite; &#8230;&#8221;<\/span> [Corano 4:43].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Poi un terzo versetto<span style=\"color: #008000;\">&#8221; O voi che credete, in verit\u00e0 il vino, il gioco d&#8217;azzardo, le pietre idolatriche, le frecce divinatorie, sono immonde opere di Satana. Evitatele, affinch\u00e9 possiate prosperare.&#8221;<\/span> [Corano 5:90],e altre tante questioni nella Shari&#8217;ah.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">La legislazione nell&#8217;Islam ,per eliminare completamente le cattive usanze ereditate per secoli e radicate negli animi della gente e nella societ\u00e0, ha adottato il metodo graduale come il modo piu adatto per preparare gli animi della gente a ricevere gli insegnamenti religiosi ed ad accettare le sentenze di Allah e questo metodo graduale va seguito da tutti coloro che lavorano nell&#8217;invito all&#8217;islam.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #3366ff; font-size: 12pt; font-family: 'times new roman', times;\">La facilitazione nella legislazione obbligata:<\/span><\/strong><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Chiunque contempli nella Shari&#8217;a islamica, la trover\u00e0 basata sulla facilitazione , che \u00e8 un metodo divino e profetico ed un carattere distinto di questa religione , il profeta Muhammad -pace e benedizione su di lui- teneva molto alla facilitazione ed incoraggiava i suoi compagni a facilitare le cose , ci sono tanti testi che provano che la nostra religione \u00e8 basata sulla facilitazione ;<\/span><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Allah l&#8217;Onnipotente dice :<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8221; &#8230;Allah vi vuole facilitare e non procurarvi disagio,..&#8221; <span style=\"color: #000000;\">[Corano 2:185]<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8221; Ti faciliteremo la [via] pi\u00f9 facile. &#8220;<\/span> [Corano 87:8]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8220;&#8230;. Egli vi ha scelti e non ha posto nulla di gravoso nella religione ..&#8221;<\/span> [Corano 22:78].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Da Ab\u00fb Hurayra \u2013 che Allah sia soddisfatto di lui,<\/span><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">dal Profeta (pace e benedizioni di Allah su di lui), che disse: <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">\u00abLa religione \u00e8 leggera, e non si render\u00e0 dura la religione senz&#8217;esserne schiacciati; seguite la via giusta, ponetevi nel giusto mezzo, rasserenatevi, e chiedete soccorso all&#8217;aurora ed al crepuscolo, ed un poco della notte\u00bb<\/span>.Lo ha trasmesso Al-Bukh\u00e2r\u00ee.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Narr\u00f2 Anas che il Profeta (pace e benedizioni di Allah su di lui), diceva:<\/span><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8220;Facilitate, non &#8211; rendete difficile; date buone notizie e non rendetevi antipatici..&#8221;<\/span> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">E in un&#8217;altra versione dello stesso hadith, il Messaggero di Allah (pace e benedizioni di Allah su di lui) ha detto ai suoi compagni quando li mandava ad invitare la gente :<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><\/span><span style=\"color: #008000; font-size: 12pt; font-family: 'times new roman', times;\">&#8220;Date la lieta novella (alla gente); non create (nelle loro menti) avversione (verso la religione); mostrate loro indulgenza e non siate duri con loro.&#8221;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000; font-size: 12pt; font-family: 'times new roman', times;\"><\/span><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Il contenuto di questi testi sopracitati non solo incoraggia a facilitare e dare buone notizie, ma anche vieta rendere le cose difficili , il Messaggero di Allah (pace e benedizioni di Allah su di lui) non ha reso mai le cose difficili , la Madre dei Credenti &#8216;Aisha &#8221; che Allah sia sodisfatto di lei &#8221; disse :<span style=\"color: #008000;\"> <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">&#8221; Ogni volta che il Messaggero di Allah \u00e8 stata data la scelta tra due cose ha sempre scelto il pi\u00f9 facile dei due fino a quando non era peccato. Se era peccato allora era la pi\u00f9 lontana delle persone da esso. &#8220;<\/span> .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Nella legislazione islamica c&#8217;\u00e8 una regola importante &#8221; <span style=\"color: #993366;\">ogni difficolta richiede per forza la facilitazione<\/span> &#8220;<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #3366ff; font-size: 12pt; font-family: 'times new roman', times;\">La giustizia nella legislazione:<\/span><\/strong><br \/><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">La giustizia e la moderazione sono due parole simili come se fossero due sinonimi<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Allah l&#8217;Onnipotente dice :<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">&#8221; <span style=\"color: #008000;\">&#8230;&#8221; E cos\u00ec facemmo di voi una comunit\u00e0 equilibrata, affinch\u00e9 siate testimoni di fronte ai popoli e il Messaggero sia testimone di fronte a voi&#8230;.&#8221;<\/span>[Corano2:143 ] il profeta ha detto che &#8221; una comunit\u00e0 equilibrata&#8221; vuol dire una comunit\u00e0 di giustizia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Abu-Sa&#8217;id Al-Khudri ha riferito che Il Profeta Muhammad (sallallahu &#8216;aleyhi wa sallam) disse:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\"> &#8221; Arriva No\u00e8 con la sua gente, Allah si rivolge a No\u00e8: &#8220;Dimmi No\u00e8, hai dato a loro il Messaggio?&#8221; No\u00e8 risponde: &#8220;Si, mio Signore&#8221;.<\/span><\/span><br \/><span style=\"color: #008000; font-size: 12pt; font-family: 'times new roman', times;\">Allah si rivolge al suo popolo &#8220;No\u00e8 vi ha avvisato?&#8221; rispondono &#8220;No, non \u00e8 mai stato mandato a noi un Profeta&#8221;, Allah chiede a No\u00e8 &#8220;Chi far\u00e0 testimonianza della tua missione che li hai avvisati?&#8221;&nbsp;<\/span><span style=\"font-size: 12pt; font-family: 'times new roman', times;\"><span style=\"color: #008000;\">No\u00e8 risponde: &#8220;Muhammad e la sua comunit\u00e0&#8221;, finch\u00e8 la comunit\u00e0 di Muhammad dir\u00e0 &#8220;Si nostro Signore, lui ci ha avvisato, questo \u00e8 il significato del versetto che dice: &#8221; E cos\u00ec facemmo di voi una comunit\u00e0 equilibrata, affinch\u00e9 siate testimoni di fronte ai popoli &#8221; l&#8217;equilibrio significa la giustizia &#8220;<\/span>.,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: 'times new roman', times;\">Se Allah L&#8217;Onnipotente ha scelto la comunit\u00e0 musulmana per essere testimoni di fronte a tutti gli altri popoli , questo vuol dire che la giustizia e l&#8217;onest\u00e0 sono delle qualit\u00e0 di questa comunit\u00e0 musulmana, cos\u00ec ha detto Allah L&#8217;Onnipotente nel Sacro Corano ed anche ha detto il profeta pace e benedizione su di lui nei suoi Hadith<\/span><br \/><span style=\"color: #ff0000; font-size: 12pt; font-family: 'times new roman', times;\">traduzione: Ahmed Abdullah<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-191\" src=\"http:\/\/localhost\/rs\/it\/wp-content\/uploads\/sites\/6\/2018\/04\/4.jpg\" alt=\"\" width=\"255\" height=\"60\" \/><br \/><span style=\"color: #ff0000; font-size: 12pt; font-family: 'times new roman', times;\">www.r-islam.com<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La moderazione dell&#8217;Islam nella legislazione Il discorso della moderazione dell&#8217;islam nella legislazione \u00e8 molto lungo perch\u00e9 contiene tutti i lati della legislazione islamica, la moderazione dell&#8217;Islam si dimostra in ogni rito lontano dall&#8217; esagerazione e dall&#8217; incuria.e questo si rivela chiaro in tante questioni nella Shari&#8217;ah come :gradazione nella legislazione:la misericordia di Allah L&#8217;Onnipotente \u2013 &hellip;<\/p>\n","protected":false},"author":7,"featured_media":952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[58,87,63,60,65,59,64,76,88,61,62],"class_list":["post-953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-verita-dell-isalm","tag-donna","tag-allah","tag-convertito","tag-corano","tag-hadith","tag-lislam","tag-miracoli","tag-moschea","tag-muhammad","tag-profeta","tag-sunnah"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La moderazione dell&#039;Islam nella legislazione - II vero Islam II vero Islam<\/title>\n<meta name=\"description\" content=\"La moderazione dell&#039;Islam nella legislazione II vero Islam %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La moderazione dell&#039;Islam nella legislazione - II vero Islam II vero Islam\" \/>\n<meta property=\"og:description\" content=\"La moderazione dell&#039;Islam nella legislazione II vero Islam %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/\" \/>\n<meta property=\"og:site_name\" content=\"II vero Islam\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-23T13:22:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ahmed Abdallah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ahmed Abdallah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/\"},\"author\":{\"name\":\"Ahmed Abdallah\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\"},\"headline\":\"La moderazione dell&#8217;Islam nella legislazione\",\"datePublished\":\"2015-08-23T13:22:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/08\\\/1-web.jpg\",\"keywords\":[\",donna\",\"Allah,\",\"convertito,\",\"Corano,\",\"Hadith,\",\"l'Islam,\",\"Miracoli,\",\"moschea,\",\"Muhammad,\",\"Profeta,,\",\"Sunnah,\"],\"articleSection\":[\"La verit\u00e0 dell'Isalm\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/\",\"name\":\"La moderazione dell'Islam nella legislazione - II vero Islam II vero Islam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/08\\\/1-web.jpg\",\"datePublished\":\"2015-08-23T13:22:52+00:00\",\"description\":\"La moderazione dell'Islam nella legislazione II vero Islam %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/08\\\/1-web.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/08\\\/1-web.jpg\",\"width\":425,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/la-moderazione-dell-islam-nella-legislazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La moderazione dell&#8217;Islam nella legislazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"name\":\"II vero Islam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#organization\",\"name\":\"II vero Islam\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/cropped-logo-small.jpg\",\"width\":512,\"height\":512,\"caption\":\"II vero Islam\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/it\\\/#\\\/schema\\\/person\\\/50843a866a13df1a858ff77dda9b0e24\",\"name\":\"Ahmed Abdallah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g\",\"caption\":\"Ahmed Abdallah\"},\"url\":\"https:\\\/\\\/r-islam.com\\\/it\\\/author\\\/ahmed-abdallah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La moderazione dell'Islam nella legislazione - II vero Islam II vero Islam","description":"La moderazione dell'Islam nella legislazione II vero Islam %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/","og_locale":"it_IT","og_type":"article","og_title":"La moderazione dell'Islam nella legislazione - II vero Islam II vero Islam","og_description":"La moderazione dell'Islam nella legislazione II vero Islam %","og_url":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/","og_site_name":"II vero Islam","article_published_time":"2015-08-23T13:22:52+00:00","og_image":[{"width":425,"height":283,"url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg","type":"image\/jpeg"}],"author":"Ahmed Abdallah","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ahmed Abdallah","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/"},"author":{"name":"Ahmed Abdallah","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24"},"headline":"La moderazione dell&#8217;Islam nella legislazione","datePublished":"2015-08-23T13:22:52+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg","keywords":[",donna","Allah,","convertito,","Corano,","Hadith,","l'Islam,","Miracoli,","moschea,","Muhammad,","Profeta,,","Sunnah,"],"articleSection":["La verit\u00e0 dell'Isalm"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/","url":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/","name":"La moderazione dell'Islam nella legislazione - II vero Islam II vero Islam","isPartOf":{"@id":"https:\/\/r-islam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg","datePublished":"2015-08-23T13:22:52+00:00","description":"La moderazione dell'Islam nella legislazione II vero Islam %","breadcrumb":{"@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#primaryimage","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2015\/08\/1-web.jpg","width":425,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/it\/la-moderazione-dell-islam-nella-legislazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/it\/"},{"@type":"ListItem","position":2,"name":"La moderazione dell&#8217;Islam nella legislazione"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/it\/#website","url":"https:\/\/r-islam.com\/it\/","name":"II vero Islam","description":"","publisher":{"@id":"https:\/\/r-islam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/it\/#organization","name":"II vero Islam","url":"https:\/\/r-islam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/it\/wp-content\/uploads\/sites\/6\/2024\/02\/cropped-logo-small.jpg","width":512,"height":512,"caption":"II vero Islam"},"image":{"@id":"https:\/\/r-islam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/r-islam.com\/it\/#\/schema\/person\/50843a866a13df1a858ff77dda9b0e24","name":"Ahmed Abdallah","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8776f08fb80f791da754e383fcbc7576b76b5a7d1fc8ce2d4c654187474224d3?s=96&d=mm&r=g","caption":"Ahmed Abdallah"},"url":"https:\/\/r-islam.com\/it\/author\/ahmed-abdallah\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/posts\/953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/media?parent=953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/categories?post=953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/it\/wp-json\/wp\/v2\/tags?post=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}