{"id":57,"date":"2018-05-18T14:36:00","date_gmt":"2018-05-18T14:36:00","guid":{"rendered":"http:\/\/localhost\/rs\/sp\/2018\/05\/18\/el-ayuno-de-ramadan\/"},"modified":"2018-05-18T14:36:00","modified_gmt":"2018-05-18T14:36:00","slug":"el-ayuno-de-ramadan","status":"publish","type":"post","link":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/","title":{"rendered":"El ayuno de Ramad\u00e1n"},"content":{"rendered":"<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"> <strong><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-56\" style=\"float: right; margin-left: 12px; margin-right: 12px;\" src=\"http:\/\/localhost\/rs\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg\" width=\"366\" height=\"244\" border=\"0\" srcset=\"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg 432w, https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011-300x200.jpg 300w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" \/>Definici\u00f3n<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El ayuno es la abstinencia total de todo aquello que rompe el ayuno (Bien sea comida o bebida o relaciones sexuales) desde el alba hasta la puesta del sol.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El ayuno del mes de Ramad\u00e1n es obligatorio a todo musulm\u00e1n adulto y con juicio, bien sea hombre o mujer.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>\u00bfCUANDO EMPIEZA?<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El mes de Ramad\u00e1n es el noveno mes lunar y empieza el ayuno con la aparici\u00f3n de la luna a finales de Sha&#8217;ban (octavo mes en el calendario lunar isl\u00e1mico).<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Dice el Profeta (PB): \u00abAyunad a su visi\u00f3n (ver la luna) y romped a su visi\u00f3n y si se os es oculta (la luna por causa atmosf\u00e9rica) concluid el mes de Ramad\u00e1n contando treinta d\u00edas. Igualmente al comienzo del mes de Ramad\u00e1n se contar\u00e1n treinta d\u00edas de Sha&#8217;b\u00e1n sino es visible el nacimiento de la luna.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>LOS PILARES DEL AYUNO<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Los pilares del ayuno en el Islam, bien sea en el mes de Ramad\u00e1n, o en otros meses, son los siguientes:<br \/> 1) La abstinencia de todo aquello que rompa el ayuno [Bien sea bebida, comida o relaciones carnales) desde el alba hasta la puesta del sol.<\/p>\n<p><\/span> <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">2) Tener presente la intenci\u00f3n<br \/> Se debe tenerla presente en la mente y en el coraz\u00f3n, sin necesidad de decir nada con la lengua [de pronunciar algo concreto (es decir la intenci\u00f3n)], tiene que ser antes del fayr (inicio del tiempo de la primera oraci\u00f3n del d\u00eda), y puede ser dicha diariamente, o por todo el mes desde su inicio.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>\u00bfQUIEN DEBE AYUNAR?<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El ayuno es deber del musulm\u00e1n adulto, sano de juicio, saludable, residente (no de viaje) bien sea hombre o mujer. En cuanto a la mujer, debe estar fuera de la menstruaci\u00f3n, y del puerperio. Por lo tanto, no debe ayunar el enfermo mental, ni el menor, ni el viajante, ni a la mujer durante la menstruaci\u00f3n o puerperio, as\u00ed como a la embarazada, o la lactante que teme por su peque\u00f1o, ni los ancianos d\u00e9biles.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>CASOS ESPECIALES<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1- El ayuno del menor de edad<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El menor de edad no est\u00e1 obligado a ayunar, pero se le debe ordenar por parte de sus padres, para que se acostumbre a ello, y practicarlo sin mucha dificultad al ser mayor. L\u00f3gicamente, tiene que ser sano y poder hacerlo sin repercusiones adversas.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">2- A qui\u00e9n se le permite desayunar en Ramad\u00e1n y pagar la compensaci\u00f3n:<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">a) El anciano d\u00e9bil cuya salud puede empeorar.<br \/> b) El enfermo cr\u00f3nico y que no tiene la posibilidad de recuperar los d\u00edas desayunados.<br \/> c) Todos los casos mencionados anteriormente est\u00e1n obligados a dar de comer en compensaci\u00f3n a un pobre por cada d\u00eda que no hayan ayunado, y no tienen por qu\u00e9 recuperarlo.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">3- A qui\u00e9nes se les permite desayunar en Ramad\u00e1n y tienen que recuperar los d\u00edas desayunados:<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">a) Los enfermos cuyo estado de salud puede empeorar con el ayuno y se espera su recuperaci\u00f3n de la enfermedad y su curaci\u00f3n.<br \/> b) En casos de tener hambre o sed severos que pueden repercutir muy gravemente en el estado de la salud.<br \/> c) Al que est\u00e1 de viaje se le permite desayunar cuando viaja la misma distancia por la que se le permite acortar las oraciones y rezarlas juntas. Es decir, la del Duhur con la del &#8216;Asr 2 y 2 Rak&#8217;atas en vez de 4 y 4; las del Magrib con las de &#8216;Isha 3 y 2 en vez de 3 y 4 Rak&#8217;ats.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Los casos en que se les proh\u00edbe ayunar y deben recuperar los d\u00edas desayunados.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">a) Las mujeres que est\u00e1n con la menstruaci\u00f3n o durante el puerperio, ya que est\u00e1 tajantemente prohibido su ayuno, as\u00ed como su oraci\u00f3n, teniendo que recuperar el ayuno, pero no la oraci\u00f3n.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">DEBERES QUE SE PRESERVAN DURANTE EL AYUNO<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1) As-suhur:<br \/> El suhur consiste en tomar alg\u00fan alimento por la madrugada, siempre antes del Fayr, por muy poco que sea la cantidad de comida o bebida, aunque fuera un poco de agua, tiempo que se extiende desde la medianoche hasta la entrada del momento de la oraci\u00f3n, antes de las primeras luces del alba, con la intenci\u00f3n del ayuno presente en la mente, pues el suhur es bendici\u00f3n y prosperidad como dice el Profeta (PB).<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">2) Romper el ayuno inmediatamente despu\u00e9s de la puesta del sol y al comienzo del tiempo de la oraci\u00f3n de magrib:<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Pues dice el Profeta (PB): \u00abLos hombres permanecen en el bien mientras no retrasen la ruptura del ayuno despu\u00e9s de la puesta del sol\u00bb.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">3) El orar y suplicar en el momento de romper el ayuno:<br \/> Por ejemplo, dec\u00eda el Profeta (PB): \u00abSe fue la sed, se hidrataron las venas, y se logr\u00f3 la recompensa con el permiso de Dios\u00bb.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">4) El abstenerse de todo lo que contradice el ayuno en lo moral:<br \/> Ya que el ayuno es una gran escuela de disciplina y doctrina, tanto espirituales como morales, pues no se limita a la abstinencia de comer o beber solamente, sino de todo lo que sea mala palabra, mal acto o mal pensamiento. El ayunante deber\u00eda ser indulgente en caso de ser insultado o agredido por alguien, debiendo evitar todas las obscenidades.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">5) El uso del siu\u00e1k durante el ayuno:<br \/> Es un trozo de rama de un \u00e1rbol especial que se encuentra en la pen\u00ednsula ar\u00e1biga y que es de muchos beneficios, tanto para los dientes como para las enc\u00edas y la boca, y se usa como un cepillo de dientes.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">6) Ser generoso:<br \/> El musulm\u00e1n siempre tiene que ser generoso, pero lo es m\u00e1s en el mes de Ramad\u00e1n.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">7) Incrementar la lectura del Sagrado Cor\u00e1n:<br \/> Durante el mes de Ramad\u00e1n, en que fue revelado el Sagrado Cor\u00e1n, se debe recitar \u00e9ste con mayor frecuencia que en los otros meses. Adem\u00e1s dijo el Profeta (PB): \u00abEl ayuno y el Sagrado Cor\u00e1n interceder\u00e1n a favor del siervo el D\u00eda de la Resurrecci\u00f3n.\u00bb<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">8) Incrementar las pr\u00e1cticas:<br \/> Sobre todo en los \u00faltimos diez d\u00edas del mes de Ramad\u00e1n, tal como lo hac\u00eda el Profeta (PB).<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong>COSAS Y HECHOS QUE EST\u00c1N PERMITIDOS DURANTE EL PERIODO DE ABSTINENCIA.<\/strong><\/span> <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1) Ba\u00f1arse, ducharse, nadar y sumergirse en el agua con la condici\u00f3n de que no trague nada por la boca o por la nariz.<br \/> 2) Poner el Kuhl o colirio en los ojos, sea en gotas, cremas, etc. El Kuhl es una clase de mascara natural (polvo natural negro) que se utiliza para los bordes de los p\u00e1rpados, bien como medio de tratamiento de los ojos de algunas enfermedades, o bien como medio de belleza.<br \/> 3) El beso: el besar uno a otra, as\u00ed como el hombre a su esposa y viceversa, pero sin acceder al orgasmo o salida del liquido seminal.<br \/> 4) Las inyecciones, sean intramusculares, subcut\u00e1neas o intra cut\u00e1neas, a condici\u00f3n de que no sean nutritivas.<br \/> 5) La sangr\u00eda (venopunci\u00f3n) que se utiliza en algunas enfermedades como medio de tratamiento.<br \/> 6) Enjuagarse la boca con agua o aspirar el agua por la nariz durante las abluciones y volver a echarlo hacia fuera, con la finalidad de limpiar la boca y las fosas nasales.<br \/> 7) Est\u00e1 permitido tragar las cosas inevitables como son la saliva, o el polvo (en algunos trabajos).<br \/> 8) El uso de supositorios, ya sean anales o vaginales.<br \/> 9) El uso de colonias, perfumes y maquillajes.<br \/> 10) Comer, beber y tener relaciones sexuales desde que se rompa el ayuno ( puesta de sol) hasta la abstinencia (salida del alba).<br \/> 11) Est\u00e1 permitido retrasar el Gusl (la abluci\u00f3n mayor) hasta despu\u00e9s de la salida del sol a las mujeres que tuvieron menstruaci\u00f3n o puerperio y quedaron libres la noche anterior.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>COSAS Y HECHOS QUE INVALIDAN EL AYUNO Y HAY QUE RECUPERARLO<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1) Comer o beber intencionadamente. En cambio el comer o beber olvidando el ayuno no invalida \u00e9ste, pero una vez que se de cuenta de ello, tiene que abstenerse y completar el d\u00eda ayunando.<br \/> 2) El vomitar intencionadamente. En caso de ser involuntario no debe recuperarlo.<br \/> 3) La menstruaci\u00f3n o el puerperio, aunque empiecen en las ultimas horas del d\u00eda (antes de ponerse el sol) se debe recuperar.<br \/> 4) La masturbaci\u00f3n intencionadamente. bien sea por la mano o por cualquier otro medio, abrazando a su mujer, bes\u00e1ndola, acarici\u00e1ndola.<br \/> 5) El tener la intenci\u00f3n de desayunar, aunque no haya tomado nada de comida o bebida que rompe el ayuno.<br \/> 6) El comer, beber, o tener relaciones sexuales, creyendo que se hab\u00eda puesto el sol, o hubiera salido el alba, pero posteriormente se da cuenta de lo contrario. En caso de tener relaciones sexuales durante la abstinencia, queda anulado el ayuno de dicho d\u00eda y hay que hacer lo que se conoce en el Islam como \u00abKaff\u00e1rah\u00bb.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">Kaff\u00e1rah: Es ayunar dos meses seguidos, si le fuera posible, o dar de comer a 60 pobres, en caso de no poder ayunar, o librar a un esclavo, si no puede ayunar o dar de comer a 60 pobres. En caso de tener el hombre relaciones sexuales con su esposa voluntariamente por ambos, los dos tienen que hacer Kaff\u00e1rah.<br \/> En cambio en caso de ser forzada la mujer, por su esposo, no tiene porque hacer kaff\u00e1rah. Si comete el mismo acto otro d\u00eda, tendr\u00e1 que hacer otra kafr\u00e1rah y en caso de hacerlo dos veces en el mismo d\u00eda har\u00e1 solo una kaff\u00e1rah, ya que se considera cada d\u00eda independientemente de los otros.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><br \/><strong>La recuperaci\u00f3n de los d\u00edas desayunados en Ramad\u00e1n<\/strong><\/span> <span style=\"font-size: large;\"><br \/> La recuperaci\u00f3n de los d\u00edas desayunados o anulados durante el mes de Ramad\u00e1n no tiene por qu\u00e9 ser inmediatamente despu\u00e9s de dicho mes, sino que dispone de un largo per\u00edodo de tiempo que se extiende desde que finaliza el actual mes de Ramad\u00e1n, hasta que empiece el siguiente. Lo mismo sucede con la kaff\u00e1rah. Hay que recuperar un d\u00eda por cada d\u00eda que haya desayunado durante el mes de Ramad\u00e1n, pero no tienen porque ser todos los d\u00edas seguidos (en caso de ser m\u00e1s de un d\u00eda). Se podr\u00e1n hacer seguidos o salteados. En caso de llegar el mes de Ramad\u00e1n del a\u00f1o siguiente, y no hubiera recuperado los d\u00edas adeudados, ayunar\u00e1 ese mes y recuperar\u00e1 lo que adeudare m\u00e1s tarde, y debe alimentar a un pobre por cada d\u00eda recuperado. En caso de fallecer y deber d\u00edas del mes de Ramad\u00e1n, \u00e9stos podr\u00e1n ser recuperados bien por su \u00abualy\u00bb (familiar encargado), o bien por uno de los que lo heredan.<br \/> El ayuno se diferencia de la oraci\u00f3n en este sentido, ya que la oraci\u00f3n no podr\u00e1 ser recuperada por otros.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>LAILAT-UL QADR<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">La llegada del mes de Ramad\u00e1n trae consigo uno de los acontecimientos m\u00e1s importantes y especiales, tanto real como simb\u00f3licamente, para un musulm\u00e1n: Lailat-ul Qadr, la noche del decreto. Como sabemos, \u00e9sta es la noche en la cual Muhammad (PB) recibi\u00f3 la primera revelaci\u00f3n del Sagrado Cor\u00e1n, y as\u00ed comenz\u00f3 su misi\u00f3n como Profeta y Mensajero de Allah. Por si solo este hecho es causa de gran regocijo.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>Otros ayunos<\/strong><\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">El ayuno se puede clasificar en dos tipos:<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1- El ayuno obligatorio (Fard)<br \/> 2- El ayuno voluntario (Nafl)<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">1 &#8211; El ayuno obligatorio (Fard) se divide a su vez en:<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\">a) El ayuno del mes de \u00abRamad\u00e1n\u00bb<br \/> b) El ayuno del \u00abKaff\u00e1rah\u00bb<br \/> c) El ayuno del \u201cNadr\u201d o de las promesas que hace uno a si mismo ante Dios.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: times new roman,times;\"><span style=\"font-size: large;\"><strong>http:\/\/www.islamhoy.org\/<\/strong><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Definici\u00f3n \u00a0 El ayuno es la abstinencia total de todo aquello que rompe el ayuno (Bien sea comida o bebida o relaciones sexuales) desde el alba hasta la puesta del sol. \u00a0 El ayuno del mes de Ramad\u00e1n es obligatorio a todo musulm\u00e1n adulto y con juicio, bien sea hombre o mujer. \u00a0 \u00bfCUANDO EMPIEZA? &hellip;<\/p>\n","protected":false},"author":1,"featured_media":56,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ayuno de Ramad\u00e1n - El Islam Verdadero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ayuno de Ramad\u00e1n - El Islam Verdadero\" \/>\n<meta property=\"og:description\" content=\"Definici\u00f3n \u00a0 El ayuno es la abstinencia total de todo aquello que rompe el ayuno (Bien sea comida o bebida o relaciones sexuales) desde el alba hasta la puesta del sol. \u00a0 El ayuno del mes de Ramad\u00e1n es obligatorio a todo musulm\u00e1n adulto y con juicio, bien sea hombre o mujer. \u00a0 \u00bfCUANDO EMPIEZA? &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/\" \/>\n<meta property=\"og:site_name\" content=\"El Islam Verdadero\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheRightislam.SP\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-18T14:36:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"432\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@verdadeiroIslam\" \/>\n<meta name=\"twitter:site\" content=\"@verdadeiroIslam\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#\\\/schema\\\/person\\\/f8e20432ecf4d7630f8fbb68383d56c4\"},\"headline\":\"El ayuno de Ramad\u00e1n\",\"datePublished\":\"2018-05-18T14:36:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/\"},\"wordCount\":1976,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/05\\\/ramadan-2011.jpg\",\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/\",\"name\":\"El ayuno de Ramad\u00e1n - El Islam Verdadero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/05\\\/ramadan-2011.jpg\",\"datePublished\":\"2018-05-18T14:36:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/05\\\/ramadan-2011.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/05\\\/ramadan-2011.jpg\",\"width\":432,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/el-ayuno-de-ramadan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ayuno de Ramad\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#website\",\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/\",\"name\":\"El Islam Verdadero\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#organization\",\"name\":\"El Islam Verdadero\",\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/03\\\/logo-small.jpg\",\"contentUrl\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/03\\\/logo-small.jpg\",\"width\":180,\"height\":180,\"caption\":\"El Islam Verdadero\"},\"image\":{\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TheRightislam.SP\\\/\",\"https:\\\/\\\/x.com\\\/verdadeiroIslam\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/#\\\/schema\\\/person\\\/f8e20432ecf4d7630f8fbb68383d56c4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/r-islam.com\"],\"url\":\"https:\\\/\\\/r-islam.com\\\/sp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ayuno de Ramad\u00e1n - El Islam Verdadero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/","og_locale":"es_ES","og_type":"article","og_title":"El ayuno de Ramad\u00e1n - El Islam Verdadero","og_description":"Definici\u00f3n \u00a0 El ayuno es la abstinencia total de todo aquello que rompe el ayuno (Bien sea comida o bebida o relaciones sexuales) desde el alba hasta la puesta del sol. \u00a0 El ayuno del mes de Ramad\u00e1n es obligatorio a todo musulm\u00e1n adulto y con juicio, bien sea hombre o mujer. \u00a0 \u00bfCUANDO EMPIEZA? &hellip;","og_url":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/","og_site_name":"El Islam Verdadero","article_publisher":"https:\/\/www.facebook.com\/TheRightislam.SP\/","article_published_time":"2018-05-18T14:36:00+00:00","og_image":[{"width":432,"height":288,"url":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@verdadeiroIslam","twitter_site":"@verdadeiroIslam","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#article","isPartOf":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/"},"author":{"name":"admin","@id":"https:\/\/r-islam.com\/sp\/#\/schema\/person\/f8e20432ecf4d7630f8fbb68383d56c4"},"headline":"El ayuno de Ramad\u00e1n","datePublished":"2018-05-18T14:36:00+00:00","mainEntityOfPage":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/"},"wordCount":1976,"commentCount":0,"publisher":{"@id":"https:\/\/r-islam.com\/sp\/#organization"},"image":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg","articleSection":["Art\u00edculos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/","url":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/","name":"El ayuno de Ramad\u00e1n - El Islam Verdadero","isPartOf":{"@id":"https:\/\/r-islam.com\/sp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#primaryimage"},"image":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#primaryimage"},"thumbnailUrl":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg","datePublished":"2018-05-18T14:36:00+00:00","breadcrumb":{"@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#primaryimage","url":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg","contentUrl":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2018\/05\/ramadan-2011.jpg","width":432,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/r-islam.com\/sp\/el-ayuno-de-ramadan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r-islam.com\/sp\/"},{"@type":"ListItem","position":2,"name":"El ayuno de Ramad\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/r-islam.com\/sp\/#website","url":"https:\/\/r-islam.com\/sp\/","name":"El Islam Verdadero","description":"","publisher":{"@id":"https:\/\/r-islam.com\/sp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r-islam.com\/sp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/r-islam.com\/sp\/#organization","name":"El Islam Verdadero","url":"https:\/\/r-islam.com\/sp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/r-islam.com\/sp\/#\/schema\/logo\/image\/","url":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2024\/03\/logo-small.jpg","contentUrl":"https:\/\/r-islam.com\/sp\/wp-content\/uploads\/sites\/9\/2024\/03\/logo-small.jpg","width":180,"height":180,"caption":"El Islam Verdadero"},"image":{"@id":"https:\/\/r-islam.com\/sp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TheRightislam.SP\/","https:\/\/x.com\/verdadeiroIslam"]},{"@type":"Person","@id":"https:\/\/r-islam.com\/sp\/#\/schema\/person\/f8e20432ecf4d7630f8fbb68383d56c4","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb04ea9d748163234e422df75aeb140deeb34bae04b5c0670f6e57325ec35cc4?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/r-islam.com"],"url":"https:\/\/r-islam.com\/sp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/media\/56"}],"wp:attachment":[{"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/r-islam.com\/sp\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}